{"id":8179,"date":"2025-07-21T17:24:14","date_gmt":"2025-07-21T17:24:14","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/?post_type=rbc_tl&#038;p=8179\/supply-management-explained"},"modified":"2025-07-21T17:32:55","modified_gmt":"2025-07-21T17:32:55","slug":"demystification-de-la-gestion-de-loffre","status":"publish","type":"rbc_tl","link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","title":{"rendered":"D\u00e9mystification de la gestion de l\u2019offre"},"content":{"rendered":"\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t-0 mob-pad-t-0\" style=\"border-radius:0x\">\n<h2 class=\"wp-block-heading mar-b-hlf mob-mar-b-hlf has-rbc-dark-blue-tint-color has-text-color has-link-color wp-elements-b7520fe3bcb13fd31d921258cb0d2ddd\" id=\"h-sommaire\">Sommaire<\/h2>\n\n\n\n<ul class=\"wp-block-rbc-list pad-l mob-pad-l default is-style-black-disc\">\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Le syst\u00e8me canadien de la gestion de l\u2019offre, qui repr\u00e9sente 30&nbsp;milliards de dollars, est l\u2019assise de la souverainet\u00e9 et de la s\u00e9curit\u00e9 alimentaires du pays depuis plus de 50&nbsp;ans.<\/strong> S\u2019appliquant aux produits laitiers, au poulet, \u00e0 la dinde et aux \u0153ufs, il assure la stabilit\u00e9 des prix et de l\u2019offre de denr\u00e9es de base.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Le syst\u00e8me reconna\u00eet que la production d\u2019aliments co\u00fbte cher. <\/strong>Il favorise la stabilit\u00e9 de la cha\u00eene logistique, mais peut faire monter les prix \u00e0 la consommation, surtout dans un contexte de hausse du co\u00fbt des intrants<strong>.<\/strong><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Les trois piliers de la gestion de l\u2019offre sont de nouveau attaqu\u00e9s.<\/strong> L\u2019int\u00e9grit\u00e9 du syst\u00e8me est garantie par trois choses&nbsp;: des contingents de production, des prix fixes et des contingents d\u2019importation. \u00c0 l\u2019heure actuelle, les trois font l\u2019objet de critiques au sein du Canada et de la part de ses principaux partenaires commerciaux, dont les \u00c9tats-Unis.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Une nouvelle loi limite la capacit\u00e9 d\u2019Ottawa \u00e0 ouvrir le secteur.<\/strong> Les partisans du syst\u00e8me soutiennent que le projet de loi&nbsp;C-202 accorde la priorit\u00e9 \u00e0 la s\u00e9curit\u00e9 alimentaire nationale et emp\u00eache le ministre des Affaires \u00e9trang\u00e8res d\u2019accorder de nouvelles concessions dans le cadre d\u2019\u00e9ventuels accords commerciaux. D\u2019autres experts affirment qu\u2019il pourrait d\u00e9savantager le Canada dans les n\u00e9gociations commerciales, notamment celles li\u00e9es \u00e0 la r\u00e9vision de l\u2019Accord Canada\u2013\u00c9tats-Unis\u2013Mexique (ACEUM) l\u2019an prochain.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Les accords commerciaux r\u00e9duisent la mainmise des producteurs canadiens. <\/strong>Par ailleurs, l\u2019\u00e9largissement de l\u2019acc\u00e8s aux march\u00e9s mondiaux pour les agriculteurs canadiens soumis \u00e0 la gestion de l\u2019offre pourrait aller \u00e0 l\u2019encontre de la conception du syst\u00e8me.Une petite base de production adapt\u00e9e \u00e0 la consommation int\u00e9rieure rend ces derniers mal \u00e9quip\u00e9s pour rivaliser en tant qu\u2019exportateurs sur les march\u00e9s mondiaux, o\u00f9 les volumes \u00e9lev\u00e9s et les prix concurrentiels sont d\u00e9terminants.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>Le Canada n\u2019est pas le seul pays \u00e0 devoir faire des choix difficiles en mati\u00e8re de politique agricole. <\/strong>En Nouvelle-Z\u00e9lande, le secteur agricole est aux prises avec une empreinte GES d\u00e9mesur\u00e9e, et au Royaume-Uni, il peine \u00e0 reprendre pied depuis le Brexit. Le Br\u00e9sil, qui n\u2019est devanc\u00e9 que par les \u00c9tats-Unis pour les exportations totales de produits agroalimentaires, aspire \u00e0 accro\u00eetre sa part du march\u00e9 mondial. Le Canada pourrait tirer des le\u00e7ons de ces changements sur la sc\u00e8ne internationale, \u00e0 l\u2019heure des d\u00e9cisions concernant son secteur alimentaire national.<\/p>\n<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"853\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8359\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png 7735w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?resize=300,250 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?resize=768,640 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?resize=1024,853 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?resize=1536,1280 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Infographic-Supply-Management-Report-FR.png?resize=2048,1706 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-rbc-dark-blue-tint-color has-text-color has-link-color wp-elements-a8df52a2c8db607ab1640ac9857193a3\" id=\"h-evolution-du-paysage-des-politiques-commerciales-pour-les-industries-soumises-a-la-gestion-de-l-offre\">\u00c9volution du paysage des politiques commerciales pour les industries soumises \u00e0 la gestion de l&rsquo;offre<\/h2>\n\n\n\n<p>Dans le contexte actuel de ren\u00e9gociation de l\u2019accord commercial entre le Canada et les \u00c9tats-Unis, le syst\u00e8me canadien de la gestion de l\u2019offre est une fois de plus dans la mire de l\u2019administration Trump, qui le consid\u00e8re comme un irritant majeur.<\/p>\n\n\n\n<p>Cela a donn\u00e9 lieu \u00e0 un nouveau d\u00e9bat sur les secteurs alimentaires canadiens sous gestion de l\u2019offre, notamment ceux des produits laitiers, du poulet, de la dinde et des \u0153ufs, qui sont au c\u0153ur de la politique nationale depuis les ann\u00e9es&nbsp;1970.<\/p>\n\n\n\n<p>Essentiellement, le syst\u00e8me garantit un prix stable qui r\u00e9mun\u00e8re \u00e9quitablement les agriculteurs pour la production d\u2019aliments de qualit\u00e9 sup\u00e9rieure. Ses d\u00e9fenseurs avancent qu\u2019il renforce la s\u00e9curit\u00e9 alimentaire, soutient les producteurs nationaux et assure la r\u00e9gularit\u00e9 de la qualit\u00e9 et de l\u2019offre pour les consommateurs. En revanche, ses d\u00e9tracteurs soutiennent qu\u2019il freine l\u2019innovation, gonfle les prix et limite la concurrence.<\/p>\n\n\n\n<p>Le syst\u00e8me a fait l\u2019objet d\u2019un examen minutieux dans presque toutes les n\u00e9gociations commerciales et p\u00e9riodes de ralentissement \u00e9conomique, et sera probablement \u00e0 l\u2019ordre du jour de la r\u00e9vision de l\u2019Accord Canada\u2013\u00c9tats-Unis\u2013Mexique (ACEUM) l\u2019an prochain. Il est \u00e9galement remis en question dans le cadre d\u2019un mouvement national visant \u00e0 d\u00e9velopper un march\u00e9 unifi\u00e9 pour les biens et les services. Les avis sont polaris\u00e9s, allant des appels \u00e0 l\u2019abandon de la gestion de l\u2019offre jusqu\u2019au statu quo, en passant par une gamme d\u2019id\u00e9es nuanc\u00e9es sur la r\u00e9forme d\u2019un syst\u00e8me en place depuis plus d\u2019un demi-si\u00e8cle.<\/p>\n\n\n\n<p>Ceux qui veulent pr\u00e9server le syst\u00e8me passent \u00e0 l\u2019action. En juin, le projet de loi&nbsp;C-202 a re\u00e7u la sanction royale, avec le soutien massif des associations d\u2019agriculteurs canadiens soumis \u00e0 la gestion de l\u2019offre. Cette loi ordonne au ministre des Affaires \u00e9trang\u00e8res de cesser d\u2019attribuer aux partenaires commerciaux de nouveaux contingents dans les secteurs des produits laitiers, de la volaille et des \u0153ufs en vertu d\u2019accords internationaux. N\u00e9anmoins, le d\u00e9bat se poursuit, les parties prenantes d\u00e9signant des \u00e9l\u00e9ments pr\u00e9cis, allant des syst\u00e8mes r\u00e9gionaux de mise en commun du lait jusqu\u2019\u00e0 la question de savoir quel maillon de la cha\u00eene logistique devrait avoir acc\u00e8s aux contingents \u00e9trangers.<\/p>\n\n\n\n<p>Et les discussions ne se limitent pas \u00e0 l\u2019agriculture. La gestion de l\u2019offre a des r\u00e9percussions sur de nombreux aspects de l\u2019\u00e9conomie canadienne, y compris le prix des aliments, les options offertes, les emplois dans la cha\u00eene logistique, la diversification des \u00e9changes commerciaux et les perspectives de croissance.<\/p>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t-0 mob-pad-t-0\" style=\"border-radius:0x\">\n<h2 class=\"wp-block-heading has-rbc-dark-blue-tint-color has-text-color has-link-color wp-elements-ab397acb0fb3dba0e6f0f2f68a778815\" id=\"h-qu-est-ce-qui-est-en-jeu\">Qu\u2019est-ce qui est en jeu&nbsp;?<\/h2>\n\n\n\n<p><strong><strong>La gestion de l\u2019offre en chiffres&nbsp;:<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-black-disc pad-l mob-pad-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>1&nbsp;%. <\/strong>L\u2019apport des secteurs sous gestion de l\u2019offre au PIB du Canada, soit plus de 30&nbsp;milliards de dollars. L\u2019ensemble du secteur agricole et agroalimentaire compte pour plus de 7&nbsp;% du PIB du Canada.<sup><a href=\"#legal-1\" data-dig-id=\"LP-16033-3e2c4131\" data-dig-label=\"1\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">1<\/a> <a href=\"#legal-2\" data-dig-id=\"LP-16033-b1c8be11\" data-dig-label=\"2\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">2<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>33<\/strong>9<strong> 000 <\/strong>Le nombre d\u2019emplois \u00e0 temps plein dans les secteurs sous gestion de l\u2019offre, de l\u2019exploitation \u00e0 la transformation, en passant par la distribution.<sup><a href=\"#legal-3\" data-dig-id=\"LP-16033-0e389b91\" data-dig-label=\"3\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">3<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>14&nbsp;699.<\/strong> Le nombre d\u2019exploitations agricoles soumises \u00e0 la gestion de l\u2019offre au Canada, soit 8&nbsp;% des quelque 190&nbsp;000&nbsp;exploitations agricoles du pays.<sup><a href=\"#legal-4\" data-dig-id=\"LP-16033-62f4dbd6\" data-dig-label=\"4\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">4<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>9&nbsp;430.<\/strong> Le nombre de fermes laiti\u00e8res, principalement au Qu\u00e9bec et en Ontario. Depuis le d\u00e9but des ann\u00e9es&nbsp;2000, le nombre de fermes laiti\u00e8res au Canada a chut\u00e9 de plus de 50&nbsp;% en raison de la consolidation du march\u00e9.<sup><a href=\"#legal-5\" data-dig-id=\"LP-16033-6e404bc0\" data-dig-label=\"5\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">5<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p><strong>7&nbsp;%.<\/strong> Le pourcentage d\u2019augmentation du nombre d\u2019\u00e9levages de volaille et de poules pondeuses au cours des 20&nbsp;derni\u00e8res ann\u00e9es. On les retrouve principalement en Ontario, en Colombie-Britannique et au Qu\u00e9bec, mais les provinces des Prairies connaissent aussi une hausse.<sup><a href=\"#legal-6\" data-dig-id=\"LP-16033-47b78042\" data-dig-label=\"6\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">6<\/a><\/sup><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t-0 mob-pad-t-0\" style=\"border-radius:0x\">\n<h2 class=\"wp-block-heading has-rbc-dark-blue-tint-color has-text-color has-link-color wp-elements-ec13a6f4025fa6e2544d48d6f4a5bec8\" id=\"h-les-trois-s-de-la-gestion-de-l-offre\">Les trois \u00ab&nbsp;S&nbsp;\u00bb de la gestion de l\u2019offre<\/h2>\n\n\n\n<p>Le syst\u00e8me canadien est con\u00e7u pour pr\u00e9server la souverainet\u00e9, la stabilit\u00e9 et les standards alimentaires, ce qui contribue \u00e0 la prosp\u00e9rit\u00e9 de l\u2019industrie, mais pose \u00e9galement des d\u00e9fis dans un march\u00e9 mondial en constante \u00e9volution.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-souverainete\">Souverainet\u00e9<\/h3>\n\n\n\n<p><em><em><em>La gestion de l\u2019offre garantit des prix stables et une cha\u00eene logistique nationale solide pour r\u00e9pondre \u00e0 la demande. Toutefois, le Canada \u00e9tant un pays orient\u00e9 sur l\u2019exportation, une cha\u00eene logistique exclusivement nationale peut \u00eatre la source de tensions lors de n\u00e9gociations commerciales.<\/em><\/em><\/em><\/p>\n\n\n\n<p>La gestion de l\u2019offre contrarie les principaux partenaires commerciaux du Canada, en particulier les \u00c9tats-Unis, l\u2019Union europ\u00e9enne (UE) et, il y a peu, la Nouvelle-Z\u00e9lande. Un point de friction majeur&nbsp;: les restrictions canadiennes sur les contingents d\u2019importation.<br><br>Ces contingents visent \u00e0 limiter les importations dans les secteurs canadiens sous gestion de l\u2019offre. Cela dit, le Canada a r\u00e9cemment fait davantage de concessions. Par exemple, dans le cadre des pourparlers entourant l\u2019Accord de Partenariat transpacifique global et progressiste (PTPGP), le Canada a accept\u00e9 d\u2019accorder aux pays participants une part d\u2019environ 3,25&nbsp;% de son march\u00e9 int\u00e9rieur des produits laitiers<sup><a href=\"#legal-7\" data-dig-id=\"LP-8179-051fd871\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"7\" class=\"rbc-link-format\">7<\/a><\/sup>. Cependant, comme les transformateurs canadiens d\u00e9tiennent la majorit\u00e9 des contingents tarifaires d\u2019importation, les importateurs \u00e9trangers font valoir qu\u2019ils ont un acc\u00e8s limit\u00e9 au march\u00e9 canadien pour r\u00e9aliser leurs volumes exempt\u00e9s de droits de douane n\u00e9goci\u00e9s dans l\u2019accord.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"719\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8364\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?resize=300,211 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?resize=768,539 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?resize=1024,719 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?resize=1536,1078 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-07.png?resize=2048,1438 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Les accords commerciaux r\u00e9duisent la mainmise des producteurs canadiens.<\/strong> Les concessions ont entra\u00een\u00e9 un l\u00e9ger d\u00e9ficit commercial pour le Canada pour tous les produits soumis \u00e0 la gestion de l\u2019offre, \u00e0 l\u2019exception de la viande de poulet. Par exemple, les importations repr\u00e9sentent aujourd\u2019hui environ 4&nbsp;% du march\u00e9 laitier canadien<sup><a href=\"#legal-8\" data-dig-id=\"LP-8179-d580db52\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"8\" class=\"rbc-link-format\">8<\/a><\/sup>. R\u00e9sultat&nbsp;: le gouvernement a vers\u00e9 4,8&nbsp;milliards de dollars aux producteurs et transformateurs de produits laitiers, de volaille et d\u2019\u0153ufs pour compenser les pertes de b\u00e9n\u00e9fices d\u00e9coulant de la concurrence \u00e9trang\u00e8re<sup><a href=\"#legal-9\" data-dig-id=\"LP-8179-788f2e13\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"9\" class=\"rbc-link-format\">9<\/a><\/sup>. Autrement dit, les Canadiens paient doublement pour leurs aliments soumis \u00e0 la gestion l\u2019offre&nbsp;: \u00e0 la caisse et par le biais de leurs imp\u00f4ts.<\/p>\n\n\n\n<p>De 1995 \u00e0 2017, l\u2019acc\u00e8s des autres pays aux contingents tarifaires dans le secteur laitier canadien \u00e9tait limit\u00e9 par des engagements pris dans le cadre de l\u2019Organisation mondiale du commerce (OMC). Avec la mise en \u0153uvre progressive de l\u2019ACEUM, de l\u2019Accord \u00e9conomique et commercial global (AECG) entre le Canada et l\u2019Union europ\u00e9enne et du PTPGP au cours des 10&nbsp;prochaines ann\u00e9es, l\u2019acc\u00e8s des produits laitiers canadiens aux march\u00e9s \u00e9trangers devrait grimper pour atteindre environ 10&nbsp;% de la production laiti\u00e8re du Canada<sup><a href=\"#legal-10\" data-dig-id=\"LP-8179-86fbae19\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"10\" class=\"rbc-link-format\">10<\/a><\/sup>. En contrepartie, le Canada a \u00e9largi l\u2019acc\u00e8s des pays concern\u00e9s \u00e0 ses march\u00e9s pour les produits laitiers, la volaille et les \u0153ufs. Toutefois, l\u2019augmentation des volumes d\u2019exportation n\u2019est pas un objectif pour les secteurs canadiens sous gestion de l\u2019offre. Le Canada a une petite base de production, et sa cha\u00eene logistique de m\u00eame que ses relations sont pens\u00e9es pour le march\u00e9 int\u00e9rieur. Par cons\u00e9quent, les secteurs sous gestion de l\u2019offre sont mal \u00e9quip\u00e9s pour \u00eatre des chefs de file sur les march\u00e9s mondiaux, o\u00f9 les volumes \u00e9lev\u00e9s et les prix concurrentiels sont essentiels \u00e0 la r\u00e9ussite.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"674\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8360\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?resize=300,197 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?resize=768,505 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?resize=1024,674 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?resize=1536,1011 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-08.png?resize=2048,1348 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Les cha\u00eenes logistiques nationales contribuent \u00e0 prot\u00e9ger les Canadiens contre les r\u00e9percussions des guerres commerciales.<\/strong> En p\u00e9riode de perturbations mondiales, la cha\u00eene logistique alimentaire nationale a bien servi la population. Prenons l\u2019exemple du mouvement \u00ab&nbsp;Acheter canadien&nbsp;\u00bb qui a vu le jour \u00e0 la suite de la guerre commerciale d\u00e9clench\u00e9e par le pr\u00e9sident am\u00e9ricain Donald&nbsp;Trump. Il a entra\u00een\u00e9 une baisse des ventes des marques am\u00e9ricaines, les Canadiens les rempla\u00e7ant par des produits nationaux dans la mesure du possible. En ce qui concerne les produits laitiers, la volaille et les \u0153ufs, plus particuli\u00e8rement, les Canadiens peuvent avoir la certitude d\u2019un acc\u00e8s imm\u00e9diat aux cha\u00eenes d\u2019approvisionnement \u00e9tablies au pays.<\/p>\n\n\n\n<div class=\"wp-block-columns pad-t-dbl mob-pad-t-dbl pad-b-dbl mob-pad-b-dbl pad-l-dbl mob-pad-l-dbl pad-r-dbl mob-pad-r-dbl has-rbc-bright-blue-tint-4-background-color has-background is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<h3 class=\"wp-block-heading\" id=\"h-eliminer-les-failles\">\u00c9liminer les failles&nbsp;:<\/h3>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-black-disc pad-l mob-pad-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p>Dans le cas des produits transform\u00e9s, comme les plats pr\u00e9par\u00e9s, les fronti\u00e8res peuvent \u00eatre floues entre les diff\u00e9rents codes&nbsp;SH (qui permettent de cat\u00e9goriser les biens et de services).<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Ainsi, certains importateurs introduisent leurs produits au Canada en franchise de droits de douane, contournant le syst\u00e8me canadien de contingents tarifaires, qui fixe les volumes allou\u00e9s en vertu d\u2019accords de libre-\u00e9change, y compris l\u2019ACEUM, l\u2019AECG et le PTPGP. <\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Certaines de ces failles ont \u00e9t\u00e9 combl\u00e9es, notamment celle li\u00e9e au fromage import\u00e9 en franchise de droits de douane lorsqu\u2019il entrait dans la composition de plats pr\u00e9par\u00e9s, comme les n\u00e9cessaires \u00e0 pizza destin\u00e9s aux restaurants, qui \u00e9tait exclu des contingents tarifaires. Par contre, d\u2019autres subsistent. C\u2019est le cas, par exemple, de la volaille de r\u00e9forme (poules pondeuses \u00e2g\u00e9es), qui peut \u00eatre cat\u00e9goris\u00e9e \u00e0 tort comme du poulet \u00e0 frire \u00e9lev\u00e9 pour la consommation de viande afin d\u2019\u00e9viter le paiement des droits de douane canadiens.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Bien que les importateurs b\u00e9n\u00e9ficient de contingents tarifaires pour les produits laitiers, les \u0153ufs et la volaille, cette voie d\u2019acc\u00e8s est souvent sous-utilis\u00e9e, puisque les transformateurs canadiens contr\u00f4lent la majorit\u00e9 du syst\u00e8me ainsi que l\u2019espace r\u00e9serv\u00e9 dans les rayons des \u00e9piceries.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Cette situation cause de plus en plus de tensions entre le Canada et ses partenaires commerciaux, surtout les \u00c9tats-Unis qui pr\u00e9tendent que le Canada \u00ab&nbsp;ne respecte pas l\u2019esprit&nbsp;\u00bb de l\u2019ACEUM et complique l\u2019acc\u00e8s des producteurs am\u00e9ricains \u00e0 son march\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"602\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8366\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?resize=300,176 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?resize=768,451 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?resize=1024,602 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?resize=1536,903 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-09.png?resize=2048,1204 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-stabilite\">Stabilit\u00e9<\/h3>\n\n\n\n<p><em><em><em>La gestion de l\u2019offre est synonyme de stabilit\u00e9. Mais \u00e0 quel prix et pour qui&nbsp;? Compte tenu de l\u2019accentuation des perturbations sur les march\u00e9s mondiaux, il est essentiel de d\u00e9terminer une voie qui profite \u00e0 la fois aux agriculteurs et aux consommateurs canadiens.<\/em><\/em><\/em><\/p>\n\n\n\n<p>Les cha\u00eenes logistiques alimentaires canadiennes se sont distingu\u00e9es pendant la pand\u00e9mie et lors d\u2019autres crises, comme la r\u00e9cente \u00e9closion de grippe aviaire qui a ravag\u00e9 l\u2019industrie am\u00e9ricaine.<\/p>\n\n\n\n<p>Aux \u00c9tats-Unis, les prix des \u0153ufs ont r\u00e9cemment explos\u00e9 \u00e0 cause de cette maladie. En juillet&nbsp;2025, on d\u00e9nombrait 174&nbsp;millions de cas confirm\u00e9s dans les exploitations avicoles et plus de 1&nbsp;074&nbsp;troupeaux de vaches laiti\u00e8res avaient \u00e9t\u00e9 touch\u00e9s.<sup><a href=\"#legal-11\" data-dig-id=\"LP-16033-1bc7f3bb\" data-dig-label=\"11\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">11<\/a><\/sup><br><br>TLes r\u00e9percussions ont \u00e9t\u00e9 beaucoup moins graves au Canada, avec environ 14&nbsp;millions d\u2019oiseaux infect\u00e9s et aucun cas signal\u00e9 chez les vaches laiti\u00e8res<sup><a href=\"#legal-12\" data-dig-id=\"LP-8179-25a1087c\" data-dig-label=\"12\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">12<\/a><\/sup>.Par ailleurs, les \u00e9levages canadiens de volaille, de poules pondeuses et de vaches laiti\u00e8res ont mieux r\u00e9sist\u00e9 gr\u00e2ce aux normes de bios\u00e9curit\u00e9 et de bien-\u00eatre animal en vigueur dans le secteur. La production \u00e0 plus petite \u00e9chelle et plus dispers\u00e9e que celle des \u00c9tats-Unis (hormis les zones \u00e0 forte densit\u00e9 telles que la vall\u00e9e du Fraser en Colombie-Britannique) y est aussi pour quelque chose. Ces facteurs propres aux exploitations agricoles contribuent \u00e0 la stabilit\u00e9 des prix \u00e0 la consommation et \u00e0 la disponibilit\u00e9 des produits. De 2017 \u00e0 2025, une douzaine d\u2019\u0153ufs vendus au Canada se vendait en moyenne 1&nbsp;$ de plus qu\u2019aux \u00c9tats-Unis. En f\u00e9vrier&nbsp;2025, toutefois, la situation s\u2019est invers\u00e9e, et la douzaine d\u2019\u0153ufs co\u00fbtaient 3,52&nbsp;$ de plus aux \u00c9tats-Unis qu\u2019au Canada.<sup><a href=\"#legal-13\" data-dig-id=\"LP-16033-ebb98b4e\" data-dig-label=\"13\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">13<\/a> <a href=\"#legal-14\" data-dig-id=\"LP-16033-e68e55f7\" data-dig-label=\"14\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">14<\/a><\/sup><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"609\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8367\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?resize=300,178 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?resize=768,457 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?resize=1024,609 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?resize=1536,914 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-11.png?resize=2048,1218 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Divers enjeux risquent d\u2019intensifier les perturbations des cha\u00eenes logistiques et des march\u00e9s, notamment l\u2019abandon progressif de la r\u00e9glementation du commerce \u00e0 l\u2019\u00e9chelle mondiale, ainsi que les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames et la propagation de maladies et de ravageurs d\u00e9coulant des changements climatiques. Les d\u00e9cideurs doivent en tenir compte, car la volatilit\u00e9 fr\u00e9quente a une incidence sur les prix des marchandises.<\/p>\n\n\n\n<p><strong>La production d\u2019aliments co\u00fbte cher.<\/strong> Dans les secteurs sous gestion de l\u2019offre, les contingents et les prix fixes sont une source de certitude pour les agriculteurs, ce qui favorise la stabilit\u00e9 de la cha\u00eene logistique. Cependant, cette stabilit\u00e9 n\u2019est pas gratuite, car les produits deviennent in\u00e9vitablement plus chers quand le co\u00fbt des intrants augmente au Canada. La d\u00e9t\u00e9rioration de l\u2019accessibilit\u00e9 a un impact disproportionn\u00e9 sur la s\u00e9curit\u00e9 alimentaire des familles \u00e0 faible revenu, mais la forte volatilit\u00e9 des prix influence aussi les d\u00e9penses des m\u00e9nages de la classe moyenne.<sup><a href=\"#legal-15\" data-dig-id=\"LP-16033-e2bef3f0\" data-dig-label=\"15\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">15<\/a> <a href=\"#legal-16\" data-dig-id=\"LP-16033-085289b3\" data-dig-label=\"16\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">16<\/a><\/sup><br><br>Au contraire, les producteurs de bl\u00e9 et les \u00e9leveurs de bovins de boucherie qui ne sont pas assujettis \u00e0 la gestion de l\u2019offre sont expos\u00e9s aux march\u00e9s des marchandises, de sorte que leurs marges b\u00e9n\u00e9ficiaires et les prix de leurs produits fluctuent en fonction de l\u2019\u00e9volution de ces march\u00e9s. Les agriculteurs non soumis \u00e0 la gestion de l\u2019offre sont souvent \u00e0 la merci des prix et ne peuvent pas refiler la hausse des co\u00fbts aux consommateurs.<\/p>\n\n\n\n<p><strong>L\u2019aide fournie par le Canada aux agriculteurs est controvers\u00e9e, mais comparable \u00e0 celle des \u00c9tats-Unis.<\/strong> Si l\u2019on compare le total du soutien direct aux producteurs, l\u2019apport des \u00c9tats-Unis est 6,5&nbsp;fois sup\u00e9rieur \u00e0 celui du Canada. Cela dit, les deux pays sont \u00e0 peu pr\u00e8s \u00e0 \u00e9galit\u00e9 si l\u2019on consid\u00e8re les estimations du soutien direct aux producteurs en pourcentage de la valeur produite \u00e0 la sortie de l\u2019exploitation, soit environ 7&nbsp;%<sup><a href=\"#legal-17\" data-dig-id=\"LP-8179-74a8a35e\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"17\" class=\"rbc-link-format\">17<\/a><\/sup>. En ce qui concerne les produits soumis \u00e0 la gestion de l\u2019offre, le soutien aux producteurs est clairement align\u00e9 sur l\u2019approche de chaque pays. L\u2019apport du Canada correspond au prix que les producteurs re\u00e7oivent en fonction de la gestion de l\u2019offre, tandis que celui des \u00c9tats-Unis fluctue au gr\u00e9 de la volatilit\u00e9 des march\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"543\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8368\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?resize=300,159 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?resize=768,407 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?resize=1024,543 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?resize=1536,815 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-10.png?resize=2048,1086 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Les exploitations agricoles sous gestion de l\u2019offre contribuent \u00e0 la prosp\u00e9rit\u00e9 de l\u2019\u00e9conomie rurale du Canada.<\/strong> La stabilit\u00e9 joue \u00e9galement un r\u00f4le \u00e9largi dans l\u2019\u00e9conomie rurale canadienne. Les donn\u00e9es du plus r\u00e9cent recensement agricole montrent que, sur une p\u00e9riode de cinq ans (de 2016 \u00e0 2021), le nombre de fermes laiti\u00e8res a diminu\u00e9 de 11&nbsp;%, tandis que la taille des troupeaux a augment\u00e9 de 13&nbsp;%<sup><a href=\"#legal-18\" data-dig-id=\"LP-8179-7891006e\" data-dig-label=\"18\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">18<\/a><\/sup>. Aux \u00c9tats-Unis, sur la m\u00eame p\u00e9riode, le nombre de fermes laiti\u00e8res a recul\u00e9 de 34&nbsp;%, et la taille des troupeaux a grimp\u00e9 de 48&nbsp;%<sup><a href=\"#legal-19\" data-dig-id=\"LP-8179-29396dfa\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"19\" class=\"rbc-link-format\">19<\/a><\/sup>. La consolidation permet aux grandes exploitations laiti\u00e8res am\u00e9ricaines de r\u00e9aliser des \u00e9conomies d\u2019\u00e9chelle. Par contre, chez nos voisins du sud, cette tendance r\u00e9cente entra\u00eene une perte de diversit\u00e9 en termes de taille des exploitations et une concentration des troupeaux, ce qui les rend plus vuln\u00e9rables aux maladies et aux \u00e9pid\u00e9mies de ravageurs. De plus, il y a un risque de chute de la demande \u00e0 l\u2019\u00e9gard des entreprises de soutien et au sein des communaut\u00e9s rurales.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-standards\">Standards<\/h3>\n\n\n\n<p><em><em><em>Le syst\u00e8me canadien de la gestion de l\u2019offre r\u00e9pond \u00e0 des normes \u00e9lev\u00e9es, ce qui se traduit par une efficacit\u00e9 accrue et de meilleurs r\u00e9sultats en mati\u00e8re de durabilit\u00e9. N\u00e9anmoins, ce syst\u00e8me n\u2019est pas con\u00e7u pour maximiser la production.<\/em><\/em><\/em><\/p>\n\n\n\n<p>Les agriculteurs canadiens renforcent de plus en plus leurs capacit\u00e9s \u00e0 mesurer, d\u00e9clarer et v\u00e9rifier leurs progr\u00e8s dans l\u2019adoption de pratiques de gestion exemplaires, plus particuli\u00e8rement celles li\u00e9es \u00e0 la durabilit\u00e9 environnementale et au bien-\u00eatre animal. La gestion de l\u2019offre s\u2019accompagne d\u2019une solide gouvernance et d\u2019un contr\u00f4le des march\u00e9s, ce qui favorise l\u2019adoption g\u00e9n\u00e9ralis\u00e9e et uniforme de pratiques et de normes, \u00e0 la ferme et \u00e0 chaque \u00e9tape de la cha\u00eene d\u2019approvisionnement. Pour participer aux march\u00e9s r\u00e9glement\u00e9s, les exploitations soumises \u00e0 la gestion de l\u2019offre adh\u00e8rent \u00e0 un code de pratique et \u00e0 des normes, ce qui explique le rehaussement des standards canadiens concernant le bien-\u00eatre et la sant\u00e9 des animaux, ainsi que la qualit\u00e9 des aliments. Bien que cela puisse \u00eatre contraignant, les agriculteurs doivent s\u2019y conformer afin d\u2019acc\u00e9der \u00e0 ces march\u00e9s. Les syst\u00e8mes de production canadiens qui ne sont pas assujettis \u00e0 la gestion de l\u2019offre, comme celui du b\u0153uf, disposent aussi de programmes qui garantissent le respect de normes \u00e9lev\u00e9es dans les exploitations agricoles, par exemple, le programme d\u2019assurance qualit\u00e9 du b\u0153uf nourri au ma\u00efs de l\u2019Ontario. Toujours est-il que le syst\u00e8me de gouvernance de la gestion de l\u2019offre permet une adoption g\u00e9n\u00e9ralis\u00e9e et uniforme des pratiques<a>&nbsp;\u2013<\/a> un objectif difficile \u00e0 atteindre lorsque la r\u00e9glementation et le contr\u00f4le des march\u00e9s sont moins rigoureux.<\/p>\n\n\n\n<p><strong>Des standards plus stricts que ceux des \u00c9tats-Unis&nbsp;:<\/strong> Le programme proAction a \u00e9t\u00e9 mis sur pied par les Producteurs laitiers du Canada afin d\u2019\u00e9tablir des normes et d\u2019encadrer les pratiques entourant les six volets suivants&nbsp;: qualit\u00e9 du lait, salubrit\u00e9 des aliments, tra\u00e7abilit\u00e9, bios\u00e9curit\u00e9, bien-\u00eatre des animaux et environnement. Un total de 99,7&nbsp;% des producteurs laitiers canadiens y adh\u00e8rent<sup><a href=\"#legal-20\" data-dig-id=\"LP-8179-68d5a52e\" data-dig-label=\"20\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">20<\/a><\/sup>. De m\u00eame, aux \u00c9tats-Unis, il y a le programme National Dairy Farmers Assuring Responsible Management (FARM), qui couvre 99&nbsp;% de l\u2019offre de lait du pays<sup><a href=\"#legal-21\" data-dig-id=\"LP-8179-8f035926\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"21\" class=\"rbc-link-format\">21<\/a><\/sup>. Toutefois, les normes de ces deux programmes et les r\u00e9glementations compl\u00e9mentaires diff\u00e8rent, ce qui peut avoir des r\u00e9percussions sur la sant\u00e9 animale et la qualit\u00e9 du lait. Les \u00c9tats-Unis autorisent aussi des valeurs plus \u00e9lev\u00e9es pour le comptage des cellules somatiques, c\u2019est-\u00e0-dire le nombre de globules blancs des vaches. Tout comme chez les humains, un taux \u00e9lev\u00e9 de globules blancs signifie que l\u2019organisme lutte contre une maladie ou une inflammation, ce qui est susceptible d\u2019alt\u00e9rer la qualit\u00e9 du lait. Aux \u00c9tats-Unis, la limite est de 750&nbsp;000&nbsp;cellules somatiques individuelles par millilitre (ml), tandis qu\u2019au Canada, elle est de 400&nbsp;000&nbsp;cellules somatiques individuelles par ml <sup><a href=\"#legal-22\" data-dig-id=\"LP-8179-c0851686\" data-dig-label=\"22\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">22<\/a> <a href=\"#legal-23\" data-dig-id=\"LP-8179-12378efe\" data-dig-label=\"23\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">23<\/a><\/sup>.<\/p>\n\n\n\n<p><strong>L\u2019industrie met l\u2019accent sur l\u2019efficacit\u00e9 et la durabilit\u00e9.<\/strong> Les cadres de gouvernance de la gestion de l\u2019offre fournissent \u00e9galement une plateforme pour accro\u00eetre la participation des agriculteurs \u00e0 des initiatives sectorielles touchant divers sujets, dont l\u2019efficacit\u00e9, l\u2019innovation et la durabilit\u00e9. Par exemple, les producteurs d\u2019\u0153ufs du Canada mesurent et d\u00e9clarent leurs progr\u00e8s en mati\u00e8re de durabilit\u00e9 par l\u2019interm\u00e9diaire de l\u2019Outil d\u2019\u00e9valuation de l\u2019empreinte \u00e9cologique des fermes (OEEEF). Cette approche unifi\u00e9e fait contrepoids \u00e0 la fragmentation croissante des projets ax\u00e9s sur la durabilit\u00e9 et la r\u00e9g\u00e9n\u00e9ration que de nombreux agriculteurs entreprennent pour acc\u00e9der au march\u00e9 ou obtenir de nouvelles sources de revenus gr\u00e2ce \u00e0 des m\u00e9canismes comme les cr\u00e9dits carbone et les primes vertes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" height=\"595\" width=\"1024\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?quality=80&amp;w=1024\" alt=\"\" class=\"wp-image-8369\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png 4000w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?resize=300,174 300w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?resize=768,446 768w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?resize=1024,595 1024w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?resize=1536,893 1536w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/Supply-Management-Graphs-FR-12.png?resize=2048,1190 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t-0 mob-pad-t-0\" style=\"border-radius:0x\">\n<h2 class=\"wp-block-heading has-rbc-dark-blue-tint-color has-text-color has-link-color wp-elements-5fe0b6dae2536e792ba35fc13c686683\" id=\"h-lecons-pour-l-industrie-laitiere-comment-les-autres-marches-mondiaux-se-debrouillent-face-a-la-transition-et-aux-perturbations\">Le\u00e7ons pour l\u2019industrie laiti\u00e8re&nbsp;: comment les autres march\u00e9s mondiaux se d\u00e9brouillent face \u00e0 la transition et aux perturbations<\/h2>\n\n\n\n<p>La s\u00e9curit\u00e9 et la souverainet\u00e9 alimentaires figurent parmi les priorit\u00e9s des gouvernements du monde entier, \u00e0 l\u2019heure o\u00f9 les ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames d\u00e9truisent les cultures et o\u00f9 les barri\u00e8res commerciales perturbent les \u00e9changes.<\/p>\n\n\n\n<p>Les produits laitiers, qui sont importants tant sur le plan nutritif que culturel (qu\u2019on pense au fromage fran\u00e7ais ou lassi indien) connaissent une forte demande, mais aussi une grande volatilit\u00e9 sur les march\u00e9s internationaux. C\u2019est pourquoi le secteur fait l\u2019objet d\u2019une attention particuli\u00e8re en mati\u00e8re de politique, de commerce et de soutien aux agriculteurs.<\/p>\n\n\n\n<p>Voici comment d\u2019autres pays g\u00e8rent leur industrie laiti\u00e8re en cette p\u00e9riode de transition et de perturbation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-nouvelle-zelande-un-chef-de-file-international-dont-l-empreinte-ges-est-en-hausse\"><strong><strong>Nouvelle-Z\u00e9lande&nbsp;:<\/strong> Un chef de file international dont l\u2019empreinte GES est en hausse<\/strong><\/h3>\n\n\n\n<p>La Nouvelle-Z\u00e9lande a aboli ses contingents de production dans les ann\u00e9es&nbsp;1980 en raison d\u2019une crise budg\u00e9taire, faisant ainsi du pays le plus grand exportateur de produits laitiers au monde. En 2001, le gouvernement a mis en place Fonterra, une coop\u00e9rative agricole qui fixe les prix. Cette derni\u00e8re est maintenant le principal acheteur de lait n\u00e9o-z\u00e9landais. Le calcul des prix est fond\u00e9 sur les revenus tir\u00e9s de la vente de lait, d\u00e9duction faite des charges d\u2019exploitation, des frais g\u00e9n\u00e9raux et du recouvrement du capital. La Nouvelle-Z\u00e9lande a plus que doubl\u00e9 son cheptel national depuis le d\u00e9but des ann\u00e9es&nbsp;1980. La taille des troupeaux individuels a tripl\u00e9 et leur nombre est pass\u00e9 de 15&nbsp;753 en 1985 \u00e0 10&nbsp;485 en 2024<sup><a href=\"#legal-24\" data-dig-id=\"LP-8179-9b12f225\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"24\" class=\"rbc-link-format\">24<\/a><\/sup>. La lib\u00e9ralisation du march\u00e9 a m\u00e9tamorphos\u00e9 les cha\u00eenes d\u2019approvisionnement de l\u2019industrie laiti\u00e8re n\u00e9o-z\u00e9landaise, plus particuli\u00e8rement celle de la production de lait en poudre, dont le volume a augment\u00e9 de 237&nbsp;% depuis 2000, gr\u00e2ce aux accords de libre-\u00e9change conclus avec de grands importateurs comme la Chine et aux investissements \u00e9trangers et nationaux pour renforcer la capacit\u00e9 et automatiser les processus de transformation<sup><a href=\"#legal-25\" data-dig-id=\"LP-8179-68bc2bde\" data-dig-label=\"25\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">25<\/a><\/sup>.<\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse1d7993ea\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse1d7993ea\" data-dig-id=\"LP-8179-1d7993ea\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"En savoir plus\"><span>En savoir plus<\/span><span>lire les fichiers<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse1d7993ea\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p>Le secteur a gagn\u00e9 en efficacit\u00e9 et en comp\u00e9titivit\u00e9, comme en t\u00e9moigne la consolidation du cheptel. En revanche, la croissance du nombre de vaches a accentu\u00e9 ses r\u00e9percussions environnementales, notamment ses \u00e9missions de gaz \u00e0 effet de serre (GES). Aujourd\u2019hui, en Nouvelle-Z\u00e9lande, l\u2019agriculture est \u00e0 l\u2019origine de plus de 50&nbsp;% des \u00e9missions de GES du pays, et c\u2019est surtout \u00e0 cause de l\u2019industrie laiti\u00e8re<sup><a href=\"#legal-26\" data-dig-id=\"LP-8179-9857ab26\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"26\" class=\"rbc-link-format\">26<\/a><\/sup>. Les r\u00e9cents objectifs en mati\u00e8re de GES ont fait na\u00eetre de l\u2019incertitude dans le secteur, ce qui a donn\u00e9 lieu \u00e0 une r\u00e9vision des cibles nationales et du r\u00f4le de l\u2019agriculture dans l\u2019atteinte de celles-ci. Le partenariat public-priv\u00e9 AgriZero met l\u2019accent sur le financement participatif et l\u2019acc\u00e9l\u00e9ration de la lutte contre les changements climatiques en agriculture. Il s\u2019agit d\u2019un mod\u00e8le unique pour mobiliser des fonds \u00e0 un moment o\u00f9 l\u2019attention port\u00e9e \u00e0 cette lutte s\u2019essouffle.<\/p>\n\n\n\n<p><strong>Le\u00e7on pour le Canada&nbsp;:<\/strong> En tant que premi\u00e8re initiative du genre, AgriZero peut servir d\u2019exemple au Canada, dans un contexte o\u00f9 les fonds destin\u00e9s \u00e0 la lutte contre les changements climatiques s\u2019\u00e9puisent et o\u00f9 le besoin d\u2019une action coordonn\u00e9e et \u00e0 grande \u00e9chelle dans le secteur agricole se fait de plus en plus pressant.<br><\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-royaume-uni-abandon-du-modele-de-l-ue\"><strong><strong>Royaume-Uni&nbsp;: <\/strong>Abandon du mod\u00e8le de l\u2019UE<\/strong><\/h3>\n\n\n\n<p>Depuis le Brexit, le Royaume-Uni r\u00e9oriente sa politique vers des subventions r\u00e9gionales dans le cadre des dispositifs de gestion environnementale des terres. Ces dispositifs reposent sur des mesures d\u2019agriculture durable, par exemple, la r\u00e9habilitation des terres marginales. Les producteurs laitiers britanniques recevaient des paiements directs au titre de la politique agricole commune de l\u2019UE, mais ces versements seront progressivement \u00e9limin\u00e9s d\u2019ici 2028, \u00e9tant donn\u00e9 la sortie du Royaume-Uni du bloc \u00e9conomique. Cette transition impose un fardeau financier et administratif, alors m\u00eame que les agriculteurs doivent s\u2019adapter au changement, tout en faisant face \u00e0 la hausse des co\u00fbts de production au niveau national et \u00e0 la concurrence accrue des importateurs.<\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse7c2afe51\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse7c2afe51\" data-dig-id=\"LP-8179-7c2afe51\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"En savoir plus\"><span>En savoir plus<\/span><span>lire les fichiers<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse7c2afe51\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p>Afin de favoriser les \u00e9changes agroalimentaires entre l\u2019UE et le Royaume-Uni, les deux ont convenu d\u2019\u00e9tablir un espace sanitaire et phytosanitaire commun (c\u2019est-\u00e0-dire des normes collectives en mati\u00e8re de s\u00e9curit\u00e9 et de qualit\u00e9 des aliments). Toutefois, certains estiment que cette d\u00e9cision maintient les liens du Royaume-Uni avec l\u2019UE et pourrait entraver sa capacit\u00e9 \u00e0 conclure des accords commerciaux avec d\u2019autres pays.<br><br><strong>Le\u00e7on pour le Canada&nbsp;:<\/strong> Au moment o\u00f9 le Canada s\u2019engage dans une mission visant \u00e0 renforcer et \u00e0 diversifier ses relations commerciales internationales, il convient d\u2019\u00e9viter de passer d\u2019une d\u00e9pendance excessive envers les \u00c9tats-Unis \u00e0 un alignement trop important sur des normes \u00e9trang\u00e8res restrictives \u00e0 outrance \u00e0 l\u2019\u00e9gard des produits agroalimentaires.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bresil-la-difficulte-de-percer-sur-le-marche-mondial-malgre-une-ambition-affichee\"><strong><strong>Br\u00e9sil&nbsp;: <\/strong>La difficult\u00e9 de percer sur le march\u00e9 mondial, malgr\u00e9 une ambition affich\u00e9e<\/strong><\/h3>\n\n\n\n<p>Le Br\u00e9sil a transform\u00e9 son secteur agricole et se classe maintenant parmi les plus grands exportateurs agroalimentaires, n\u2019\u00e9tant devanc\u00e9 que par les \u00c9tats-Unis. Pourtant, moins de 1&nbsp;% de la production laiti\u00e8re du pays est export\u00e9e<sup><a href=\"#legal-27\" data-dig-id=\"LP-8179-11822114\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"27\" class=\"rbc-link-format\">27<\/a><\/sup>. La demande int\u00e9rieure, un syst\u00e8me de commercialisation qui n\u2019est pas ax\u00e9 sur les exportations et la forte concurrence sur le march\u00e9 international ont frein\u00e9 son expansion.<\/p>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapsee3970d06\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapsee3970d06\" data-dig-id=\"LP-8179-e3970d06\" data-dig-category=\"LP\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"En savoir plus\"><span>En savoir plus<\/span><span>lire les fichiers<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapsee3970d06\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<p>Les infrastructures de production et de transformation des produits laitiers du Br\u00e9sil varient grandement, allant des petites exploitations de subsistance aux entreprises modernes de grande envergure. Les premi\u00e8res peuvent b\u00e9n\u00e9ficier de subventions pour les investissements dans des actifs tels que les cuves de refroidissement, les p\u00e2turages et les infrastructures de traite. Les prix pay\u00e9s aux agriculteurs sont principalement dict\u00e9s par le march\u00e9, mais le gouvernement peut intervenir par l\u2019interm\u00e9diaire de la CONAB (soci\u00e9t\u00e9 nationale d\u2019approvisionnement) et acheter le lait exc\u00e9dentaire ou accorder des subventions pour l\u2019entreposage.<\/p>\n\n\n\n<p>Affichant l\u2019ambition d\u2019une perc\u00e9e internationale fracassante, le Br\u00e9sil devra affronter une vive concurrence, notamment de la part de la Nouvelle-Z\u00e9lande, qui lorgne elle aussi les march\u00e9s du Moyen-Orient, de l\u2019Am\u00e9rique latine et de l\u2019Asie. Pour conna\u00eetre une croissance mondiale, le Br\u00e9sil doit aussi revoir ses normes et r\u00e9glementations moins rigoureuses en mati\u00e8re d\u2019utilisation des terres, d\u2019\u00e9missions de GES, de tra\u00e7abilit\u00e9 et de services logistiques de la cha\u00eene du froid.<\/p>\n\n\n\n<p><strong>Le\u00e7on pour le Canada&nbsp;:<\/strong> Bien que le Br\u00e9sil et le Canada aient suivi jusqu\u2019\u00e0 pr\u00e9sent des trajectoires diff\u00e9rentes, ils se disputent de plus en plus la m\u00eame part du march\u00e9 mondial des exportations agroalimentaires. L\u2019approche du Br\u00e9sil, qui favorise la coexistence d\u2019exploitations de tailles diverses et cible la croissance \u00e0 la fois du march\u00e9 int\u00e9rieur et des exportations, devrait inciter le Canada \u00e0 examiner sa propre production, qui continue de se consolider et qui fait face \u00e0 une concurrence \u00e9trang\u00e8re croissante.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel mar-b-dbl mob-mar-b-dbl\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t mob-pad-t pad-b mob-pad-b pad-l mob-pad-l pad-r mob-pad-r has-rbc-bright-blue-tint-4-background-color has-background\" style=\"border-radius:0x\">\n<h3 class=\"wp-block-heading\" id=\"h-perspectives-des-marches\">PERSPECTIVES DES MARCH\u00c9S<\/h3>\n\n\n\n<p>Le syst\u00e8me canadien de la gestion de l\u2019offre est con\u00e7u pour offrir une protection contre les fluctuations des march\u00e9s internationaux. Les d\u00e9cideurs doivent n\u00e9anmoins rester \u00e0 l\u2019aff\u00fbt des changements structurels et des tendances macro\u00e9conomiques ayant trait \u00e0 l\u2019agriculture mondiale.<\/p>\n\n\n\n<p><strong><strong>Produits laitiers<\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-black-disc pad-l mob-pad-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p>On s\u2019attend \u00e0 ce que les prix mondiaux r\u00e9els des produits laitiers pour les producteurs suivent une tendance baissi\u00e8re au cours de cette d\u00e9cennie. Toutefois, ils devraient augmenter par rapport au co\u00fbt des intrants, surtout \u00e0 mesure que la production laiti\u00e8re par animal progresse<sup><a href=\"#legal-28\" data-dig-id=\"LP-8179-7d1f17fb\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"28\" class=\"rbc-link-format\">28<\/a><\/sup>. Les agriculteurs am\u00e9ricains pourraient voir leurs prix r\u00e9els baisser en moyenne de 8&nbsp;% par an, ce qui risque de se traduire par une baisse des rendements pour les fermes laiti\u00e8res qui n\u2019innovent pas et ne se d\u00e9veloppent pas sur les march\u00e9s des marchandises<sup><a href=\"#legal-29\" data-dig-id=\"LP-8179-d58cb294\" data-dig-label=\"29\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">29<\/a><\/sup>.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>La consommation mondiale de produits laitiers devrait augmenter de 1&nbsp;% par an. La production, quant \u00e0 elle, devrait cro\u00eetre de 1,6&nbsp;% par an pour s\u2019\u00e9tablir \u00e0 1&nbsp;085&nbsp;millions de tonnes, stimul\u00e9e par celle de l\u2019Inde, du Pakistan et de l\u2019Afrique subsaharienne, qui est principalement destin\u00e9e \u00e0 la consommation int\u00e9rieure.<sup><a href=\"#legal-30\" data-dig-id=\"LP-16033-7893d3b4\" data-dig-label=\"30\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">30<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>La consommation de produits laitiers frais en Am\u00e9rique du Nord et en Europe est stable ou en baisse. Cela s\u2019explique par le fait que les consommateurs d\u00e9laissent le lait entier et la cr\u00e8me et que des boissons v\u00e9g\u00e9tales, comme le lait d\u2019avoine, se sont impos\u00e9es comme solution de remplacement. La consommation de produits laitiers transform\u00e9s, notamment le beurre et le lait en poudre, est en hausse, en raison de leur utilisation dans la fabrication de produits alimentaires, comme les pr\u00e9parations pour nourrissons et les produits de boulangerie. Enfin, la consommation de fromage, qui est \u00e9troitement li\u00e9e au revenu des m\u00e9nages, augmente dans certains march\u00e9s internationaux en plein essor, tels que le Mexique, les \u00c9tats-Unis, le Br\u00e9sil et l\u2019Arabie saoudite.<sup><a href=\"#legal-31\" data-dig-id=\"LP-16033-3a570b57\" data-dig-label=\"31\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">31<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Seulement 7&nbsp;% de la production mondiale de lait est vendue \u00e0 l\u2019international, \u00e0 cause de la nature p\u00e9rissable de cette denr\u00e9e et du fait que dans de nombreux pays, les syst\u00e8mes de commercialisation sont surtout con\u00e7us pour la distribution nationale ou r\u00e9gionale, \u00e0 quelques exceptions pr\u00e8s comme la Nouvelle-Z\u00e9lande et l\u2019Irlande. Cependant, plus de 50&nbsp;% du lait en poudre, y compris entier et \u00e9cr\u00e9m\u00e9, est export\u00e9.<sup><a href=\"#legal-32\" data-dig-id=\"LP-16033-d1575856\" data-dig-label=\"32\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">32<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Seulement 7&nbsp;% de la production mondiale de lait est vendue \u00e0 l\u2019international, \u00e0 cause de la nature p\u00e9rissable de cette denr\u00e9e et du fait que dans de nombreux pays, les syst\u00e8mes de commercialisation sont surtout con\u00e7us pour la distribution nationale ou r\u00e9gionale, \u00e0 quelques exceptions pr\u00e8s comme la Nouvelle-Z\u00e9lande et l\u2019Irlande. Cependant, plus de 50&nbsp;% du lait en poudre, y compris entier et \u00e9cr\u00e9m\u00e9, est export\u00e9.<sup><a href=\"#legal-33\" data-dig-id=\"LP-16033-89d4c618\" data-dig-label=\"33\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">33<\/a><\/sup><\/p>\n<\/li>\n<\/ul>\n\n\n\n<p><strong><strong><strong>Volaille et \u0153ufs<\/strong><\/strong><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-rbc-list is-style-black-disc pad-l mob-pad-l\">\n<li class=\"wp-block-rbc-list-item\">\n<p>Les prix mondiaux de la volaille et des \u0153ufs devraient baisser \u00e0 la suite du repli de l\u2019inflation et du co\u00fbt des intrants. Par exemple, aux \u00c9tats-Unis, le prix \u00e0 la ferme d\u2019une douzaine d\u2019\u0153ufs devrait diminuer de 0,90&nbsp;$&nbsp;US au cours de la prochaine d\u00e9cennie, avec un recul moyen de 4&nbsp;% d\u2019une ann\u00e9e sur l\u2019autre<sup><a href=\"#legal-34\" data-dig-id=\"LP-8179-0d42a344\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"34\" class=\"rbc-link-format\">34<\/a><\/sup>. Par ailleurs, on s\u2019attend \u00e0 ce que la production am\u00e9ricaine augmente de 12&nbsp;% d\u2019ici&nbsp;2033, par rapport \u00e0 l\u2019ann\u00e9e de r\u00e9f\u00e9rence&nbsp;2022.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>Stimul\u00e9e par la demande croissante, la production de volaille devrait s\u2019intensifier et finir par repr\u00e9senter pr\u00e8s de la moiti\u00e9 de toute la viande produite. On anticipe une hausse de 16&nbsp;% de la consommation de volaille dans les 10&nbsp;ann\u00e9es qui viennent, soit la plus forte progression parmi les prot\u00e9ines animales. D\u2019ici&nbsp;2034, la volaille devrait repr\u00e9senter 43&nbsp;% des prot\u00e9ines animales consomm\u00e9es, avec une croissance notable au Br\u00e9sil, en Europe et aux \u00c9tats-Unis.<sup><a href=\"#legal-35\" data-dig-id=\"LP-16033-bc792bb2\" data-dig-label=\"35\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">35<\/a><\/sup><\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>La politique alimentaire autonome de la Chine et la r\u00e9cente r\u00e9surgence de la peste porcine africaine et de la grippe aviaire ont entra\u00een\u00e9 une diminution du commerce mondial de viande par rapport au sommet atteint en 2021, ann\u00e9e o\u00f9 la Chine comptait pour environ le quart des importations mondiales de viande.<\/p>\n<\/li>\n\n\n\n<li class=\"wp-block-rbc-list-item\">\n<p>La croissance de la population et du PIB en Afrique et en Asie est susceptible de faire rebondir les exportations de viande au cours de la prochaine d\u00e9cennie, surtout celles de volaille, qui devrait repr\u00e9senter plus de 40&nbsp;% du total.<sup><a href=\"#legal-36\" data-dig-id=\"LP-16033-fb402acf\" data-dig-label=\"36\" data-dig-action=\"link click\" data-dig-category=\"LP\" class=\"rbc-link-format\">36<\/a><\/sup><\/p>\n<\/li>\n<\/ul>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel mar-b-dbl mob-mar-b-dbl\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block inner-section-white section-inner  has-rbc-bright-blue-tint-1-background-color has-background\" style=\"border-radius:0x\">\n<section class=\"wp-block-rbc-section-block  pos-rel has-rbc-bright-blue-tint-1-background-color has-background\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t-0 mob-pad-t-0 pad-b-0 mob-pad-b-0\" style=\"border-radius:0x\">\n<h3 class=\"wp-block-heading has-white-color has-text-color has-link-color wp-elements-a63b650448f58837b16990f4da46a13a\" id=\"h-contributeurs\">Contributeurs :<\/h3>\n\n\n\n<p class=\"mob-mar-b-0 mar-b-0 has-white-color has-text-color has-link-color wp-elements-d2509a8784e4e833366a9ace4155d82f\"><strong>Auteur principal<\/strong><\/p>\n\n\n\n<p class=\"mar-b-hlf mob-mar-b-hlf has-white-color has-text-color has-link-color wp-elements-a73449ad55a19e22000f4e2ead321c66\"><strong>Lisa Ashton <\/strong>&#8211; directrice, Politique agricole<\/p>\n\n\n\n<p class=\"mar-b-0 mob-mar-b-0 has-white-color has-text-color has-link-color wp-elements-23f40b3c5e333a0f6aa60369d8bc06ac\"><strong>\u00c9diteur<\/strong><\/p>\n\n\n\n<p class=\"mar-b-hlf mob-mar-b-hlf has-white-color has-text-color has-link-color wp-elements-4e9d8916172a629fdcb24f62ee79dcfc\"><strong>Yadullah Hussain<\/strong> &#8211; r\u00e9dacteur en chef<\/p>\n\n\n\n<p class=\"mob-mar-b-0 mar-b-0 has-white-color has-text-color has-link-color wp-elements-fbef68487de6f40c93f8e48c3c1339a2\"><strong>Conception et r\u00e9alisation<\/strong><\/p>\n\n\n\n<p class=\"mob-mar-b-0 mar-b-0 has-white-color has-text-color has-link-color wp-elements-76471a80fe223313233b264d609b868b\"><strong>Caprice Biasoni <\/strong>&#8211; sp\u00e9cialiste en design graphiqu<\/p>\n<\/div>\n<\/section>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<div class=\"wp-block-columns has-border-color has-grey-border-color is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" style=\"border-width:1px\">\n<div class=\"wp-block-column has-border-color has-grey-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:1px;flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"362\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Download-PDF-FR.png?quality=80\" alt=\"\" class=\"wp-image-8361\" srcset=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Download-PDF-FR.png 572w, https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Download-PDF-FR.png?resize=300,190 300w\" sizes=\"auto, (max-width: 572px) 100vw, 572px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h4 class=\"wp-block-heading mar-t mar-l\" id=\"h-telecharger-le-rapport\">T\u00e9l\u00e9charger le rapport<\/h4>\n\n\n\n<div class=\"wp-block-buttons  mar-l is-layout-flex wp-block-buttons-is-layout-flex\"><div>\n<div class=\"wp-block-button btn before is-style-tertiary tertiary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/RBC-TL-Demystification-de-la-gestion-de-loffre-Report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" data-dig-id=\"LP-8179-09519300\" data-dig-category=\"LP\" data-dig-action=\"button click\" data-dig-label=\"T\u00e9l\u00e9charger-https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/RBC-TL-Demystification-de-la-gestion-de-loffre-Report.pdf \">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-rbc-legal-collapsible disclaimer\" aria-label=\"Legal Disclaimers\"><div class=\"section-inner\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapseDisclaimer\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapseDisclaimer\" data-dig-id=\"LP-8179-742161de\" data-dig-category=\"LP\" data-dig-action=\"legal close\" data-dig-label=\"legal close\" action-closed=\"legal close\" action-opened=\"legal open\" label-close=\"legal open\" label-open=\"legal close\"><span>References<\/span><span>Hide References<\/span><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapseDisclaimer\"><div class=\"collapse-inner\"><div class=\"table-wpr\">\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-1\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>1<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. PIB au prix de base, par secteur, province et territoire, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-2\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>2<\/sup><\/div><div class=\"table-cell\">\n<p>Agriculture et Agroalimentaire Canada (AAC). Aper\u00e7u du secteur agricole et agroalimentaire canadien, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-3\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>3<\/sup><\/div><div class=\"table-cell\">\n<p><a href=\"https:\/\/dairyfarmersofcanada.ca\/en\/canadian-goodness\/articles\/what-supply-management-means-canadians\" data-dig-id=\"LP-8179-ee651682\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"Les Producteurs laitiers du Canada\" class=\"rbc-link-format\">Les Producteurs laitiers du Canada<\/a>. Ce que repr\u00e9sente la gestion de l\u2019offre pour les Canadiens, 2024.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-4\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>4<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. Exploitations agricoles class\u00e9es selon leur type, donn\u00e9es chronologiques du Recensement de l\u2019agriculture, 2022..<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-5\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>5<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-6\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>6<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-7\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>7<\/sup><\/div><div class=\"table-cell\">\n<p>Association des transformateurs laitiers du Canada. Accord de Partenariat transpacifique global et progressiste (PTPGP).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-8\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>8<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. Statistiques laiti\u00e8res et informations sur les march\u00e9s, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-9\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>9<\/sup><\/div><div class=\"table-cell\">\n<p>Agriculture et Agroalimentaire Canada (AAC). Soutien des industries canadiennes sous gestion de l\u2019offre, 2023.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-10\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>10<\/sup><\/div><div class=\"table-cell\">\n<p>Association des transformateurs laitiers du Canada. Accord Canada\u2013\u00c9tats-Unis\u2013Mexique (ACEUM).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-11\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>11<\/sup><\/div><div class=\"table-cell\">\n<p>Centers for Disease Control and Prevention des \u00c9tats-Unis. Avian Influenza (Bird Flu), 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-12\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>12<\/sup><\/div><div class=\"table-cell\">\n<p>Agence canadienne d\u2019inspection des aliments (ACIA). \u00c9tat de r\u00e9ponse en cours aux d\u00e9tections d\u2019influenza aviaire, par province, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-13\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>13<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. Prix de d\u00e9tail moyens mensuels pour certains produits, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-14\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>14<\/sup><\/div><div class=\"table-cell\">\n<p>Bureau of Labor Statistics des \u00c9tats-Unis. Consumer Price Index&nbsp;\u2013 Average price data, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-15\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>15<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. D\u00e9penses des m\u00e9nages selon le quintile de revenu du m\u00e9nage, Canada, r\u00e9gions et provinces, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-16\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>16<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. Ins\u00e9curit\u00e9 alimentaire selon le type de famille \u00e9conomique, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-17\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>17<\/sup><\/div><div class=\"table-cell\">\n<p>Organisation de coop\u00e9ration et de d\u00e9veloppement \u00e9conomiques (OCDE). Suivi de la politique agricole, 2024.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-18\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>18<\/sup><\/div><div class=\"table-cell\">\n<p>Statistique Canada. Nombre de bovins, selon la classe et le type d\u2019exploitation agricole (x&nbsp;1&nbsp;000), 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-19\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>19<\/sup><\/div><div class=\"table-cell\">\n<p>National Agricultural Statistic Services du Department of Agriculture des \u00c9tats-Unis. 2022 Census of Agriculture, 2024.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-20\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>20<\/sup><\/div><div class=\"table-cell\">\n<p>Les Producteurs laitiers du Canada. proAction, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-21\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>21<\/sup><\/div><div class=\"table-cell\">\n<p>Farmers Assuring Responsible Management (FARM).Animal Care, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-22\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>22<\/sup><\/div><div class=\"table-cell\">\n<p>Les Producteurs laitiers du Canada. proAction&nbsp;\u2013 Qualit\u00e9 du lait, 2021.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-23\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>23<\/sup><\/div><div class=\"table-cell\">\n<p><a href=\"https:\/\/www.aphis.usda.gov\/sites\/default\/files\/btscc_2017infosheet.pdf\" data-dig-id=\"LP-8179-c4d22df7\" data-dig-category=\"LP\" data-dig-action=\"link click\" data-dig-label=\"Department of Agriculture des \u00c9tats-Unis.\" class=\"rbc-link-format\">Department of Agriculture des \u00c9tats-Unis.<\/a> Determining U.S. Milk Quality Using Bulk-Tank Somatic Cell Counts, 2018.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-24\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>24<\/sup><\/div><div class=\"table-cell\">\n<p>DairyNZ et LIC. New Zealand Dairy Statistics 2023-24, 2024.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-25\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>25<\/sup><\/div><div class=\"table-cell\">\n<p>Foreign Agricultural Service du Department of Agriculture des \u00c9tats-Unis. New Zealand: Dairy and Products Annual, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-26\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>26<\/sup><\/div><div class=\"table-cell\">\n<p>Ministry of the Environment et la Nouvelle-Z\u00e9lande. New Zealand&rsquo;s Greenhouse Gas Inventory, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-27\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>27<\/sup><\/div><div class=\"table-cell\">\n<p>Organisation des Nations unies pour l\u2019alimentation et l\u2019agriculture (FAO). Dairy Market Review: Overview of global market developments in 2024, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-28\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>28<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO. Perspectives agricoles de l\u2019OCDE et de la FAO 2024-2033, 2024.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-29\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>29<\/sup><\/div><div class=\"table-cell\">\n<p>Economic Research Service du Department of Agriculture des \u00c9tats-Unis. USDA Agricultural Projections to 2034, 2025.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-30\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>30<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-31\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>31<\/sup><\/div><div class=\"table-cell\">\n<p>FAO.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-32\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>32<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-33\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>33<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-34\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>34<\/sup><\/div><div class=\"table-cell\">\n<p>Department of Agriculture des \u00c9tats-Unis.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-35\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>35<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-rbc-rbc-disclaimer-block\"><div class=\"table-row\" id=\"legal-36\"><div class=\"table-cell\"><span class=\"offscreen\">Legal Disclaimer<\/span><sup>36<\/sup><\/div><div class=\"table-cell\">\n<p>OCDE et FAO.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"<p>Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation<\/p>\n","protected":false},"author":300,"featured_media":8379,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"rbc_tl_category":[150],"rbc_tl_tag":[],"class_list":["post-8179","rbc_tl","type-rbc_tl","status-publish","has-post-thumbnail","hentry","rbc_tl_category-lespace-commercial"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9mystification de la gestion de l\u2019offre - RBC<\/title>\n<meta name=\"description\" content=\"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9mystification de la gestion de l\u2019offre\" \/>\n<meta property=\"og:description\" content=\"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-21T17:32:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Branded-1200x627-1.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"2500\" \/>\n\t<meta property=\"og:image:height\" content=\"1306\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"D\u00e9mystification de la gestion de l\u2019offre\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/\",\"name\":\"D\u00e9mystification de la gestion de l\u2019offre - RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/07\\\/SM-Report-Banners_Banner-wide.jpg?quality=80\",\"datePublished\":\"2025-07-21T17:24:14+00:00\",\"dateModified\":\"2025-07-21T17:32:55+00:00\",\"description\":\"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/07\\\/SM-Report-Banners_Banner-wide.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/07\\\/SM-Report-Banners_Banner-wide.jpg?quality=80\",\"width\":7250,\"height\":3500,\"caption\":\"D\u00e9mystification de la gestion de l\u2019offre\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/\",\"name\":\"RBC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9mystification de la gestion de l\u2019offre - RBC","description":"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9mystification de la gestion de l\u2019offre","og_description":"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation","og_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","og_site_name":"RBC","article_modified_time":"2025-07-21T17:32:55+00:00","og_image":[{"width":2500,"height":1306,"url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Branded-1200x627-1.jpg?quality=80","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"D\u00e9mystification de la gestion de l\u2019offre","twitter_misc":{"Est. reading time":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","name":"D\u00e9mystification de la gestion de l\u2019offre - RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80","datePublished":"2025-07-21T17:24:14+00:00","dateModified":"2025-07-21T17:32:55+00:00","description":"Les compromis du syst\u00e8me canadien de gestion de l\u2019offre dans un march\u00e9 alimentaire mondial en pleine mutation","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80","width":7250,"height":3500,"caption":"D\u00e9mystification de la gestion de l\u2019offre"},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/#website","url":"https:\/\/www.rbc.com\/fr\/","name":"RBC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"D\u00e9mystification de la gestion de l\u2019offre","url":"http:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/demystification-de-la-gestion-de-loffre\/"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80&w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80"},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"Shiplu Talukder"}],"creator":["Shiplu Talukder"],"publisher":{"@type":"Organization","name":"RBC","logo":""},"keywords":[],"dateCreated":"2025-07-21T17:24:14Z","datePublished":"2025-07-21T17:24:14Z","dateModified":"2025-07-21T17:32:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"D\\u00e9mystification de la gestion de l\\u2019offre\",\"url\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/lespace-commercial\\\/demystification-de-la-gestion-de-loffre\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/07\\\/SM-Report-Banners_Banner-wide.jpg?quality=80&w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/07\\\/SM-Report-Banners_Banner-wide.jpg?quality=80\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"Shiplu Talukder\"}],\"creator\":[\"Shiplu Talukder\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-07-21T17:24:14Z\",\"datePublished\":\"2025-07-21T17:24:14Z\",\"dateModified\":\"2025-07-21T17:32:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbc.com\/p.js"},"featured_img":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/07\/SM-Report-Banners_Banner-wide.jpg?quality=80&w=1024","coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbc.com\/fr\/author\/shiplutalukder\/","display_name":"Shiplu Talukder"},"relative_dates":{"created":"Publi\u00e9 10 mois il y a","modified":"Mis \u00e0 jour 10 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 21 juillet 2025","modified":"Mise \u00e0 jour le 21 juillet 2025"},"absolute_dates_time":{"created":"Publi\u00e9 le 21 juillet 2025 5:24  ","modified":"Mise \u00e0 jour le 21 juillet 2025 5:32  "},"featured_img_caption":"","tax_additional":{"rbc_tl_category":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/lespace-commercial\/\" class=\"advgb-post-tax-term\">L\u2019Espace commercial<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">L\u2019Espace commercial<\/span>"],"slug":"rbc_tl_category","name":"Categories"},"rbc_tl_tag":{"linked":[],"unlinked":[],"slug":"rbc_tl_tag","name":"Tags"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/8179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/types\/rbc_tl"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/users\/300"}],"version-history":[{"count":48,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/8179\/revisions"}],"predecessor-version":[{"id":8384,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/8179\/revisions\/8384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media\/8379"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media?parent=8179"}],"wp:term":[{"taxonomy":"rbc_tl_category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl_category?post=8179"},{"taxonomy":"rbc_tl_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl_tag?post=8179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}