{"id":4263,"date":"2023-03-22T17:45:00","date_gmt":"2023-03-22T17:45:00","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/leadership-avise\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/"},"modified":"2025-04-02T21:26:21","modified_gmt":"2025-04-02T21:26:21","slug":"perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation","status":"publish","type":"rbc_tl","link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","title":{"rendered":"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ?"},"content":{"rendered":"<p>Un d\u00e9fi important attend le gouvernement f\u00e9d\u00e9ral dans l\u2019\u00e9tablissement du budget qu\u2019il d\u00e9posera le 28\u00a0mars\u00a0: mettre sa politique climatique sur les rails tout en emp\u00eachant les investissements dans les actifs \u00e0 faibles \u00e9missions de carbone d\u2019affluer vers les \u00c9tats-Unis, sous l\u2019impulsion de la loi am\u00e9ricaine sur la r\u00e9duction de l\u2019inflation.<\/p>\n<p>La concurrence dans les secteurs li\u00e9s au climat sera au premier plan lorsque le pr\u00e9sident am\u00e9ricain Joe\u00a0Biden se rendra \u00e0 Ottawa cette semaine. Gr\u00e2ce \u00e0 la loi sur la r\u00e9duction de l\u2019inflation, les \u00c9tats-Unis sont parvenus \u00e0 restaurer leur cr\u00e9dibilit\u00e9 sur le plan climatique ainsi qu\u2019\u00e0 changer la donne. Les g\u00e9n\u00e9reuses subventions accord\u00e9es aux producteurs pour faire baisser les co\u00fbts de la d\u00e9carbonisation \u00e0 l\u2019\u00e9chelle nationale font du pays un investisseur de taille dans le secteur mondial de la r\u00e9duction des \u00e9missions. Le Canada devra redoubler d\u2019efforts pour faire concurrence \u00e0 son voisin du Sud dans ce domaine.<\/p>\n<p>Contrairement \u00e0 la croyance populaire, le Canada <em>poss\u00e8de<\/em> la capacit\u00e9 d\u2019\u00e9galer les investissements pour le climat pr\u00e9vus dans la loi sur la r\u00e9duction de l\u2019inflation. Il pourrait allouer environ 12\u00a0milliards de dollars par ann\u00e9e pour parvenir \u00e0 une r\u00e9duction de 10\u00a0% des \u00e9missions, comme le pr\u00e9voit la loi. La plupart des provinces pourraient \u00e9galement accro\u00eetre leurs actions. Pour ce faire, les deux ordres de gouvernement devront faire preuve de retenue \u00e0 l\u2019\u00e9gard des d\u00e9penses consacr\u00e9es \u00e0 d\u2019autres fins.<\/p>\n<p>La question va toutefois bien au-del\u00e0 de l\u2019argent\u00a0: il faut se demander comment le Canada peut \u00eatre strat\u00e9giquement concurrentiel. S\u2019il parvient \u00e0 \u00e9galer la port\u00e9e de la loi sur la r\u00e9duction de l\u2019inflation, il risque d\u2019\u00e9puiser son enveloppe de financement et de limiter les retomb\u00e9es sur l\u2019\u00e9conomie canadienne. Notons toutefois que les \u00e9missions du Canada diff\u00e8rent de celles des \u00c9tats-Unis. Des dispositions semblables \u00e0 celles pr\u00e9vues par cette loi ne permettront pas de diminuer les \u00e9missions aussi fortement qu\u2019au sud de la fronti\u00e8re.<\/p>\n<p>Le Canada a besoin d\u2019un nouveau plan judicieux pour maximiser sa capacit\u00e9 unique de favoriser la transition \u00e9nerg\u00e9tique \u00e0 l\u2019\u00e9chelle mondiale. L\u2019adoption de mesures dans certains secteurs strat\u00e9giques lui permettra de saisir la valeur ajout\u00e9e associ\u00e9e \u00e0 la technologie canadienne et de r\u00e9duire les \u00e9missions.<\/p>\n<h3 class=\"text-center\">Liste de contr\u00f4le climatique du Canada<\/h3>\n<ul class=\"task\">\n<li><img loading=\"lazy\" decoding=\"async\" class=\"task-img\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/IRA-Icon-1.png\" alt=\"\" width=\"128\" height=\"128\" \/>\n<p class=\"sp-text\">~ 18 milliards de dollars contre 35 milliards de dollars<\/p>\n<p>Investissements li\u00e9s \u00e0 la transition en 2022 par rapport aux besoins annuels pour l\u2019atteinte des objectifs de 2030<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"task-img\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/IRA-Icon-2.png\" alt=\"\" width=\"128\" height=\"128\" \/>\n<p class=\"sp-text\">12 milliards de dollars par ann\u00e9e<\/p>\n<p>Nouveaux investissements du gouvernement f\u00e9d\u00e9ral requis pour \u00e9galer ceux pr\u00e9vus dans la loi sur la r\u00e9duction de l\u2019inflation<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"task-img\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/IRA-Icon-3.png\" alt=\"\" width=\"128\" height=\"128\" \/>\n<p class=\"sp-text\">\u00c9lectricit\u00e9, p\u00e9trole, gaz, transport<\/p>\n<p>Secteurs o\u00f9 il faudra investir le plus pour atteindre les objectifs de 2030<\/li>\n<li><img loading=\"lazy\" decoding=\"async\" class=\"task-img\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/IRA-Icon-4.png\" alt=\"\" width=\"128\" height=\"128\" \/>\n<p class=\"sp-text\">19 $ contre 21 $ la tonne<\/p>\n<p>Investissements du Canada et des \u00c9tats-Unis dans la transition \u00e9nerg\u00e9tique en 2021<\/li>\n<\/ul>\n<h4><span style=\"color: #004da4\"><b>1. En consid\u00e9rant la loi sur la r\u00e9duction de l\u2019inflation comme un instrument de lutte contre les changements climatiques, et non comme un \u00e9l\u00e9ment de concurrence<\/b><\/span><\/h4>\n<p>La loi sur la r\u00e9duction de l\u2019inflation ne constitue pas un appel \u00e0 la concurrence en vue de la r\u00e9duction des \u00e9missions. La politique climatique de base du Canada est solide. Elle comporte une tarification du carbone, des r\u00e8glements et des investissements. Elle n\u2019est toutefois pas assez ambitieuse pour que le pays atteigne ses objectifs de 2030. Le Canada doit commencer \u00e0 planifier les mesures de r\u00e9duction qu\u2019il devra adopter imm\u00e9diatement apr\u00e8s cette ann\u00e9e-l\u00e0. Pour ce faire, il peut s\u2019inspirer de l\u2019approche pr\u00e9vue par la loi am\u00e9ricaine sur la r\u00e9duction de l\u2019inflation.<\/p>\n<p>Celle-ci pr\u00e9voit des investissements en amont \u00e9lev\u00e9s dans les \u00e9nergies propres, comme l\u2019hydrog\u00e8ne, l\u2019\u00e9lectricit\u00e9 et les carburants renouvelables, qui contribueront \u00e0 la d\u00e9carbonisation dans l\u2019ensemble des secteurs. L\u2019octroi de subventions favorise les investissements priv\u00e9s et r\u00e9duit les co\u00fbts pour les m\u00e9nages et les consommateurs industriels. Il favorisera donc l\u2019adoption de technologies ax\u00e9es sur les \u00e9nergies propres et la diminution des \u00e9missions aux \u00c9tats-Unis.<\/p>\n<p>La tarification du carbone au Canada stimulera aussi les investissements, mais l\u2019incertitude entourant la technologie, le manque d\u2019infrastructures et d\u2019autres obstacles pourraient se traduire par un d\u00e9ploiement technologique insuffisant pour r\u00e9duire les co\u00fbts et les \u00e9missions \u00e0 temps. La politique canadienne doit pr\u00e9voir des mesures semblables \u00e0 celles de la loi sur la r\u00e9duction de l\u2019inflation pour que le pays se dote d\u2019une approche syst\u00e9mique de d\u00e9carbonisation, car de tels investissements repr\u00e9sentent un pas dans la bonne direction. Le secteur de l\u2019\u00e9lectricit\u00e9 joue un r\u00f4le crucial : l\u2019\u00e9limination des obstacles \u00e0 la construction d\u2019infrastructures \u00e9lectriques pourrait r\u00e9duire les \u00e9missions du r\u00e9seau, faire baisser les co\u00fbts de transition et maintenir les co\u00fbts de l\u2019\u00e9nergie \u00e0 un niveau abordable.<\/p>\n<p>Toutes ces mesures faciliteraient la d\u00e9carbonisation. De plus, elles ouvriraient la voie \u00e0 de nouveaux secteurs ne g\u00e9n\u00e9rant pas d\u2019\u00e9missions et \u00e0 des investissements suppl\u00e9mentaires dans des entreprises soucieuses des \u00e9missions, ce qui favoriserait le d\u00e9veloppement de la propri\u00e9t\u00e9 intellectuelle, les exportations et la saisie de nouvelles occasions \u00e9conomiques.<\/p>\n<h4><span style=\"color: #004da4\"><b>2. En misant sur les avantages du Canada<\/b><\/span><\/h4>\n<p>L\u2019\u00e9laboration d\u2019une strat\u00e9gie est primordiale. Une politique industrielle expansionniste visant \u00e0 se livrer \u00e0 une guerre de subventions dans trop de domaines risque d\u2019aboutir \u00e0 des r\u00e9sultats m\u00e9diocres et de ralentir le rythme de la d\u00e9carbonisation mondiale. Le Canada n\u2019a pas besoin de s\u2019engager dans l\u2019ensemble des secteurs. Il devrait plut\u00f4t privil\u00e9gier les activit\u00e9s \u00e9conomiques \u00e0 forte valeur ajout\u00e9e pour lesquelles il b\u00e9n\u00e9ficie d\u2019avantages sectoriels \u00e0 l\u2019\u00e9chelle mondiale.<\/p>\n<p>La loi sur la r\u00e9duction de l\u2019inflation a d\u2019ailleurs renforc\u00e9 les avantages du Canada en lui donnant acc\u00e8s \u00e0 des march\u00e9s am\u00e9ricains en pleine croissance. Les concessions obtenues de haute lutte sur la cha\u00eene d\u2019approvisionnement nord-am\u00e9ricaine de v\u00e9hicules \u00e9lectriques en sont un exemple. Cependant, dans certains cas, la saisie de valeur a \u00e9t\u00e9 plus difficile, car les g\u00e9n\u00e9reuses mesures incitatives am\u00e9ricaines orientent les investissements vers les \u00c9tats-Unis.<\/p>\n<p>La capture du carbone en est un bon exemple : les entreprises en d\u00e9marrage canadiennes b\u00e9n\u00e9ficient d\u2019\u00e9normes avantages li\u00e9s \u00e0 leur exp\u00e9rience, et le Canada est dot\u00e9 d\u2019un vaste substrat g\u00e9ologique pour la s\u00e9questration du carbone.<\/p>\n<p>En facilitant le d\u00e9ploiement des technologies de capture du carbone \u00e0 l\u2019\u00e9chelle du pays, le Canada peut r\u00e9duire ses \u00e9missions, poursuivre le d\u00e9veloppement de ces technologies et cr\u00e9er une industrie nationale qui exporte l\u2019\u00e9quipement et son savoir-faire en capture du carbone dans le monde entier.<\/p>\n<p>Ces avantages sont certainement \u00e0 notre port\u00e9e. L\u2019industrie lourde n\u2019est pas \u00e9tablie ici par hasard : le Canada repr\u00e9sente un endroit attrayant pour produire et vendre de l\u2019acier, du ciment et des produits chimiques. Lorsque la d\u00e9carbonisation de ces secteurs sera r\u00e9alis\u00e9e, ils b\u00e9n\u00e9ficieront de solides perspectives \u00e9conomiques \u00e0 faible \u00e9mission de carbone et la r\u00e9duction de leurs \u00e9missions sera consid\u00e9r\u00e9e comme d\u00e9finitive.<\/p>\n<p>Les autres secteurs dans lesquels le Canada poss\u00e8de un avantage li\u00e9 \u00e0 l\u2019exp\u00e9rience comprennent la recherche et l\u2019innovation dans les technologies propres, la production \u00e0 forte consommation d\u2019\u00e9lectricit\u00e9 (puisque le r\u00e9seau propre du Canada offre des avantages li\u00e9s aux \u00e9missions de p\u00e9rim\u00e8tre 2), les cha\u00eenes d\u2019approvisionnement de min\u00e9raux essentiels et les carburants renouvelables.<\/p>\n<h4><span style=\"color: #004da4\"><b>3.\tEn mettant en place des structures aptes \u00e0 maintenir la valeur ajout\u00e9e <\/b><\/span><\/h4>\n<p>Le Canada gagnerait \u00e0 aller au-del\u00e0 des domaines de la cha\u00eene de valeur o\u00f9 il dispose d\u2019avantages li\u00e9s \u00e0 l\u2019exp\u00e9rience. Il est essentiel pour le pays de faire appel \u00e0 de nouveaux secteurs \u00e0 forte valeur ajout\u00e9e pour se pr\u00e9munir contre la baisse des revenus r\u00e9els d\u00e9coulant de la transition hors des secteurs traditionnels.<\/p>\n<p>Cela dit, la concurrence sera f\u00e9roce dans les domaines o\u00f9 les avantages du Canada sont marginaux. Il sera n\u00e9cessaire qu\u2019il r\u00e9agisse plus vigoureusement, notamment vis-\u00e0-vis de la cha\u00eene d\u2019approvisionnement des batteries, qui conna\u00eet un essor important. Les usines de ce secteur b\u00e9n\u00e9ficient de nombreuses subventions. Selon certaines estimations, les cr\u00e9dits d\u2019imp\u00f4t am\u00e9ricains pour une seule m\u00e9ga-usine pourraient s\u2019\u00e9lever \u00e0 deux milliards de dollars par ann\u00e9e.<\/p>\n<p>Le Canada renoncera \u00e0 toute mesure de stimulation \u00e9conomique s\u2019il ne peut allouer ces investissements aux secteurs o\u00f9 il b\u00e9n\u00e9ficie d\u2019avantages, puisque les effets de r\u00e9seau faciliteront la saisie de la valeur de la cha\u00eene en amont ou en aval. La formation d\u2019une main-d\u2019\u0153uvre qualifi\u00e9e ou la recherche et le d\u00e9veloppement inciteront le pays \u00e0 exploiter ces occasions.<\/p>\n<p>Les cha\u00eenes d\u2019approvisionnement de min\u00e9raux essentiels constituent un exemple convaincant : le Canada poss\u00e8de de solides avantages dans le secteur minier et un fort potentiel de raffinage gr\u00e2ce \u00e0 son r\u00e9seau propre. La fabrication cellulaire et l\u2019assemblage de batteries font partie des principaux secteurs \u00e0 valeur ajout\u00e9e susceptibles de stimuler la demande de min\u00e9raux canadiens et d\u2019assemblage en aval. Compte tenu de la concurrence mondiale, le Canada doit d\u2019abord am\u00e9liorer sa position. Les investissements dans la qualification de la main-d\u2019\u0153uvre et l\u2019infrastructure pour des batteries innovantes, combin\u00e9s \u00e0 l\u2019acc\u00e8s aux march\u00e9s am\u00e9ricains font du Canada un choix logique pour de futurs \u00e9tablissements, et ce, sans mesures budg\u00e9taires importantes.<\/p>\n<h4><span style=\"color: #004da4\"><b>4.\tEn recourant \u00e0 de vastes instruments transparents dans des secteurs cibl\u00e9s<\/b><\/span><\/h4>\n<p>La rapidit\u00e9 et la transparence du r\u00e9gime fiscal concernant les d\u00e9cisions d\u2019investissement et de pr\u00eat font partie des principaux atouts de la loi am\u00e9ricaine sur la r\u00e9duction de l\u2019inflation. Les cr\u00e9dits d\u2019imp\u00f4t assur\u00e9s et transparents aux \u00c9tats-Unis contrastent avec l\u2019incertitude et la volatilit\u00e9 li\u00e9es aux prix des cr\u00e9dits de carbone au Canada, et avec l\u2019opacit\u00e9 de ses programmes de subventions. Il est plus facile d\u2019obtenir des pr\u00eats avec des cr\u00e9dits d\u2019imp\u00f4t, qui favorisent la mobilisation de fonds priv\u00e9s pour la lutte contre les changements climatiques.<\/p>\n<p>Le gouvernement devrait \u00e9viter d\u2019avoir recours \u00e0 des instruments sur mesure dont l\u2019ex\u00e9cution est lente, comme le Fonds strat\u00e9gique pour l\u2019innovation. Il gagnerait plut\u00f4t \u00e0 mettre en place des mesures fiscales pr\u00e9cises pour favoriser le d\u00e9veloppement de l\u2019ensemble des secteurs cl\u00e9s. La population canadienne aurait ainsi la possibilit\u00e9 de savoir exactement ce qu\u2019elle finance et de s\u2019unir autour d\u2019une nouvelle strat\u00e9gie \u00e9conomique.<\/p>\n<p><em><b>Cynthia Leach<\/b> contribue \u00e0 fa\u00e7onner la description et le programme de recherche li\u00e9s \u00e0 l\u2019analyse \u00e9conomique et strat\u00e9gique prospective de l\u2019\u00e9quipe Services \u00e9conomiques et leadership avis\u00e9 RBC. Elle s\u2019est jointe \u00e0 l\u2019\u00e9quipe en 2020. Auparavant, Mme Leach \u00e9tait cadre au minist\u00e8re des Finances Canada o\u00f9 elle dirigeait tout r\u00e9cemment une \u00e9quipe responsable de la politique de financement du logement.<\/em><\/p>\n<p><em><b>Colin Guldimann<\/b> est entr\u00e9 au service de RBC en 2019, \u00e0 titre d\u2019\u00e9conomiste. Il est titulaire d\u2019un baccalaur\u00e9at en \u00e9conomie de l\u2019Universit\u00e9 d\u2019Ottawa et d\u2019une ma\u00eetrise \u00e8s arts en \u00e9conomie de l\u2019Universit\u00e9 de Colombie-Britannique. Avant de se joindre \u00e0 RBC, M. Guldimann analysait les politiques li\u00e9es aux pr\u00eats hypoth\u00e9caires, au logement et \u00e0 l\u2019\u00e9conomie au minist\u00e8re des Finances du Canada.<\/em><\/p>\n<style class=\"advgb-styles-renderer\">.mar20bot{margin-bottom:20px;}.sp_title{font-family: RBCDisplay!important;}hr{float: left; width: 100%;}h2 {color: #004da4;}strong{font-weight: 700!important;}.mar30top{margin-top:30px!important;}.mar30bot{margin-bottom:30px!important;}.fl-l{float: left;}.task{padding: 0px !important;margin: 0 0 40px 0!important;width: 100%;display: table;} .task li{text-align:center; border: 1px solid black; list-style: none; width: 380px;float: left; padding:60px 50px;display:table;height:440px!important}.task li:first-child{margin:0 10px 0 0;}.task li:nth-child(2){height:354px;}.task li:nth-child(3){margin-right:10px;}.sp-text{font-size: 24px;font-weight: 700;color:#006ac3!important;}.task li:last-child{padding: 73px 50px;}.task-img{width: 110px!important; height: auto; margin: 0 auto;}@media screen and (max-width: 640px) {.task li {width: 100%; padding: 20px 10px;height: 250px!important;}.sp-text{font-size: 20px;}.task-img {width: 80px!important;}.task li:nth-child(2){margin:0px;border-bottom:none;border-top:none;}.task li:nth-child(3){margin:0!important;border-bottom:none;}.task li:last-child{padding: 20px 10px;}}@media screen and (max-width: 768px){.task li {width: 100%;margin: 0;}}<\/style>\n","protected":false},"excerpt":{"rendered":"<p>Un d\u00e9fi important attend le gouvernement f\u00e9d\u00e9ral dans l\u2019\u00e9tablissement du budget qu\u2019il d\u00e9posera le 28 mars :<\/p>\n","protected":false},"author":300,"featured_media":4268,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"rbc_tl_category":[156,135,92,91],"rbc_tl_tag":[136],"class_list":["post-4263","rbc_tl","type-rbc_tl","status-publish","has-post-thumbnail","hentry","rbc_tl_category-commentaire-dexpert","rbc_tl_category-institut-action-climatique","rbc_tl_category-perspectives-vedettes","rbc_tl_category-recherche-economique","rbc_tl_tag-climat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ? - RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ?\" \/>\n<meta property=\"og:description\" content=\"Un d\u00e9fi important attend le gouvernement f\u00e9d\u00e9ral dans l\u2019\u00e9tablissement du budget qu\u2019il d\u00e9posera le 28 mars :\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-02T21:26:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/\",\"name\":\"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ? - RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80\",\"datePublished\":\"2023-03-22T17:45:00+00:00\",\"dateModified\":\"2025-04-02T21:26:21+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/institut-action-climatique\\\/commentaire-dexpert\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80\",\"width\":2560,\"height\":1236},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/\",\"name\":\"RBC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ? - RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","og_locale":"fr_FR","og_type":"article","og_title":"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ?","og_description":"Un d\u00e9fi important attend le gouvernement f\u00e9d\u00e9ral dans l\u2019\u00e9tablissement du budget qu\u2019il d\u00e9posera le 28 mars :","og_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","og_site_name":"RBC","article_modified_time":"2025-04-02T21:26:21+00:00","og_image":[{"width":2560,"height":1236,"url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","name":"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ? - RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80","datePublished":"2023-03-22T17:45:00+00:00","dateModified":"2025-04-02T21:26:21+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80","width":2560,"height":1236},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/#website","url":"https:\/\/www.rbc.com\/fr\/","name":"RBC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbc.com\/fr\/leadership-avise\/recherche-economique\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \u00e9conomique apr\u00e8s l\u2019entr\u00e9e en vigueur de la loi sur la r\u00e9duction de l\u2019inflation ?","url":"http:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\/"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80&w=150&h=150&crop=1","image":{"@type":"ImageObject","url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80"},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"Shiplu Talukder"}],"creator":["Shiplu Talukder"],"publisher":{"@type":"Organization","name":"RBC","logo":""},"keywords":[],"dateCreated":"2023-03-22T17:45:00Z","datePublished":"2023-03-22T17:45:00Z","dateModified":"2025-04-02T21:26:21Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Perspectives et politique : Comment le Canada peut-il gagner sur le plan \\u00e9conomique apr\\u00e8s l\\u2019entr\\u00e9e en vigueur de la loi sur la r\\u00e9duction de l\\u2019inflation ?\",\"url\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/recherche-economique\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/recherche-economique\\\/perspectives-et-politique-comment-le-canada-peut-il-gagner-sur-le-plan-economique-apres-lentree-en-vigueur-de-la-loi-sur-la-reduction-de-linflation\\\/\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80&w=150&h=150&crop=1\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/03\\\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"Shiplu Talukder\"}],\"creator\":[\"Shiplu Talukder\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2023-03-22T17:45:00Z\",\"datePublished\":\"2023-03-22T17:45:00Z\",\"dateModified\":\"2025-04-02T21:26:21Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbc.com\/p.js"},"featured_img":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/03\/DL-Blog-Image-Template-IRA_Banner-wide-scaled-1.jpg?quality=80&w=1024","coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbc.com\/fr\/author\/shiplutalukder\/","display_name":"Shiplu Talukder"},"relative_dates":{"created":"Publi\u00e9 3 ans il y a","modified":"Mis \u00e0 jour 1 an il y a"},"absolute_dates":{"created":"Publi\u00e9 le 22 mars 2023","modified":"Mise \u00e0 jour le 2 avril 2025"},"absolute_dates_time":{"created":"Publi\u00e9 le 22 mars 2023 5:45  ","modified":"Mise \u00e0 jour le 2 avril 2025 9:26  "},"featured_img_caption":"","tax_additional":{"rbc_tl_category":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/commentaire-dexpert\/\" class=\"advgb-post-tax-term\">Commentaire d&#039;expert<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/institut-action-climatique\/\" class=\"advgb-post-tax-term\">Institut Action Climatique<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/perspectives-vedettes\/\" class=\"advgb-post-tax-term\">Perspectives vedettes<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/\" class=\"advgb-post-tax-term\">Recherche \u00e9conomique<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Commentaire d&#039;expert<\/span>","<span class=\"advgb-post-tax-term\">Institut Action Climatique<\/span>","<span class=\"advgb-post-tax-term\">Perspectives vedettes<\/span>","<span class=\"advgb-post-tax-term\">Recherche \u00e9conomique<\/span>"],"slug":"rbc_tl_category","name":"Categories"},"rbc_tl_tag":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/topics\/climat\/\" class=\"advgb-post-tax-term\">Climat<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Climat<\/span>"],"slug":"rbc_tl_tag","name":"Tags"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/4263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/types\/rbc_tl"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/users\/300"}],"version-history":[{"count":1,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/4263\/revisions"}],"predecessor-version":[{"id":5808,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl\/4263\/revisions\/5808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media\/4268"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media?parent=4263"}],"wp:term":[{"taxonomy":"rbc_tl_category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl_category?post=4263"},{"taxonomy":"rbc_tl_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_tl_tag?post=4263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}