{"id":2489,"date":"2007-09-01T00:00:00","date_gmt":"2007-09-01T00:00:00","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/"},"modified":"2022-10-17T18:41:14","modified_gmt":"2022-10-17T18:41:14","slug":"septembre-2007-a-la-decouverte-de-notre-patrimoine","status":"publish","type":"rbc_letter","link":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","title":{"rendered":"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine"},"content":{"rendered":"<div id=\"layout-column-main\">\n<p>\u00c0 peine une douzaine de monuments dans le monde ont acquis une valeur symbolique assez forte pour sugg\u00e9rer aussit\u00f4t l&rsquo;image d&rsquo;une ville ou d&rsquo;un pays, et le secteur touristique les utilise abondamment pour \u00e9voquer l&rsquo;attrait de lointaines contr\u00e9es : le Taj Mahal pour l&rsquo;Inde, la tour Eiffel pour Paris, le Parlement pour Londres. L&rsquo;un des plus r\u00e9put\u00e9s est le Parth\u00e9non. Ce temple d&rsquo;Ath\u00e9na, la d\u00e9esse vierge, domine du sommet de l&rsquo;Acropole la ville qui porte son nom. M\u00eame \u00e0 moiti\u00e9 en ruines, sa repr\u00e9sentation \u00e9voque non seulement Ath\u00e8nes et la Gr\u00e8ce, mais tout l&rsquo;univers intellectuel et artistique de l&rsquo;antiquit\u00e9 classique.<\/p>\n<p>Son architecture est si parfaite qu&rsquo;il serait presque sacril\u00e8ge de penser que le Parth\u00e9non doit en partie son renom \u00e0 la place pr\u00e9\u00e9minente qu&rsquo;il occupe dans une grande ville. Il le doit plus encore \u00e0 la volont\u00e9 de ses cr\u00e9ateurs de ne pas m\u00e9nager la d\u00e9pense. \u00c0 l&rsquo;exception des poutres de son toit et des crampons de fer qui en joignent les moellons, ce temple a \u00e9t\u00e9 enti\u00e8rement construit en marbre poli, quasi-indestructible (jusqu&rsquo;\u00e0 la venue de la pollution industrielle), cisel\u00e9 par des mains amoureuses pour parfaire les alignements et les courbes imperceptibles auxquels ce monument, subtil entre tous, doit sa vitalit\u00e9. L&rsquo;ornementation du Parth\u00e9non comprend aussi des sculptures d&rsquo;une abondance inusit\u00e9e, toutes d&rsquo;une qualit\u00e9 insurpass\u00e9e. Son co\u00fbt, en grande partie assum\u00e9 par les alli\u00e9s assujettis d&rsquo;Ath\u00e8nes, fut colossal. La ferveur religieuse et la fiert\u00e9 civique se sont combin\u00e9es pour \u00e9riger un monument triomphal \u00e0 la richesse et la puissance de la d\u00e9mocratie ath\u00e9nienne.<\/p>\n<p>La c\u00f4te orientale du Canada et la Nouvelle-Angleterre sont parsem\u00e9es de maisons traditionnelles dites \u00ab\u00a0en bo\u00eete \u00e0 sel\u00a0\u00bb, comportant deux \u00e9tages en avant mais un seul \u00e0 l&rsquo;arri\u00e8re, si bien que, vue de c\u00f4t\u00e9, la pente arri\u00e8re du toit sur pignon est nettement plus longue que celle de la fa\u00e7ade. Souvent tr\u00e8s attrayante dans son \u00e9l\u00e9gance fonctionnelle, la \u00ab\u00a0bo\u00eete \u00e0 sel\u00a0\u00bb v\u00eatue de bois, \u00e0 vocation priv\u00e9e et profane plut\u00f4t que publique et sacr\u00e9e, d\u00e9nu\u00e9e d&rsquo;ornements et sans la moindre pr\u00e9tention, ne pourrait \u00eatre plus diff\u00e9rente du Parth\u00e9non.<\/p>\n<p>N\u00e9anmoins, tous deux ont en commun un point important : ils ont \u00e9t\u00e9 d\u00e9sign\u00e9s par des autorit\u00e9s comp\u00e9tentes comme des \u00e9l\u00e9ments du patrimoine architectural et, par cons\u00e9quent, comme dignes d&rsquo;\u00eatre pr\u00e9serv\u00e9s. On en compte bien d&rsquo;autres. Apr\u00e8s des d\u00e9buts h\u00e9sitants au dix-neuvi\u00e8me si\u00e8cle, le mouvement en faveur de la protection des monuments dits \u00ab\u00a0historiques\u00a0\u00bb a pris son \u00e9lan au vingti\u00e8me, souvent \u00e0 la faveur de la destruction d&rsquo;un \u00e9difice important, tel que la Pennsylvania Station \u00e0 New York, qui a secou\u00e9 l&rsquo;opinion publique. Depuis plusieurs d\u00e9cennies maintenant, la protection du patrimoine national fait partie des objectifs politiques officiels de pratiquement tous les pays, m\u00eame si dans les faits, elle est pratiqu\u00e9e avec une efficacit\u00e9 tr\u00e8s al\u00e9atoire. Elle joue un r\u00f4le important dans l&rsquo;affectation des espaces urbains et naturels en r\u00e9ponse aux besoins des hommes. Des minist\u00e8res, des organismes officiels semi-autonomes et des associations b\u00e9n\u00e9voles \u00e9dictent des r\u00e8gles, proposent des m\u00e9thodes, publient des guides, font des suggestions pratiques, et surtout, dressent des listes de monuments, de sites et de paysages dont l&rsquo;int\u00e9grit\u00e9 doit \u00eatre respect\u00e9e en toute circonstance ou, tout au moins, qui ne peuvent \u00eatre d\u00e9molis ou modifi\u00e9s qu&rsquo;avec la sanction d&rsquo;une autorit\u00e9. Le nombre de sites ainsi r\u00e9pertori\u00e9s est stup\u00e9fiant. Aux \u00c9tats-Unis seulement, le registre national des sites historiques, qui n&rsquo;existe que depuis 1966, comprend d\u00e9j\u00e0 plus de 87 000 sites et plusieurs s&rsquo;ajoutent \u00e0 la liste r\u00e9guli\u00e8rement.<\/p>\n<p>Comme partout ailleurs, cette croissance r\u00e9sulte en grande partie de l&rsquo;\u00e9largissement du concept de \u00ab\u00a0patrimoine\u00a0\u00bb lui-m\u00eame. Autrefois limit\u00e9 \u00e0 des \u00e9difices publics importants, g\u00e9n\u00e9ralement vieux de plusieurs si\u00e8cles, le patrimoine comprend aujourd&rsquo;hui des sites arch\u00e9ologiques, des paysages, des b\u00e2timents industriels\u0085 tout ce qui est repr\u00e9sentatif d&rsquo;un mode de vie distinctif ou d&rsquo;une \u00e9poque particuli\u00e8re, m\u00eame inscrite dans la m\u00e9moire de t\u00e9moins encore vivants. Le patrimoine a aussi \u00e9t\u00e9 \u00e9tendu \u00e0 des r\u00e9gions sauvages qui rappellent ce que l&rsquo;homme a \u00e9pargn\u00e9 plut\u00f4t que ce qu&rsquo;il a cr\u00e9\u00e9 &#8211; et \u00e0 des activit\u00e9s culturelles consid\u00e9r\u00e9es comme suffisamment \u00e9vocatrices d&rsquo;une tradition. Cette \u00e9lasticit\u00e9 explique que les bo\u00eetes \u00e0 sel aient rejoint, parmi les sites du patrimoine de l&rsquo;humanit\u00e9, le Parth\u00e9non, ainsi que les maisons troglodytes du plateau du Loess en Chine septentrionale, les rocs sculpt\u00e9s de l&rsquo;\u00e2ge du fer en Su\u00e8de, les statues monolithiques de l&rsquo;\u00eele de P\u00e2ques, les palais des tzars en Russie et la laverie \u00e0 la vapeur de Juneau, en Alaska.<\/p>\n<p>La lecture de ces listes est \u00e0 la fois instructive et d\u00e9concertante, en ce qu&rsquo;elle souligne l&rsquo;\u00e9tendue de notre ignorance. Rares sont, en effet, les lecteurs ayant entendu parler de tous les 821 sites qui, selon l&rsquo;UNESCO, font partie du patrimoine de l&rsquo;humanit\u00e9. Cette superliste donne une bonne id\u00e9e de l&rsquo;ampleur que le concept du patrimoine a acquise de nos jours. In\u00e9vitablement, les choix de l&rsquo;UNESCO sont in\u00e9gaux ; ils ont \u00e9t\u00e9 influenc\u00e9s par l&rsquo;importance plus ou moins grande que chaque pays membre attache \u00e0 son h\u00e9ritage et, bien s\u00fbr, par les conjonctures politiques les plus diverses. Ainsi, l&rsquo;Irak, lieu de la plus ancienne civilisation du monde, ne compte que trois sites dans la liste. Deux y figurent depuis 2003 seulement, et ceux de Babylone, de Ninive et d&rsquo;Ur en sont absents, en d\u00e9pit de la place exceptionnelle que ces villes antiques ont occup\u00e9e dans l&rsquo;histoire de l&rsquo;humanit\u00e9. Ajoutons, \u00e0 la d\u00e9charge de l&rsquo;UNESCO, que cet organisme fait des efforts honorables pour dresser une nomenclature compl\u00e8te tout en appliquant des normes rigoureuses, et ces lacunes seront combl\u00e9es t\u00f4t ou tard.<\/p>\n<p>Il est plus impressionnant encore, peut-\u00eatre, qu&rsquo;une liste soit le soutien universel dont b\u00e9n\u00e9ficie l&rsquo;id\u00e9e de la pr\u00e9servation du patrimoine. Ce concept est si profond\u00e9ment inscrit dans les esprits que personne ne songerait \u00e0 en remettre la valeur en question. Comme pour la paix et la d\u00e9mocratie, personne ne conteste le principe qu&rsquo;il est souhaitable de pr\u00e9server le patrimoine de l&rsquo;humanit\u00e9, m\u00eame s&rsquo;il suscite des objections dans certains cas. Pourtant, ce principe est radicalement nouveau et son acceptation est l&rsquo;un des ph\u00e9nom\u00e8nes les plus remarquables du monde d&rsquo;aujourd&rsquo;hui. Pendant des si\u00e8cles, l&rsquo;id\u00e9e de pr\u00e9server des b\u00e2timents pour la seule raison qu&rsquo;ils t\u00e9moignent d&rsquo;un pass\u00e9 important aurait sembl\u00e9e \u00e9trange. La plupart ont \u00e9t\u00e9 construits \u00e0 des fins utilitaires, ou pour impressionner parfois certes, mais, r\u00e9cemment encore, personne ne les percevait comme des t\u00e9moins du pass\u00e9. Certains doivent \u00e0 leur seule solidit\u00e9 d&rsquo;avoir r\u00e9sist\u00e9 aux assauts du temps. Beaucoup de b\u00e2timents de pierre ou de brique importants ont travers\u00e9 les si\u00e8cles parce qu&rsquo;il \u00e9tait plus facile de les affecter \u00e0 de nouveaux usages que de les remplacer enti\u00e8rement. Quelques-uns ont perdur\u00e9 en raison du caract\u00e8re sacr\u00e9 que leur conf\u00e9raient leur fonction ou leurs liens historiques. En revanche, un conqu\u00e9rant d\u00e9termin\u00e9 n&rsquo;h\u00e9sitait pas \u00e0 d\u00e9clarer que la d\u00e9it\u00e9 serait plus heureuse ou le saint mieux honor\u00e9 dans un sanctuaire ou un tombeau plus grand et beau.<\/p>\n<p>D&rsquo;autres dangers guettaient aussi les structures, m\u00eame les plus solides. Souvent, ces dangers n&rsquo;\u00e9manaient pas d&rsquo;un d\u00e9sir de r\u00e9am\u00e9nager les lieux, mais des \u00e9conomies que permettait le recyclage. Avant l&rsquo;av\u00e8nement du chemin de fer, le transport de la pierre d&rsquo;une carri\u00e8re \u00e0 pied d&rsquo;\u009cuvre pouvait absorber le tiers ou m\u00eame la moiti\u00e9 du co\u00fbt total d&rsquo;un b\u00e2timent. C&rsquo;est pourquoi bien des temples grecs et des ch\u00e2teaux forts m\u00e9di\u00e9vaux sont devenus des bergeries ou des murs de cl\u00f4ture des champs. Si le Colis\u00e9e de Rome est aujourd&rsquo;hui partiellement en ruines, ce n&rsquo;est pas \u00e0 cause des d\u00e9pr\u00e9dations des Wisigoths ou des Vandales, mais parce que les papes l&rsquo;ont successivement utilis\u00e9 comme une carri\u00e8re d&rsquo;acc\u00e8s facile. Les principales raisons motivant de nouvelles constructions \u00e9taient toutefois les dommages caus\u00e9s par des incendies, des guerres, des cataclysmes ou, tout simplement, le passage du temps. Ces changements n&rsquo;\u00e9taient pas assez rapides pour donner l&rsquo;impression de la disparition du pass\u00e9, d&rsquo;autant plus que les nouvelles constructions ressemblaient souvent beaucoup aux anciennes.<\/p>\n<p>Un changement aussi radical dans les attitudes soul\u00e8ve des questions, surtout \u00e0 l&rsquo;\u00e9gard de l&rsquo;id\u00e9e paradoxale de pr\u00e9server le pass\u00e9 lui-m\u00eame. Le patrimoine, qu&rsquo;est-ce que c&rsquo;est ? Comment ce concept \u00e9volue-t-il ? En pratique, que pouvons-nous ou devons-nous faire pour le pr\u00e9server ? Dans quelle mesure convient-il de le faire ? Ce concept est-il menac\u00e9 par son propre succ\u00e8s ? Et dans quelle mesure est-il possible de concilier la pr\u00e9servation du pass\u00e9 et le droit d&rsquo;acc\u00e8s public ? Qui devrait assumer le co\u00fbt souvent important de la pr\u00e9servation, surtout les co\u00fbts d&rsquo;opportunit\u00e9 ? Enfin, qu&rsquo;est-ce qui a d\u00e9clench\u00e9 cette r\u00e9volution dans notre perception du pass\u00e9 ?<\/p>\n<p>\u00c0 la base, la d\u00e9finition du patrimoine est assez simple. \u00c0 l&rsquo;exception de la nature \u00e0 l&rsquo;\u00e9tat sauvage, notre patrimoine est tout ce qui survit des \u009cuvres des g\u00e9n\u00e9rations pass\u00e9es : champs et villes, routes et maisons, temples et palais, ainsi que l&rsquo;h\u00e9ritage culturel transmis par l&rsquo;enseignement et par l&rsquo;exemple. Cela dit, notre patrimoine est \u00e0 la fois plus et moins que tout ce que le pass\u00e9 nous a laiss\u00e9. C&rsquo;est moins, car il est \u00e9vident que, m\u00eame si on le dit rarement explicitement, nous ne pouvons ni ne voulons tout garder. Non seulement cela serait impossible, mais il faut aussi \u00e0 chaque g\u00e9n\u00e9ration de la place pour son propre apport \u00e0 l&rsquo;histoire. C&rsquo;est aussi plus, parce que nous sommes d&rsquo;accord pour ne vouloir conserver que ce qui a une valeur ou une signification particuli\u00e8re. D\u00e9finir cette valeur ou cette signification est la premi\u00e8re \u00e9tape incontournable de tout programme de conservation coh\u00e9rent.<\/p>\n<p>Trois crit\u00e8res importants ont \u00e9t\u00e9 invoqu\u00e9s pour r\u00e9pondre \u00e0 ces questions. Loin d&rsquo;\u00eatre mutuellement exclusifs, ces crit\u00e8res peuvent au contraire se renforcer. Il s&rsquo;agit de la valeur esth\u00e9tique, de la valeur documentaire et de la valeur identitaire. Un immeuble, un quartier urbain ou un paysage m\u00e9rite d&rsquo;\u00eatre pr\u00e9serv\u00e9 s&rsquo;il est beau ou pittoresque ; s&rsquo;il t\u00e9moigne d&rsquo;une \u00e9poque ou d&rsquo;\u00e9v\u00e9nements historiques importants, y compris par son style architectural ; ou s&rsquo;il est repr\u00e9sentatif du concept qu&rsquo;une soci\u00e9t\u00e9 a de son identit\u00e9 ou de son caract\u00e8re national. Tous ces crit\u00e8res sont plus ou moins subjectifs. Le plus objectif est sans doute la valeur documentaire, car les historiens s&rsquo;entendent g\u00e9n\u00e9ralement pour attribuer l&rsquo;architecture d&rsquo;un b\u00e2timent \u00e0 une p\u00e9riode ou \u00e0 un style. La valeur esth\u00e9tique, par contre, est loin de faire toujours l&rsquo;unanimit\u00e9.<\/p>\n<p>Il est int\u00e9ressant d&rsquo;observer que, dans les mandats ou \u00e9nonc\u00e9s de missions des organismes de conservation, la valeur esth\u00e9tique, que beaucoup d&rsquo;initiateurs du mouvement pour la protection du patrimoine auraient jug\u00e9 primordiale, n&rsquo;est g\u00e9n\u00e9ralement qu&rsquo;un \u00e9l\u00e9ment d&rsquo;une liste, quand elle est mentionn\u00e9e. Cela est sage, car la plupart des gens s&rsquo;entendent pour dire qu&rsquo;un \u00e9difice est beau ou qu&rsquo;un autre ne l&rsquo;est pas, mais le classement des monuments selon ce crit\u00e8re les assujettirait \u00e0 la fois aux go\u00fbts individuels &#8211; qu&rsquo;on pense aux \u00e9valuations souvent contradictoires de l&rsquo;esth\u00e9tique des tours de verre d&rsquo;aujourd&rsquo;hui &#8211; et aux brusques revirements de la mode. Il y a cent cinquante ans, l&rsquo;historien de l&rsquo;art John Ruskin, qui a exerc\u00e9 une influence \u00e9norme \u00e0 son \u00e9poque, affirmait que l&rsquo;art gothique anglais primitif \u00e9tait non seulement esth\u00e9tiquement, mais aussi moralement, sup\u00e9rieur \u00e0 ses successeurs \u00ab\u00a0surcharg\u00e9s et perpendiculaires\u00a0\u00bb. Les \u00e9glises de style gothique anglais primitif qui ont surgi dans tout le monde anglophone ont par la suite \u00e9t\u00e9 jug\u00e9es aussi d\u00e9su\u00e8tes que toute la gamme des autres styles dits \u00ab\u00a0victoriens\u00a0\u00bb. Dans les ann\u00e9es 1920, les arbitres du bon go\u00fbt ont d\u00e9cr\u00e9t\u00e9 que les constructions victoriennes manquaient d&rsquo;originalit\u00e9 ou, pire encore, qu&rsquo;elles \u00e9taient hideuses. L&rsquo;engouement s&rsquo;est alors r\u00e9orient\u00e9 vers la puret\u00e9 classique du style g\u00e9orgien ou le minimalisme audacieux du modern style.<\/p>\n<p>Puis la vapeur s&rsquo;est \u00e0 nouveau renvers\u00e9e. Une nouvelle g\u00e9n\u00e9ration a d\u00e9couvert toute la vigueur, la cr\u00e9ativit\u00e9, l&rsquo;exub\u00e9rance et les innombrables autres qualit\u00e9s des styles victoriens. Des chefs-d&rsquo;\u009cuvre, tels que la gare Victoria de Bombay ou le Keble College d&rsquo;Oxford, ont soudain \u00e9t\u00e9 retir\u00e9s de la liste des horreurs et admir\u00e9s pour l&rsquo;enthousiasme ind\u00e9niable de leur architecture et la qualit\u00e9 artisanale de leur d\u00e9coration. Des motifs d\u00e9coratifs ont r\u00e9apparu sur les nouvelles constructions, avec des \u00e9chos des arts classique, gothique et baroque, et le public s&rsquo;est mis \u00e0 d\u00e9plorer l&rsquo;uniformit\u00e9 monotone que le modern style avait impos\u00e9e aux villes du monde entier. Et les revirements de ce genre ne touchent pas que l&rsquo;architecture. La perception des paysages change aussi. Au XVIIIe si\u00e8cle, les cha\u00eenes de montagnes \u00e9taient consid\u00e9r\u00e9es comme des d\u00e9serts arides (le po\u00e8te Thomas Gray dit avoir tir\u00e9 les rideaux de sa diligence pour ne pas voir la laideur des Alpes). Cent ans plus tard, les m\u00eames montagnes \u00e9taient devenues des sources d&rsquo;inspiration et d&rsquo;appel \u00e0 l&rsquo;h\u00e9ro\u00efsme, \u00e9vocatrices de divinit\u00e9s. Aujourd&rsquo;hui, le voyageur est simplement reconnaissant de ne pas y voir de lignes \u00e0 haute tension ou de lotissement semblable \u00e0 celles dans lequel il habite.<\/p>\n<p>Autant dire que la valeur esth\u00e9tique est plus instable que les sables mouvants. L&rsquo;id\u00e9e qu&rsquo;un style architectural soit fondamentalement sup\u00e9rieur \u00e0 un autre semble aujourd&rsquo;hui ind\u00e9fendable, ce qui nous permet d&rsquo;admirer les monuments les plus divers, mais ne nous aide gu\u00e8re \u00e0 deviner lesquels nos descendants nous seront reconnaissants d&rsquo;avoir pr\u00e9serv\u00e9s. Les crit\u00e8res de l&rsquo;histoire et de l&rsquo;identit\u00e9 peuvent sembler plus coh\u00e9rents, mais ils n&rsquo;en sont pas moins sujets \u00e0 des changements ou, pire, \u00e0 des conflits. Au XIX<sup>e<\/sup> si\u00e8cle, les pionniers de la conservation architecturale pensaient qu&rsquo;il fallait prot\u00e9ger les cath\u00e9drales et les palais, mais pas les granges ni les maisonnettes. Leur point de vue \u00e9tait li\u00e9 \u00e0 leur conception de l&rsquo;histoire, encore presque limit\u00e9e \u00e0 des listes de rois et de batailles. Cependant, au fur et \u00e0 mesure que l&rsquo;approche de l&rsquo;histoire a \u00e9t\u00e9 \u00e9largie pour inclure l&rsquo;\u00e9volution sociale, \u00e9conomique et culturelle, puis, finalement, la vie quotidienne des petites gens, les constructions dans lesquelles ceux-ci ont v\u00e9cu et travaill\u00e9 ont acquis une signification nouvelle, surtout dans les pays neufs, colonis\u00e9s par les Europ\u00e9ens, qui n&rsquo;avaient pas de cath\u00e9drales et de palais anciens. Cette lacune a contribu\u00e9 \u00e0 l&rsquo;\u00e9largissement du concept de patrimoine et augment\u00e9 consid\u00e9rablement la vari\u00e9t\u00e9 des sites jug\u00e9s dignes de conservation.<\/p>\n<p>Parmi les trois crit\u00e8res, la valeur identitaire est, de beaucoup et pour le meilleur ou pour le pire, celui qui est le plus charg\u00e9 sur le plan affectif. Pendant la Deuxi\u00e8me Guerre mondiale, le gouvernement britannique a d\u00e9lib\u00e9r\u00e9ment fait la promotion d&rsquo;une image de l&rsquo;Angleterre faite de villages pittoresques avec \u00e9glises, manoirs, places publiques et prairies parsem\u00e9es de moutons. Cette image ne repr\u00e9sentait gu\u00e8re la r\u00e9alit\u00e9, puisque moins d&rsquo;un Anglais sur vingt vivait dans un village, pittoresque ou non. Cette contradiction est cependant sans importance. L&rsquo;image a donn\u00e9 aux Anglais une vision justifiant leur combat contre la laideur d&rsquo;une Allemagne urbaine et industrialis\u00e9e, remplie de relents empoisonn\u00e9s, de machines bruyantes et de gendarmes bott\u00e9s.<\/p>\n<p>La cr\u00e9ation de cette image idyllique est un bon exemple de l&rsquo;utilisation du patrimoine pour cr\u00e9er une identit\u00e9. Elle a \u00e9t\u00e9 largement reprise. Les autorit\u00e9s de certains pays font la promotion de monuments historiques pour renforcer un sens fragile de l&rsquo;identit\u00e9 nationale. Les pays d\u00e9mocratiques ont depuis longtemps pris conscience des liens entre le patrimoine et l&rsquo;identit\u00e9 nationale et de l&rsquo;influence qu&rsquo;ils peuvent exercer sur les \u00e9lecteurs et les consommateurs. Les hommes politiques se font photographier devant des \u00e9difices sugg\u00e9rant une vie simple et tranquille. En plus de vendre le soleil et le sable, les publicit\u00e9s touristiques cr\u00e9ent un monde compos\u00e9 de peu de villes et sans banlieues, mais plein d&rsquo;immeubles pittoresques, de paysages enchanteurs, de cath\u00e9drales ou de palais. Le probl\u00e8me, c&rsquo;est qu&rsquo;un m\u00eame b\u00e2timent ou paysage peut sugg\u00e9rer diff\u00e9rentes choses \u00e0 des groupes diff\u00e9rents mais, dans ce cas aussi, les perceptions changent avec le temps. Les demeures de style g\u00e9orgien et les ch\u00e2teaux pseudo-m\u00e9di\u00e9vaux de l&rsquo;aristocratie anglo-irlandaise \u00e9taient per\u00e7us comme des symboles d&rsquo;oppression dans les premi\u00e8res ann\u00e9es de l&rsquo;ind\u00e9pendance de l&rsquo;Irlande, et plusieurs ont \u00e9t\u00e9 incendi\u00e9s durant les soul\u00e8vements du d\u00e9but des ann\u00e9es 1920. Beaucoup d&rsquo;autres sont aujourd&rsquo;hui en ruines, mais au fur et \u00e0 mesure que s&rsquo;est estomp\u00e9 le souvenir de l&rsquo;asservissement, les \u00e9l\u00e9gantes demeures irlando-g\u00e9orgiennes sont devenues un \u00e9l\u00e9ment pr\u00e9cieux du patrimoine national. Les ch\u00e2teaux du XIX<sup>e<\/sup> si\u00e8cle ont repris du service avec un secteur touristique florissant, et les sombres aspects de leur pass\u00e9 a \u00e9t\u00e9 discr\u00e8tement mis de c\u00f4t\u00e9. Un changement d&rsquo;attitudes similaire a favoris\u00e9 la restauration des demeures entour\u00e9es de murs de l&rsquo;aristocratie lettr\u00e9e de la Chine, un moment menac\u00e9es d&rsquo;oblit\u00e9ration pendant la R\u00e9volution culturelle.<\/p>\n<p>Pour surmonter ces obstacles, les gouvernements sont port\u00e9s \u00e0 subordonner les choix \u00e0 un processus en trois \u00e9tapes. La premi\u00e8re est l&rsquo;adoption de normes officielles exprimant g\u00e9n\u00e9ralement des principes tr\u00e8s g\u00e9n\u00e9raux, dont les normes de Parcs Canada fournissent un bon exemple :<\/p>\n<blockquote><p><em>\u00ab\u00a0Valeur patrimoniale : importance esth\u00e9tique, historique, scientifique, \u00e9ducative, culturelle, sociale ou spirituelle [d&rsquo;un lieu] pour les g\u00e9n\u00e9rations pass\u00e9es, pr\u00e9sentes ou futures.\u00a0\u00bb<\/em><\/p><\/blockquote>\n<p>L&rsquo;on pourrait difficilement trouver des termes plus g\u00e9n\u00e9raux. L&rsquo;esth\u00e9tique a refait surface et la valeur \u00ab\u00a0spirituelle\u00a0\u00bb ajoute une nouvelle dimension qui pourrait d\u00e9concerter certains pays plus s\u00e9culiers. Pour l&rsquo;application de d\u00e9finitions aussi g\u00e9n\u00e9rales \u00e0 des cas particuliers, les gouvernements s&rsquo;en remettent aux opinions d&rsquo;experts &#8211; architectes, historiens, chercheurs, arch\u00e9ologues &#8211; et, de plus en plus, \u00e0 l&rsquo;opinion publique ou communautaire, qu&rsquo;ils recueillent par voie de consultations visant aussi bien les personnes directement concern\u00e9es que les groupes b\u00e9n\u00e9voles \u009cuvrant dans le domaine.<\/p>\n<p>Le cheminement en trois \u00e9tapes &#8211; normes, avis d&rsquo;experts et consultation &#8211; n&rsquo;est pas la solution id\u00e9ale. Sa complexit\u00e9 permet mal de faire face aux situations d&rsquo;urgence qui se pr\u00e9sentent fr\u00e9quemment. Comme c&rsquo;est souvent le cas avec les organismes d&rsquo;\u00c9tat modernes, ce processus peut conf\u00e9rer trop de pouvoirs aux groupes de pression, au nom de l&rsquo;engagement communautaire. Il dilue la subjectivit\u00e9 que comporte in\u00e9vitablement l&rsquo;exercice d&rsquo;un jugement de valeur mais, pas plus que tout autre processus imaginable, il ne peut l&rsquo;\u00e9liminer compl\u00e8tement. Les experts sont aussi des humains, et nous sommes tous plus ou moins prisonniers des valeurs et attitudes de notre \u00e9poque. En pratique, la d\u00e9cision est souvent dict\u00e9e par les \u00e9v\u00e9nements, par exemple quand un \u00e9difice ou un site \u00e9ventuellement important est menac\u00e9 de d\u00e9molition ou de lotissement. Mais il est difficile d&rsquo;imaginer une meilleure m\u00e9thode. Le cheminement en trois \u00e9tapes tient certainement compte de plus de faits historiques et d&rsquo;opinions inform\u00e9es, et la participation du public r\u00e9duit le risque de manipulations occultes si des sommes importantes sont en cause.<\/p>\n<p>Nous avons jusqu&rsquo;ici utilis\u00e9 les mots \u00ab\u00a0conservation\u00a0\u00bb et \u00ab\u00a0pr\u00e9servation\u00a0\u00bb indiff\u00e9remment, mais dans l&rsquo;usage courant, la pr\u00e9servation, c&rsquo;est-\u00e0-dire le maintien de l&rsquo;int\u00e9grit\u00e9 physique d&rsquo;un \u00e9difice ou d&rsquo;un site, n&rsquo;est qu&rsquo;une forme de conservation. La r\u00e9habilitation, plus ambitieuse, conf\u00e8re une nouvelle utilit\u00e9 \u00e0 un b\u00e2timent tout en pr\u00e9servant sa valeur patrimoniale, un double objectif qui suscite de s\u00e9rieuses difficult\u00e9s pratiques. Plus ambitieuse encore est la restauration, qui consiste \u00e0 rendre \u00e0 un b\u00e2timent l&rsquo;apparence qu&rsquo;il avait \u00e0 un moment particulier dans le pass\u00e9.<\/p>\n<p>La restauration pr\u00e9sente des difficult\u00e9s dans le cas de tout \u00e9difice qui a \u00e9t\u00e9 utilis\u00e9 pendant une p\u00e9riode prolong\u00e9e. D&rsquo;abord, \u00e0 quel stade de son histoire veut-on ramener le monument ? Comme on l&rsquo;a vu, nous ne croyons plus \u00e0 la sup\u00e9riorit\u00e9 des p\u00e9riodes \u00ab\u00a0classiques\u00a0\u00bb, mais l&rsquo;objectif doit, dans une certaine mesure, correspondre aux valeurs pr\u00e9valant \u00e0 l&rsquo;\u00e9poque vis\u00e9e par la restauration. On risque toujours de sacrifier la valeur historique du monument \u00e0 une mode ou une id\u00e9ologie passag\u00e8re. Prenons, par exemple, le Panth\u00e9on de Rome. Il fut construit par l&#8217;empereur Hadrien (117 135 de notre \u00e8re), et il est le plus vieux monument intact d&rsquo;Europe et l&rsquo;un des plus remarquables de tous les temps. Au VIIe si\u00e8cle, il fut converti en \u00e9glise, ce qu&rsquo;il est toujours. Au XIX<sup>e<\/sup> si\u00e8cle, les rois d&rsquo;Italie ont d\u00e9cid\u00e9, avec une certaine arrogance, de s&rsquo;y faire enterrer, et leurs tombes s&rsquo;y trouvent encore. L&rsquo;\u00e9glise et les tombeaux surprendraient beaucoup Hadrien, mais personne ne sugg\u00e8re de les en retirer au nom d&rsquo;une \u00ab\u00a0restauration\u00a0\u00bb quelconque. Les supprimer serait refaire l&rsquo;histoire plut\u00f4t que l&rsquo;illustrer.<\/p>\n<p>Quoi qu&rsquo;il en soit, l&rsquo;id\u00e9e de restaurer les monuments patrimoniaux est populaire, comme l&rsquo;est aussi celle de les reconstruire enti\u00e8rement, comme la forteresse de Louisbourg, au Cap-Breton. Bien des gens consid\u00e8rent que ces deux approches accroissent la valeur \u00e9ducative des lieux historiques. Elles augmentent certainement aussi leur valeur touristique, car ces sites attirent des visiteurs qui n&rsquo;appr\u00e9cieraient gu\u00e8re de ne trouver que quelques hectares de ruines poussi\u00e9reuses. Certains, manquant de confiance envers l&rsquo;imagination des visiteurs, ont m\u00eame recours \u00e0 des acteurs pour illustrer les activit\u00e9s des occupants d&rsquo;autrefois. Dans certains contextes, ces reconstitutions peuvent, comme le patrimoine en g\u00e9n\u00e9ral, renforcer le sentiment d&rsquo;appartenance \u00e0 une collectivit\u00e9 partageant un pass\u00e9 commun.<\/p>\n<p>H\u00e9las, la restauration et la reconstruction peuvent aussi \u00eatre asservies \u00e0 des fins personnelles et politiques. Sir Arthur Evans, qui a fait excaver le palais de Minos, \u00e0 Knossos, \u00e9tait si fier de l&rsquo;avoir fait (et si riche) qu&rsquo;il a reconstruit \u00e0 ses frais une bonne partie du palais, lui ajoutant probablement plusieurs \u00e9tages que le roi Minos n&rsquo;a jamais vus. Au Mexique, dans les d\u00e9cennies qui ont suivi la R\u00e9volution (achev\u00e9e en 1920), le gouvernement a voulu faire du pass\u00e9 pr\u00e9colombien le fondement de l&rsquo;identit\u00e9 nationale. Il a affect\u00e9 des sommes \u00e9normes \u00e0 la restauration &#8211; peut-\u00eatre pas toujours tr\u00e8s fid\u00e8le &#8211; de temples et de pyramides. Ces travaux ont contribu\u00e9 tant au secteur touristique mexicain qu&rsquo;\u00e0 la fiert\u00e9 nationale. \u00c0 des fins plus douteuses, Saddam Hussein avait entrepris de restaurer Babylone avec des briques portant l&rsquo;inscription \u00ab\u00a0Saddam, fils de Nabuchodonosor\u00a0\u00bb, comme s&rsquo;il \u00e9tait lui-m\u00eame roi de Babylone. Et pour que personne ne puisse l&rsquo;ignorer, les visiteurs \u00e9taient accueillis au site par un immense panneau montrant Saddam et Nabuchodonosor \u00e0 son c\u00f4t\u00e9.<\/p>\n<p>Un autre danger de la restauration, davantage en Am\u00e9rique du Nord peut-\u00eatre, est une \u00ab\u00a0Dysn\u00e9ification\u00a0\u00bb consistant \u00e0 pr\u00e9senter le pass\u00e9 comme \u00e9tant beaucoup plus propre, organis\u00e9 et salubre qu&rsquo;en r\u00e9alit\u00e9. La cr\u00e9ation de telles versions expurg\u00e9es est l&rsquo;un des nombreux probl\u00e8mes qu&rsquo;entra\u00eene la combinaison de projets de restauration avec les objectifs de la consommation et du tourisme. Il est bien certain que le tourisme a largement contribu\u00e9 \u00e0 populariser la conservation du patrimoine et qu&rsquo;il le justifie, surtout aux yeux des organismes publics qui doivent en assumer le co\u00fbt. Il est difficile aussi de critiquer le principe : pourquoi pr\u00e9server un patrimoine si personne ne doit le voir ? Certaines incompatibilit\u00e9s sont pourtant in\u00e9vitables. Peu de b\u00e2timents autres que des cath\u00e9drales sont assez grands pour accueillir simultan\u00e9ment des centaines ou des milliers de visiteurs. Beaucoup, d&rsquo;ailleurs, n&rsquo;ont pas \u00e9t\u00e9 con\u00e7us du tout pour accueillir le public. Les architectes de tombes d&rsquo;\u00c9gypte \u00e9taient certainement bien loin de penser aux essaims de touristes circulant en autocar. M\u00eame dans des situations moins extr\u00eames, les touristes les plus respectueux de l&rsquo;environnement peuvent causer des d\u00e9g\u00e2ts et de l&rsquo;usure. Il a fallu fermer les c\u00e9l\u00e8bres cavernes peintes de Lascaux, en France, parce que l&rsquo;haleine des visiteurs les endommageait. De plus, tous les touristes ne se comportent pas comme ils le devraient. Les ch\u00e2teaux ouverts au public doivent \u00eatre pr\u00e9alablement d\u00e9garnis des objets transportables ou empochables qui s&rsquo;y trouvent, ce qui donne l&rsquo;impression d&rsquo;un mus\u00e9e plut\u00f4t que d&rsquo;une demeure o\u00f9 des gens ont v\u00e9cu et, souvent, vivent encore.<\/p>\n<p>Il existe aussi un probl\u00e8me plus fondamental, et insoluble : celui du manque d&rsquo;espace. Le centre historique de Venise compte 70 000 habitants. Construit sur des \u00eeles, il ne peut s&rsquo;\u00e9tendre ni en hauteur ni en largeur. Or, il accueille plus de sept millions de visiteurs chaque ann\u00e9e. Il n&rsquo;est donc pas surprenant que les personnes qui ne travaillent pas dans le domaine du tourisme -cuisiniers, serveurs, guides, gondoliers &#8211; ou ne sont ni des fonctionnaires ni des \u00e9ducateurs, pr\u00e9f\u00e8rent d\u00e9m\u00e9nager. En pratique, la ville est aujourd&rsquo;hui, \u00e0 la fois, un mus\u00e9e splendide et un parc th\u00e9matique. Elle accueille des foules incroyables au printemps et en automne, et les d\u00e9tritus et la pollution s&rsquo;y accumulent \u00e0 l&rsquo;avenant. Sous la pression de la demande, les prix montent en fl\u00e8che, comme le d\u00e9couvre vite quiconque commande une tasse de caf\u00e9 sur la place Saint-Marc. Les prix des chambres d&rsquo;h\u00f4tel sont si extravagants que la plupart des visiteurs logent sur la terre ferme ou ne viennent \u00e0 Venise que pour une journ\u00e9e. Cette situation est fonci\u00e8rement anti-d\u00e9mocratique. Pourquoi les gens fortun\u00e9s seraient-ils seuls \u00e0 pouvoir profiter d&rsquo;un des lieux les plus magiques du monde ? La seule autre solution serait de limiter le passage d&rsquo;une fa\u00e7on ou d&rsquo;une autre. D&rsquo;autres sites c\u00e9l\u00e8bres, y compris Stratford-upon-Avon, en Angleterre, souffrent du m\u00eame probl\u00e8me : le tourisme de masse menace de les d\u00e9truire. Quelles que soient les solutions envisag\u00e9es, on peut facilement pr\u00e9voir que, t\u00f4t ou tard, il sera plus difficile de d\u00e9cider qui doit avoir acc\u00e8s au patrimoine que de d\u00e9terminer ce qui doit y figurer.<\/p>\n<p>N\u00e9anmoins, dans l&rsquo;ensemble, les effets du tourisme sont extr\u00eamement positifs. Il aide \u00e0 absorber les co\u00fbts, surtout en Europe, o\u00f9 la plupart des pays sont tr\u00e8s riches en monuments historiques, en sites arch\u00e9ologiques et en paysages ayant une valeur patrimoniale indiscutable, mais dont la protection, l&rsquo;entretien et le personnel co\u00fbtent cher. L&rsquo;excellent \u00e9tat des immenses cath\u00e9drales gothiques, apr\u00e8s 800 ans ou plus, est sans aucun doute un hommage \u00e0 leurs constructeurs, mais bon nombre seraient disparues aujourd&rsquo;hui si elles n&rsquo;avaient pas \u00e9t\u00e9 entretenues au fil des si\u00e8cles par des ouvriers hautement qualifi\u00e9s. Les achats et les billets d&rsquo;entr\u00e9e des touristes, ainsi que des subventions publiques souvent g\u00e9n\u00e9reuses, permettent le financement de charges souvent tr\u00e8s lourdes ; ils aident les aristocrates insuffisamment nantis \u00e0 entretenir leurs demeures ancestrales et les villes \u00e0 organiser des services d&rsquo;accueil pour les vagues annuelles de touristes. Pour rem\u00e9dier, du moins partiellement, au probl\u00e8me de la surpopulation, on pourrait imposer un \u00ab\u00a0droit de congestion\u00a0\u00bb dans le genre de celui qui est d\u00e9sormais exig\u00e9 pour circuler dans le centre de Londres. Obliger tous les visiteurs \u00e0 payer \u00e9galement, tout en pr\u00e9voyant les r\u00e9ductions usuelles pour les \u00e9tudiants et les a\u00een\u00e9s, permettrait de respecter le principe de l&rsquo;accessibilit\u00e9 tout en finan\u00e7ant l&rsquo;entretien et en pr\u00e9servant la qualit\u00e9 de l&rsquo;exp\u00e9rience pour les visiteurs.<\/p>\n<p>Quelque \u00e9pineuse que soit cette question, il devrait \u00eatre possible de la r\u00e9soudre en la consid\u00e9rant du point de vue des co\u00fbts d&rsquo;opportunit\u00e9. Un immeuble ou un paysage dont l&rsquo;on tient vraiment \u00e0 pr\u00e9server l&rsquo;int\u00e9grit\u00e9 ne peut pas \u00eatre affect\u00e9 \u00e0 des fins nouvelles. Entre autres, il ne peut pas \u00eatre r\u00e9am\u00e9nag\u00e9 de fa\u00e7on \u00e0 en rationaliser l&rsquo;usage et \u00e0 accro\u00eetre sa valeur ou les revenus qu&rsquo;il procure. Si le site appartient \u00e0 un particulier, cette restriction peut souvent entra\u00eener un manque \u00e0 gagner important pour le propri\u00e9taire. Un lotisseur est rarement populaire, surtout s&rsquo;il s&rsquo;agit d&rsquo;une grande entreprise ; pour les militants de la conservation du patrimoine, il est l&rsquo;ennemi incarn\u00e9. Mais il est difficile de justifier que le propri\u00e9taire d&rsquo;une maison puisse la vendre \u00e0 un lotisseur et r\u00e9aliser ainsi un profit (non impos\u00e9 au Canada s&rsquo;il s&rsquo;agit d&rsquo;une r\u00e9sidence principale) alors que son voisin imm\u00e9diat ne peut pas le faire, simplement parce qu&rsquo;une autorit\u00e9 a class\u00e9 sa maison comme site patrimonial. Il peut sembler logique que, si la soci\u00e9t\u00e9 veut pr\u00e9server cette maison, elle devrait compenser son propri\u00e9taire pour ce manque \u00e0 gagner. Mais l&rsquo;\u00e9normit\u00e9 des frais que l&rsquo;application de ce principe pourrait entra\u00eener a, jusqu&rsquo;ici, emp\u00each\u00e9 son adoption. Par contre, si le propri\u00e9taire doit faire des r\u00e9parations co\u00fbteuses et remplacer une plomberie du XIX<sup>e<\/sup> si\u00e8cle, il peut b\u00e9n\u00e9ficier de concessions fiscales et, parfois, d&rsquo;une subvention directe.<\/p>\n<p>Ce domaine du droit et de la jurisprudence est complexe et en pleine \u00e9volution. L&rsquo;on peut consid\u00e9rer qu&rsquo;il existe une diff\u00e9rence de principe entre le propri\u00e9taire auquel on impose une d\u00e9signation patrimoniale et le lotisseur qui ach\u00e8te la maison en comptant bien parvenir \u00e0 faire modifier son classement. C&rsquo;est ce genre de probl\u00e8mes qui impose une revue judiciaire pour tant de d\u00e9signations patrimoniales et qui incite parfois &#8211; quoique pas toujours &#8211; les juges ou arbitres \u00e0 sympathiser avec le propri\u00e9taire : en pratique, celui-ci se fait confisquer son bien sans la protection d&rsquo;une proc\u00e9dure judiciaire appropri\u00e9e. Souvent, le principal effet d&rsquo;une d\u00e9signation patrimoniale est d&rsquo;alerter le public sur la perte possible d&rsquo;un site historique. Parfois, sous la pression de l&rsquo;opinion publique, un lotisseur proposera un compromis, par exemple, la pr\u00e9servation de l&rsquo;un des \u00e9difices vis\u00e9s ou d&rsquo;une fa\u00e7ade classique du XIX<sup>e<\/sup> si\u00e8cle sur un b\u00e2timent tout neuf. En fait, il n&rsquo;existe aucune solution claire dans ce domaine, et certainement aucune solution peu on\u00e9reuse ; le syst\u00e8me actuel du cas par cas semble destin\u00e9 \u00e0 perdurer car les solutions plus rationnelles ne sont pas politiquement viables.<\/p>\n<p>Quelles conclusions tirer de tout cela ? Pourquoi tant de gens, \u00e0 travers le monde, s&rsquo;int\u00e9ressent-ils aussi activement \u00e0 la pr\u00e9servation du pass\u00e9 ?<\/p>\n<p>Deux raisons ont d\u00e9j\u00e0 \u00e9t\u00e9 sugg\u00e9r\u00e9es. D&rsquo;abord, ce patrimoine est une importante source d&rsquo;affirmation de l&rsquo;identit\u00e9 individuelle et collective dans un monde de plus en plus vou\u00e9 \u00e0 l&rsquo;homog\u00e9n\u00e9it\u00e9. Comme tous les symboles, les \u00e9difices, villes ou paysages \u00e0 caract\u00e8re patrimonial comptent plus pour ce qu&rsquo;ils repr\u00e9sentent que pour ce qu&rsquo;ils sont. Ils r\u00e9sument mieux que toute \u00e9loquence ce que cela veut dire d&rsquo;\u00eatre Am\u00e9ricain, Russe ou Mexicain. Ils relient au pass\u00e9 un pr\u00e9sent qui \u00e9volue \u00e0 un rythme d\u00e9concertant. Dans presque tous les pays, certains \u00e9difices sont devenus intouchables, pour ne pas dire sacr\u00e9s. Personne ne songerait \u00e0 r\u00e9am\u00e9nager, quelque colossale qu&rsquo;en soit la valeur potentielle, le site de la cath\u00e9drale Saint-Paul de Londres ou celui du Palais imp\u00e9rial de Tokyo. En fait, l&rsquo;homme a tellement besoin d&rsquo;affirmer son identit\u00e9 que certains \u00e9difices doivent d&rsquo;\u00eatre arrach\u00e9s \u00e0 l&rsquo;oubli et \u00e0 la n\u00e9gligence au fait qu&rsquo;ils incarnent une \u00e9poque glorieuse ou un trait national aim\u00e9.<\/p>\n<p>La seconde raison est d&rsquo;un ordre plus pratique. Le patrimoine est une \u00e9norme entreprise commerciale. La d\u00e9signation, la conservation, l&rsquo;exploitation et l&rsquo;\u00e9tude de sites, grands et petits, exigent l&rsquo;intervention de nombreuses personnes de grande comp\u00e9tence, dont les activit\u00e9s sont financ\u00e9es par l&rsquo;\u00c9tat, des organismes b\u00e9n\u00e9voles et les revenus r\u00e9alis\u00e9s par les sites eux-m\u00eames. Le patrimoine est intimement li\u00e9 au tourisme, qui est maintenant, para\u00eet-il, la plus grosse industrie du monde. Et qu&rsquo;on aime ou honnisse le tourisme, aucun gouvernement ne peut l&rsquo;ignorer et la plupart affectent des sommes consid\u00e9rables \u00e0 sa promotion. Le touriste d\u00e9sire, par d\u00e9finition, voir quelque chose qu&rsquo;il n&rsquo;a pas chez lui, et la conservation du patrimoine r\u00e9pond parfaitement \u00e0 ses aspirations.<\/p>\n<p>Ces deux raisons sont intimement li\u00e9es \u00e0 une troisi\u00e8me : la diffusion formelle et informelle du savoir. Les \u00e9coles et les universit\u00e9s inculquent aux \u00e9tudiants la conscience du pass\u00e9 et les sensibilisent \u00e0 l&rsquo;existence de soci\u00e9t\u00e9s diff\u00e9rentes, vivantes ou \u00e9teintes. La t\u00e9l\u00e9vision contribue aussi \u00e0 la diffusion de ces connaissances en offrant aux regards les merveilles de la nature et les plus belles r\u00e9alisations humaines. Elle aide ainsi les individus \u00e0 d\u00e9finir leur propre identit\u00e9 en termes de monuments et de lieux symboliques. Elle stimule leur curiosit\u00e9 en leur faisant conna\u00eetre les r\u00e9gions lointaines et renforce le besoin d&rsquo;\u00e9vasion, source fondamentale du tourisme de masse.<\/p>\n<p>La derni\u00e8re raison est sans doute la plus \u00e9vidente et fondamentale. Parler de la vitesse du changement est un clich\u00e9, mai qui nous touche tous. La plupart des plus de 40 ans ont v\u00e9cu l&rsquo;exp\u00e9rience de revoir un lieu autrefois familier sans pouvoir le reconna\u00eetre. Plus que les g\u00e9n\u00e9rations pr\u00e9c\u00e9dentes, nous savons que le pass\u00e9 ne se pr\u00e9serve pas de lui-m\u00eame. Si nous lui attribuons une valeur, nous devons le prot\u00e9ger des pressions que nous cr\u00e9ons nous-m\u00eames. Peut-\u00eatre savons-nous aussi, \u00e0 un niveau plus fondamental, que notre patrimoine ne nous appartient pas : nous en sommes les d\u00e9positaires et il nous incombe de le transmettre aussi int\u00e9gralement que possible aux g\u00e9n\u00e9rations futures. C&rsquo;est ainsi que nous acquittons notre dette envers ceux qui nous l&rsquo;ont l\u00e9gu\u00e9.<\/p>\n<\/div>\n","protected":false},"author":86,"featured_media":0,"template":"","categories":[1],"rbc_letter_theme":[],"rbc_letter_year":[82],"class_list":["post-2489","rbc_letter","type-rbc_letter","status-publish","hentry","category-uncategorized","rbc_letter_year-82"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine - RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine\" \/>\n<meta property=\"og:description\" content=\"\u00c0 peine une douzaine de monuments dans le monde ont acquis une valeur symbolique assez forte pour sugg\u00e9rer aussit\u00f4t l&rsquo;image d&rsquo;une ville ou d&rsquo;un pays, et le secteur touristique les utilise abondamment pour \u00e9voquer l&rsquo;attrait de lointaines contr\u00e9es : le Taj Mahal pour l&rsquo;Inde, la tour Eiffel pour Paris, le Parlement pour Londres. L&rsquo;un des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T18:41:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"27 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/septembre-2007-a-la-decouverte-de-notre-patrimoine\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/septembre-2007-a-la-decouverte-de-notre-patrimoine\\\/\",\"name\":\"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine - RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\"},\"datePublished\":\"2007-09-01T00:00:00+00:00\",\"dateModified\":\"2022-10-17T18:41:14+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/septembre-2007-a-la-decouverte-de-notre-patrimoine\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/\",\"name\":\"RBC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine - RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","og_locale":"fr_FR","og_type":"article","og_title":"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine","og_description":"\u00c0 peine une douzaine de monuments dans le monde ont acquis une valeur symbolique assez forte pour sugg\u00e9rer aussit\u00f4t l&rsquo;image d&rsquo;une ville ou d&rsquo;un pays, et le secteur touristique les utilise abondamment pour \u00e9voquer l&rsquo;attrait de lointaines contr\u00e9es : le Taj Mahal pour l&rsquo;Inde, la tour Eiffel pour Paris, le Parlement pour Londres. L&rsquo;un des [&hellip;]","og_url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","og_site_name":"RBC","article_modified_time":"2022-10-17T18:41:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"27 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","name":"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine - RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/#website"},"datePublished":"2007-09-01T00:00:00+00:00","dateModified":"2022-10-17T18:41:14+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/#website","url":"https:\/\/www.rbc.com\/fr\/","name":"RBC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Septembre 2007- \u00c0 la d\u00e9couverte de notre patrimoine","url":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/septembre-2007-a-la-decouverte-de-notre-patrimoine\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"zinoemielu"}],"creator":["zinoemielu"],"publisher":{"@type":"Organization","name":"RBC","logo":""},"keywords":[],"dateCreated":"2007-09-01T00:00:00Z","datePublished":"2007-09-01T00:00:00Z","dateModified":"2022-10-17T18:41:14Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Septembre 2007- \\u00c0 la d\\u00e9couverte de notre patrimoine\",\"url\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/septembre-2007-a-la-decouverte-de-notre-patrimoine\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/septembre-2007-a-la-decouverte-de-notre-patrimoine\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"zinoemielu\"}],\"creator\":[\"zinoemielu\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2007-09-01T00:00:00Z\",\"datePublished\":\"2007-09-01T00:00:00Z\",\"dateModified\":\"2022-10-17T18:41:14Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbc.com\/p.js"},"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbc.com\/fr\/author\/zinoemielu\/","display_name":"zinoemielu"},"relative_dates":{"created":"Publi\u00e9 19 ans il y a","modified":"Mis \u00e0 jour 4 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 1 septembre 2007","modified":"Mise \u00e0 jour le 17 octobre 2022"},"absolute_dates_time":{"created":"Publi\u00e9 le 1 septembre 2007 12:00  ","modified":"Mise \u00e0 jour le 17 octobre 2022 6:41  "},"featured_img_caption":"","tax_additional":{"category":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/category\/uncategorized\/\" class=\"advgb-post-tax-term\">Uncategorized<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Uncategorized<\/span>"],"slug":"category","name":"Cat\u00e9gories"},"rbc_letter_theme":{"linked":[],"unlinked":[],"slug":"rbc_letter_theme","name":"Themes"},"rbc_letter_year":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/year\/2007\/\" class=\"advgb-post-tax-term\">2007<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">2007<\/span>"],"slug":"rbc_letter_year","name":"Years"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/types\/rbc_letter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/users\/86"}],"version-history":[{"count":0,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2489\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media?parent=2489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/categories?post=2489"},{"taxonomy":"rbc_letter_theme","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_theme?post=2489"},{"taxonomy":"rbc_letter_year","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_year?post=2489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}