{"id":2116,"date":"1980-02-01T00:00:00","date_gmt":"1980-02-01T00:00:00","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/"},"modified":"2022-10-17T20:22:54","modified_gmt":"2022-10-17T20:22:54","slug":"vol-61-n-2-fevrier-1980-levolution-des-normes","status":"publish","type":"rbc_letter","link":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","title":{"rendered":"Vol. 61, N\u00b0 2 &#8211; F\u00e9vrier 1980 &#8211; L&rsquo;\u00e9volution des normes"},"content":{"rendered":"<div id=\"layout-column-main\">\n<p class=\"boldtext\">Proc\u00e9d\u00e9 d&rsquo;origine fort ancienne,                     la normalisation conna\u00eet un essor nouveau depuis que                     l&rsquo;Am\u00e9rique du Nord a d\u00e9cid\u00e9 de se rallier                     au syst\u00e8me m\u00e9trique. Voici un bref coup d&rsquo;oeil                     sur le d\u00e9veloppement des normes et leur n\u00e9cessit\u00e9,                     y compris celles que nous nous imposons&#8230; <\/p>\n<p> Chaque jour, \u00e0 chaque instant, nous vivons au milieu                     des normes. Le toit qui nous couvre et les murs qui nous entourent                     reposent sur des charpentes de largeur et d&rsquo;\u00e9paisseur                     normalis\u00e9es\u00a0; nous portons, de la t\u00eate aux                     pieds, des v\u00eatements de tailles et de pointures uniformes.                     Les normes r\u00e9gissent la fabrication et le fonctionnement                     d&rsquo;une foule de choses d&rsquo;usage quotidien\u00a0: meubles, commodit\u00e9s,                     appareils, outils, v\u00e9hicules. Il existe m\u00eame                     des normes pour contr\u00f4ler la puret\u00e9 de l&rsquo;air                     que nous respirons. <\/p>\n<p> Les normes se retrouvent aussi dans nos activit\u00e9s                     et dans notre environnement. Quand nous parlons \u00e0 quelqu&rsquo;un,                     les mots que nous pronon\u00e7ons ne sont compris que parce                     qu&rsquo;ils correspondent \u00e0 une norme, c&rsquo;est-\u00e0-dire                     qu&rsquo;ils ont le m\u00eame sens pour les autres que pour nous.                     Nous communiquons aussi au moyen de symboles normalis\u00e9s,                     appel\u00e9s chiffres, qui sont imm\u00e9diatement et                     universellement identifiables. Les aliments que nous mangeons                     doivent satisfaire \u00e0 certaines normes avant d&rsquo;\u00eatre                     vendus. Dans notre travail, quel qu&rsquo;il soit, nous utilisons                     des mani\u00e8res de faire normalis\u00e9es. C&rsquo;est ce                     que nous appelons des m\u00e9thodes ou des proc\u00e9d\u00e9s                     courants. <\/p>\n<p> Importantes dans notre vie personnelle, les normes sont                     absolument essentielles \u00e0 la soci\u00e9t\u00e9.                     Sans la norme de valeur que repr\u00e9sente l&rsquo;argent, l&rsquo;\u00e9conomie                     moderne ne pourrait pas exister. Sans unit\u00e9s de mesure,                     il n&rsquo;y aurait ni commerce, ni science ni industrie. Sans les                     normes de s\u00e9curit\u00e9, le monde serait un vaste                     et dangereux champ de mines. Sans les normes de conduite que                     renferment les codes moraux comme les dix commandements, les                     relations humaines seraient vou\u00e9es au chaos et \u00e0                     la barbarie. <\/p>\n<p> On pourrait dire que la soci\u00e9t\u00e9 telle que                     nous la connaissons est n\u00e9e avec l&rsquo;\u00e9tablissement                     des normes. L&rsquo;homme s&rsquo;est affranchi de son ignorance primitive                     gr\u00e2ce \u00e0 sa capacit\u00e9 de communiquer. Une                     esp\u00e8ce de norme se cr\u00e9a le jour o\u00f9 les                     membres d&rsquo;une tribu pr\u00e9historique convinrent qu&rsquo;un                     son d\u00e9signant une chose hors de vue avait la m\u00eame                     signification pour tous. Puis, les clans \u00e9labor\u00e8rent                     des r\u00e8gles \u00e0 observer pour maintenir la paix                     entre eux, en d&rsquo;autre termes des normes de conduite. <\/p>\n<p> En fixant pour la premi\u00e8re fois des normes de correspondance,                     les hommes des cavernes accomplissent un pas qui fait \u00e9poque                     dans le cheminement de l&rsquo;esprit humain. Leur intelligence                     a d\u00fb s&rsquo;\u00e9lever \u00e0 un niveau inconnu et plus                     \u00e9lev\u00e9 pour concevoir l&rsquo;id\u00e9e abstraite                     que cinq doigts, par exemple, correspondaient \u00e0 cinq                     poissons. En apprenant \u00e0 mesurer, ils poursuivent leur                     marche dans la voie de la civilisation. Le premier instrument                     de mesure fut sans doute une main ou un pied, mais tous les                     pieds et les mains ne convenaient pas vu qu&rsquo;ils n&rsquo;\u00e9taient                     \u00e9videmment pas tous de la m\u00eame grandeur. Il fallut                     donc choisir une unit\u00e9 convenue, comme la main du chef                     de tribu. <\/p>\n<p> Vu que le chef n&rsquo;\u00e9tait pas toujours l\u00e0 chaque                     fois qu&rsquo;on voulait mesurer, il \u00e9tait logique que ses                     sujets griffonnent les dimensions de si main sur une pierre                     plate et placent celle-ci dans un endroit central pour pouvoir                     la consulter. Mais, comme on peut le supposer, bient\u00f4t                     quelqu&rsquo;un transposa les marques sur un b\u00e2ton afin d&rsquo;aller                     mesurer quelque chose plus loin. <\/p>\n<p> \u00c0 cette \u00e9poque, il y a d\u00e9j\u00e0                     longtemps que l&rsquo;on a adopt\u00e9 l&rsquo;usage de multiplier ou                     de subdiviser l&rsquo;unit\u00e9 \u00e9talon pour effectuer                     des mesures plus ou moins grandes. La Coud\u00e9e royale                     des pharaons se d\u00e9compose de fa\u00e7on assez compliqu\u00e9e                     en largeurs de doigt et de paume. Il y a longtemps aussi que                     l&rsquo;homme a \u00e9tabli des normes pour les poids et les volumes\u00a0:                     des pierres de taille uniforme pour les poids et des urnes                     de circonf\u00e9rence et de profondeur courantes pour mesurer                     les liquides, les c\u00e9r\u00e9ales, etc. Comme les normes                     lin\u00e9aires, on les reproduit et on les subdivise pour                     en faciliter l&#8217;emploi. <\/p>\n<h3>L&rsquo;extension des mesures courantes suit                   celle du commerce<\/h3>\n<p> \u00c0 l&rsquo;aube de la civilisation, toutefois, les normes                     sont de caract\u00e8re strictement local. Un pied n&rsquo;est                     pas le m\u00eame dans un village que dans l&rsquo;autre, parce                     que sa longueur d\u00e9pend de la dimension des pieds du                     chef. Le proc\u00e9d\u00e9 que nous appelons aujourd&rsquo;hui                     la normalisation na\u00eet avec l&rsquo;av\u00e8nement du commerce                     dans l&rsquo;ancien monde, au moment o\u00f9 les habitants d&rsquo;une                     r\u00e9gion constatent qu&rsquo;il faut conna\u00eetre les mesures                     utilis\u00e9es dans une autre pour faire des affaires. Ils                     se rendent bient\u00f4t compte que les choses seraient plus                     faciles pour tout le monde s&rsquo;ils adoptaient des mesures susceptibles                     d&rsquo;\u00eatre comprises et reconnues partout o\u00f9 s&rsquo;effectuent                     d&rsquo;ordinaire les \u00e9changes. <\/p>\n<p> Vers 3500 av. J.-C., les Hittites, les Assyriens, les Ph\u00e9niciens                     et les H\u00e9breux ont tous, jusqu&rsquo;\u00e0 un certain                     point, adopt\u00e9 le syst\u00e8me de mesures institu\u00e9                     \u00e0 Babylone. Des rives de la M\u00e9diterran\u00e9e                     jusqu&rsquo;\u00e0 la vall\u00e9e de l&rsquo;Indus \u00e0 des milliers                     de kilom\u00e8tres vers l&rsquo;est, les mesures d&rsquo;origine babylonienne,                     introduites d&rsquo;abord dans le commerce, finissent par s&rsquo;implanter                     dans l&rsquo;usage courant. <\/p>\n<p> Une autre grande vague de normalisation devait co\u00efncider                     avec l&rsquo;expansion de l&rsquo;Empire romain. S&rsquo;inspirant des normes                     grecques, emprunt\u00e9es elles-m\u00eames \u00e0 l&rsquo;\u00c9gypte                     et \u00e0 Babylone, les Romains \u00e9laborent leurs propres                     mesures et les r\u00e9pandent dans toutes leurs colonies.                   <\/p>\n<p> Aux Romains revient le m\u00e9rite d&rsquo;avoir franchi le                     pas que l&rsquo;intelligence devait faire pour passer des normes                     tangibles aux normes conceptuelles, en proclamant, par exemple,                     que mille pas \u00e9quivalaient \u00e0 un <em>mille<\/em>,                     anc\u00eatre de nom seulement du <em>mile <\/em>anglais. Comme                     beaucoup de peuples avant eux, ils recherchaient des normes                     immuables \u00e0 l&rsquo;\u00e9chelle de l&rsquo;univers. Dans un                     acte de normalisation des plus m\u00e9morables de l&rsquo;histoire,                     Jules C\u00e9sar collabore avec l&rsquo;astronome Sosig\u00e8ne                     \u00e0 la mise au point d&rsquo;un calendrier fond\u00e9 sur                     la position de la terre par rapport au soleil et \u00e0                     la lune pendant les diverses saisons. M\u00eame s&rsquo;il a \u00e9t\u00e9                     modifi\u00e9 plus tard par l&#8217;empereur Auguste et le pape                     Gr\u00e9goire XIII, on se sert encore du calendrier de C\u00e9sar                     dans le monde entier pour d\u00e9terminer les dates. <\/p>\n<h3>Le haut moyen \u00e2ge, p\u00e9riode sombre pour les                     normes<\/h3>\n<p> Apr\u00e8s avoir imagin\u00e9 les normes conceptuelles,                     les Romains en \u00e9tendent l&rsquo;application \u00e0 des                     domaines nouveaux. Ils promulguent des normes \u00e9crites                     pour les ingr\u00e9dients du pain et les dimensions des                     conduites d&rsquo;eau. Ils construisent, \u00e0 Pomp\u00e9i,                     une voie empierr\u00e9e qui exige que la largeur des chars                     soit normalis\u00e9e d&rsquo;apr\u00e8s celle de la route. Les                     l\u00e9gions romaines ont des exercices et un fourniment                     normalis\u00e9s, ce qui explique peut-\u00eatre en grande                     partie leurs succ\u00e8s militaires. <\/p>\n<p> La normalisation subit un grave recul avec la chute de l&rsquo;Empire                     romain, qui marque le retour \u00e0 l&rsquo;esprit de clocher                     dans les pays d&rsquo;Europe. Les rois et les seigneurs de la f\u00e9odalit\u00e9                     prennent l&rsquo;habitude de d\u00e9cr\u00e9ter des normes dans                     leurs terres selon leur caprice. L&rsquo;absence de normes g\u00e9n\u00e9rales                     est n\u00e9faste au commerce, et le manque de contact entre                     les marchands ralentit la diss\u00e9mination du savoir et                     contribue \u00e0 prolonger l&rsquo;\u00e2ge des t\u00e9n\u00e8bres.                     Les mesures tra\u00eenent le pas. Alors que les Romains avaient                     un pied normalis\u00e9 de 12 pouces dans toute l&rsquo;\u00e9tendue                     de leur empire, il existe alors, dit-on, en Europe continentale                     jusqu&rsquo;\u00e0 280 variantes du pied. <\/p>\n<p> En Angleterre, la situation est telle qu&rsquo;au moment de la                     r\u00e9daction de la Grande Charte, en 1215, les barons                     y ins\u00e8rent une clause r\u00e9clamant des mesures                     uniformes dans tout le royaume pour la bi\u00e8re, les c\u00e9r\u00e9ales                     et le drap. Quelques ann\u00e9es plus tard, une ordonnance                     royale d\u00e9finit une vaste s\u00e9rie de normes et                     prescrit une unit\u00e9 \u00e9talon de mesure de longueur\u00a0:                     \u00ab\u00a0le Yard de fer de notre seigneur le Roi\u00a0\u00bb. \u00c0                     part quelques r\u00e9visions et de nombreuses additions,                     ces normes demeurent intactes durant six si\u00e8cles. <\/p>\n<p> Pourtant, la prolif\u00e9ration des mesures anglaises                     avec les ann\u00e9es s&rsquo;av\u00e8re une source de confusion.                     Elle suscite un fouillis de mesures diverses, qui trop souvent                     ont des bases num\u00e9riques diff\u00e9rentes\u00a0:                     furlongs, acres, perches, brasses, scrupules, onces (troy),                     onces (liquides), chopines (liquides), chopines (mati\u00e8res                     s\u00e8ches), tonnes (courtes), tonnes (longues), barils                     (huile), barils (bi\u00e8re). Ce qui complique encore des                     choses en Am\u00e9rique du Nord, c&rsquo;est que des mesures du                     m\u00eame nom au Canada et aux \u00c9tats-Unis sont parfois                     diff\u00e9rentes. Ainsi, le gallon am\u00e9ricain est                     plus petit que le gallon canadien, parce que les Am\u00e9ricains                     ont toujours tenu mordicus \u00e0 l&rsquo;ancien gallon de la                     reine Anne, malgr\u00e9 la proclamation, en 1824, du gallon                     imp\u00e9rial en Grande-Bretagne. <\/p>\n<h3>Il y a des ann\u00e9es que les livres et les yards ne                                         sont plus des normes<\/h3>\n<p> C&rsquo;est pr\u00e9cis\u00e9ment pour lutter contre le d\u00e9sordre                     ainsi cr\u00e9\u00e9 outre-Manche que la France de la                     R\u00e9volution d\u00e9clare le m\u00e8tre et le kilogramme                     seules unit\u00e9s de mesure pour tous les usages en 1795.                   <\/p>\n<p> Dans ces unit\u00e9s multipliables et divisibles par 10,                     les virgules d\u00e9cimales remplacent les embarrassantes                     fractions requises pour la conversion dans le syst\u00e8me                     anglais. Malgr\u00e9 l&rsquo;\u00e9chec de la tentative faite                     en m\u00eame temps pour instituer la journ\u00e9e de 10                     heures et le mois de 30 jours, le syst\u00e8me m\u00e9trique                     se r\u00e9pand graduellement dans le monde entier gr\u00e2ce                     \u00e0 sa simplicit\u00e9 et \u00e0 son adaptabilit\u00e9.                     En 1875, la signature de la convention du m\u00e8tre sanctionne                     la cr\u00e9ation du Bureau international des poids et mesures                     \u00e0 S\u00e8vres, pr\u00e8s de Paris. Puis, on \u00e9tablit                     les nouveaux \u00e9talons du kilogramme et du m\u00e8tre.                     L&rsquo;un de ceux-ci, constitu\u00e9 par un cylindre en platine                     iridi\u00e9 d\u00e9pos\u00e9 au pavillon de Breteuil,                     \u00e0 S\u00e8vres, demeure encore l&rsquo;\u00e9talon mondial                     du kilogramme. Mais les progr\u00e8s de la physique conduisent                     au remplacement de l&rsquo;ancien prototype m\u00e9tallique du                     m\u00e8tre. Le m\u00e8tre officiel est aujourd&rsquo;hui la                     longueur \u00e9gale \u00e0 \u00ab\u00a01 650 763.73 longueurs                     d&rsquo;onde de la radiation rouge orange du krypton 86\u00a0\u00bb.                   <\/p>\n<p> En 1893, les \u00c9tats-Unis abandonnent leurs prototypes                     en m\u00e9tal de la livre et du yard et les red\u00e9finissent                     en fonction du kilogramme et du m\u00e8tre internationaux.                     En 1951, le Canada en fait autant, apr\u00e8s avoir d\u00e9couvert,                     semble-t-il, que le mod\u00e8le canadien de la livre \u00e9talon                     britannique, \u00e0 Ottawa, diff\u00e9rait l\u00e9g\u00e8rement                     du prototype original. Par la suite, nos livres et nos yards                     officiels seront d\u00e9finis en tant que fractions ultra-pr\u00e9cises                     du m\u00e8tre et du kilogramme. La livre et le yard cesseront                     compl\u00e8tement d&rsquo;\u00eatre des normes lorsque le gouvernement                     britannique embo\u00eetera le pas en 1959. <\/p>\n<h3>Une s\u00e9rie unique de mesures dans un monde multiple<\/h3>\n<p> Ces derni\u00e8res ann\u00e9es, la Grande-Bretagne,                     le Canada et les \u00c9tats-Unis ont tous d\u00e9cid\u00e9                     de se rallier au syst\u00e8me m\u00e9trique am\u00e9lior\u00e9                     appel\u00e9 syst\u00e8me international d&rsquo;unit\u00e9s                     (SI). Cette d\u00e9cision a \u00e9t\u00e9 motiv\u00e9e                     avant tout par le souci de ces pays de s&rsquo;aligner sur la presque                     totalit\u00e9 du monde en mati\u00e8re de commerce et                     de technique. Le SI comprend non seulement les unit\u00e9s                     de masse et de longueur, mais aussi l&rsquo;unit\u00e9 de temps                     (seconde), l&rsquo;unit\u00e9 de courant \u00e9lectrique (amp\u00e8re),                     l&rsquo;unit\u00e9 de temp\u00e9rature (degr\u00e9 Kelvin)                     et celle de l&rsquo;intensit\u00e9 lumineuse (candela). Les unit\u00e9s                     de temps, de courant \u00e9lectrique et d&rsquo;intensit\u00e9                     lumineuse sont usit\u00e9es au Canada depuis de nombreuses                     ann\u00e9es, et les Canadiens apprennent maintenant \u00e0                     penser en degr\u00e9s Celsius, en kilom\u00e8tres, en                     tonnes et en litres. Gr\u00e2ce \u00e0 l&#8217;emploi quotidien                     d&rsquo;une monnaie d\u00e9cimalis\u00e9e, ils ont d\u00e9j\u00e0                     l&rsquo;habitude des calculs propres au syst\u00e8me m\u00e9trique.                     D&rsquo;ailleurs, ce syst\u00e8me fait partie depuis longtemps                     de la langue scientifique au Canada. Les Canadiens consid\u00e8rent                     comme admis l&#8217;emploi des mesures m\u00e9triques dans le                     cas des m\u00e9dicaments, des vitamines et des films. <\/p>\n<p> L&rsquo;adh\u00e9sion de l&rsquo;Am\u00e9rique du Nord et de la                     Grande-Bretagne au syst\u00e8me international offre un exemple                     de normalisation \u00e0 l&rsquo;\u00e9chelle la plus vaste,                     comparable \u00e0 l&rsquo;application universelle du temps l\u00e9gal                     con\u00e7u par le grand ing\u00e9nieur canadien Sir Sandford                     Fleming (voir <em>Bulletin <\/em>d&rsquo;ao\u00fbt 1978). L&rsquo;adoption                     d&rsquo;une s\u00e9rie unique de mesures dans toutes les parties                     de notre monde diversifi\u00e9 repr\u00e9sente \u00e0                     coup s\u00fbr un progr\u00e8s des plus importants de l&rsquo;histoire                     de l&rsquo;humanit\u00e9. Mais le mesurage n&rsquo;est qu&rsquo;une des nombreuses                     activit\u00e9s qui ob\u00e9issent aux normes. Dans la                     soci\u00e9t\u00e9 complexe de notre temps, les normes                     jouent un r\u00f4le aussi capital dans d&rsquo;autres domaines.                   <\/p>\n<p> En fait, si l&rsquo;on demande aux Canadiens d&rsquo;aujourd&rsquo;hui ce                     que c&rsquo;est qu&rsquo;une norme, la plupart penseront sans doute d&rsquo;abord                     non pas aux normes de mesure, mais aux normes de s\u00e9curit\u00e9.                     Beaucoup de ces derni\u00e8res sont prescrites par la loi\u00a0:                     r\u00e8glements concernant les aliments et les produits                     pharmaceutiques\u00a0; codes de protection incendie et de                     la construction\u00a0; moyens de lutte contre la pollution,                     etc. Mais un plus grand nombre de normes encore sont \u00e9tablies                     volontairement par les repr\u00e9sentants de l&rsquo;industrie                     et des m\u00e9tiers qui font partie des quelque 600 comit\u00e9s                     d&rsquo;\u00e9laboration des normes de l&rsquo;Association canadienne                     de normalisation. Cet organisme, qui tient de fr\u00e9quentes                     r\u00e9unions pour forger des normes applicables \u00e0                     une vaste gamme de produits, est commun\u00e9ment d\u00e9sign\u00e9e                     par le sigle \u00ab\u00a0ACNOR\u00a0\u00bb. <\/p>\n<p> Ce monogramme peut aussi bien se retrouver sur une maison                     mobile que sur une brosse \u00e0 dents \u00e9lectrique.                     Partout o\u00f9 il figure, il signifie que le produit qui                     en est rev\u00eatu s&rsquo;est r\u00e9v\u00e9l\u00e9 conforme                     \u00e0 des normes que des sp\u00e9cialistes ont mis six                     mois en moyenne \u00e0 \u00e9laborer. Chaque produit approuv\u00e9                     par l&rsquo;ACNOR a fait l&rsquo;objet de contr\u00f4les rigoureux. Les                     laboratoires de l&rsquo;association proc\u00e8dent dans chaque                     cas \u00e0 des \u00e9preuves tr\u00e8s s\u00e9v\u00e8res,                     au cours desquelles un cordon d&rsquo;appareil \u00e9lectrique,                     par exemple, pourra subir jusqu&rsquo;\u00e0 10,000 torsions.                   <\/p>\n<p> L&rsquo;ACNOR est le plus consid\u00e9rable des organismes canadiens                     qui se consacrent \u00e0 l&rsquo;\u00e9laboration de normes                     nouvelles et am\u00e9lior\u00e9es. Les principaux autres                     sont le Bureau de normalisation du Qu\u00e9bec, l&rsquo;Association                     canadienne du gaz, l&rsquo;Office des normes du gouvernement canadien                     et les <em>Underwriters&rsquo; Laboratories of Canada<\/em>. La t\u00e2che                     de coordonner et de favoriser les activit\u00e9s de ces                     divers organismes incombe au Conseil canadien des normes.                     Cette institution autonome du gouvernement f\u00e9d\u00e9ral                     a aussi pour fonction d&rsquo;assurer la repr\u00e9sentation du                     Canada sur le plan international et d&rsquo;encourager la normalisation                     dans l&rsquo;industrie canadienne. <\/p>\n<p> Un bref exemple suffira \u00e0 montrer comment fonctionne                     la normalisation industrielle\u00a0: un producteur d&rsquo;appareils                     \u00e9lectroniques employait autrefois plusieurs types diff\u00e9rents                     de transitors dans les produits qu&rsquo;il fabriquait\u00a0; le                     choix d&rsquo;un seul type lui permit d&rsquo;en commander en plus grande                     quantit\u00e9 \u00e0 meilleur prix et d&rsquo;acc\u00e9l\u00e9rer                     le rythme de sa production. <\/p>\n<p> Les normalisations de ce genre, affirme le Conseil des normes,                     conduisent les compagnies \u00e0 accro\u00eetre leur productivit\u00e9,                     \u00e0 \u00e9largir leurs march\u00e9s (internationaux                     surtout), \u00e0 consacrer plus de temps \u00e0 l&rsquo;innovation                     et \u00e0 offrir des produits moins chers au consommateur.                     C&rsquo;est l\u00e0 un objectif national de premi\u00e8re importance                     \u00e0 poursuivre. <\/p>\n<p> Mais la normalisation n&rsquo;est pas sans avoir ses d\u00e9tracteurs,                     au Canada et ailleurs. Pour beaucoup, elle comporte un degr\u00e9                     d&rsquo;uniformit\u00e9 qui d\u00e9tonne avec la tendance naturelle                     de l&rsquo;homme \u00e0 affirmer sa personnalit\u00e9. Il y                     a toujours danger qu&rsquo;en d\u00e9passant le stade des boulons                     et des \u00e9crous, elle diminue l&rsquo;\u00e9ventail de choix                     du consommateur et entrave la r\u00e9alisation de produits                     plus parfaits ou plus attrayants. Henry Ford fut l&rsquo;un des                     champions de la normalisation technique, mais il alla un peu                     loin le jour o\u00f9 il affirma, dit-on, que l&rsquo;on pouvait                     choisir une Ford de n&rsquo;importe quelle couleur \u00e0 condition                     qu&rsquo;elle soit noire. <\/p>\n<p> \u00c0 sa place, cependant, la normalisation est un facteur                     de commodit\u00e9 et d&rsquo;\u00e9conomie sans uniformit\u00e9.                     Les chaussures en offrent la preuve\u00a0: les pointures en                     sont normalis\u00e9es, mais on en trouve de tous les genres                     et de toutes les teintes. Les bi\u00e8res canadiennes ne                     manquent pas de vari\u00e9t\u00e9 du fait qu&rsquo;elles sont                     toutes pr\u00e9sent\u00e9es dans des bouteilles identiques                     et interchangeables. L&rsquo;exp\u00e9dition des marchandises                     dans des conteneurs de dimensions normalis\u00e9es, pouvant                     \u00eatre charg\u00e9s aussi bien par les navires et les                     trains que par les avions et les camions, ne peut que contribuer                     \u00e0 abaisser les prix \u00e0 la consommation. <\/p>\n<p> La normalisation est souhaitable tant qu&rsquo;il reste entendu                     que l&rsquo;on ne saurait normaliser les hommes. On peut les persuader                     de se plier \u00e0 certaines normes, mais ils doivent continuer                     de penser et d&rsquo;agir chacun \u00e0 sa mani\u00e8re personnelle.                     Les normes ont un r\u00f4le tr\u00e8s important \u00e0                     jouer dans les affaires humaines en tant que crit\u00e8res                     \u00e0 observer\u00a0: normes de biens\u00e9ance, normes                     d&rsquo;excellence, etc. Mais, comme celles de l&rsquo;industrie, ces                     normes ne sont vraiment efficaces que si elles sont accept\u00e9es                     et reconnues n\u00e9cessaires par les int\u00e9ress\u00e9s.                   <\/p>\n<p>\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"author":87,"featured_media":0,"template":"","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":""},"categories":[1],"rbc_letter_theme":[],"rbc_letter_year":[59],"class_list":["post-2116","rbc_letter","type-rbc_letter","status-publish","hentry","category-uncategorized","rbc_letter_year-59"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L&#039;\u00e9volution des normes - RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L&#039;\u00e9volution des normes\" \/>\n<meta property=\"og:description\" content=\"Proc\u00e9d\u00e9 d&rsquo;origine fort ancienne, la normalisation conna\u00eet un essor nouveau depuis que l&rsquo;Am\u00e9rique du Nord a d\u00e9cid\u00e9 de se rallier au syst\u00e8me m\u00e9trique. Voici un bref coup d&rsquo;oeil sur le d\u00e9veloppement des normes et leur n\u00e9cessit\u00e9, y compris celles que nous nous imposons&#8230; Chaque jour, \u00e0 chaque instant, nous vivons au milieu des normes. Le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T20:22:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/vol-61-n-2-fevrier-1980-levolution-des-normes\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/vol-61-n-2-fevrier-1980-levolution-des-normes\\\/\",\"name\":\"Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L'\u00e9volution des normes - RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\"},\"datePublished\":\"1980-02-01T00:00:00+00:00\",\"dateModified\":\"2022-10-17T20:22:54+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/vol-61-n-2-fevrier-1980-levolution-des-normes\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/\",\"name\":\"RBC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L'\u00e9volution des normes - RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","og_locale":"fr_FR","og_type":"article","og_title":"Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L'\u00e9volution des normes","og_description":"Proc\u00e9d\u00e9 d&rsquo;origine fort ancienne, la normalisation conna\u00eet un essor nouveau depuis que l&rsquo;Am\u00e9rique du Nord a d\u00e9cid\u00e9 de se rallier au syst\u00e8me m\u00e9trique. Voici un bref coup d&rsquo;oeil sur le d\u00e9veloppement des normes et leur n\u00e9cessit\u00e9, y compris celles que nous nous imposons&#8230; Chaque jour, \u00e0 chaque instant, nous vivons au milieu des normes. Le [&hellip;]","og_url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","og_site_name":"RBC","article_modified_time":"2022-10-17T20:22:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","name":"Vol. 61, N\u00b0 2 - F\u00e9vrier 1980 - L'\u00e9volution des normes - RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/#website"},"datePublished":"1980-02-01T00:00:00+00:00","dateModified":"2022-10-17T20:22:54+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/#website","url":"https:\/\/www.rbc.com\/fr\/","name":"RBC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Vol. 61, N\u00b0 2 &#8211; F\u00e9vrier 1980 &#8211; L&rsquo;\u00e9volution des normes","url":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/vol-61-n-2-fevrier-1980-levolution-des-normes\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[],"creator":[],"publisher":{"@type":"Organization","name":"RBC","logo":""},"keywords":[],"dateCreated":"1980-02-01T00:00:00Z","datePublished":"1980-02-01T00:00:00Z","dateModified":"2022-10-17T20:22:54Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Vol. 61, N\\u00b0 2 &#8211; F\\u00e9vrier 1980 &#8211; L&rsquo;\\u00e9volution des normes\",\"url\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/vol-61-n-2-fevrier-1980-levolution-des-normes\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/vol-61-n-2-fevrier-1980-levolution-des-normes\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"1980-02-01T00:00:00Z\",\"datePublished\":\"1980-02-01T00:00:00Z\",\"dateModified\":\"2022-10-17T20:22:54Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbc.com\/p.js"},"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbc.com\/fr\/author\/","display_name":""},"relative_dates":{"created":"Publi\u00e9 46 ans il y a","modified":"Mis \u00e0 jour 4 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 1 f\u00e9vrier 1980","modified":"Mise \u00e0 jour le 17 octobre 2022"},"absolute_dates_time":{"created":"Publi\u00e9 le 1 f\u00e9vrier 1980 12:00  ","modified":"Mise \u00e0 jour le 17 octobre 2022 8:22  "},"featured_img_caption":"","tax_additional":{"category":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/category\/uncategorized\/\" class=\"advgb-post-tax-term\">Uncategorized<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Uncategorized<\/span>"],"slug":"category","name":"Cat\u00e9gories"},"rbc_letter_theme":{"linked":[],"unlinked":[],"slug":"rbc_letter_theme","name":"Themes"},"rbc_letter_year":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/year\/1980\/\" class=\"advgb-post-tax-term\">1980<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1980<\/span>"],"slug":"rbc_letter_year","name":"Years"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/types\/rbc_letter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/users\/87"}],"version-history":[{"count":0,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2116\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media?parent=2116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/categories?post=2116"},{"taxonomy":"rbc_letter_theme","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_theme?post=2116"},{"taxonomy":"rbc_letter_year","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_year?post=2116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}