{"id":2079,"date":"1998-12-01T00:00:00","date_gmt":"1998-12-01T00:00:00","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/"},"modified":"2022-10-17T16:10:41","modified_gmt":"2022-10-17T16:10:41","slug":"decembre-1998-la-maison-du-bonheur","status":"publish","type":"rbc_letter","link":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","title":{"rendered":"D\u00e9cembre 1998 &#8211; La maison du bonheur"},"content":{"rendered":"<div id=\"layout-column-main\">\n<p class=\"boldtext\">Quand la maison n&rsquo;a pas ou n&rsquo;a plus les vertus du chez- soi dont on r\u00eave, la tentation est forte d&rsquo;en claquer la porte. Ceux qui restent fid\u00e8les \u00e0 cet id\u00e9al rendent pourtant un immense service \u00e0 la soci\u00e9t\u00e9, \u00e0 leurs proches&#8230; et \u00e0 eux-m\u00eames.<\/p>\n<p>\u00ab\u00a0Maison\u00a0\u00bb\u00a0: mot doux et flou, plus flou que doux \u00e0 bien y penser. Son sens premier confine \u00e0 l&rsquo;\u00e9vidence\u00a0: la maison, c&rsquo;est l&rsquo;endroit o\u00f9 on vit, non\u00a0? Non, r\u00e9torquerait Polly Adler, demi-mondaine am\u00e9ricaine dont les m\u00e9moires prouvent, l\u00e0 encore \u00e0 l&rsquo;\u00e9vidence, que le toit ne fait pas la maison. A contrario, \u00ab\u00a0chez nous\u00a0\u00bb\u00a0peut d\u00e9signer un quartier, une ville, une r\u00e9gion ou un pays aussi bien que les quatre murs d&rsquo;une maison. Tout d\u00e9pend du point de vue.<\/p>\n<p>Comble d&rsquo;ambigu\u00eft\u00e9, \u00ab\u00a0maison\u00a0\u00bb\u00a0a donn\u00e9 naissance \u00e0 une foule d&rsquo;expressions qui n&rsquo;\u00e9voquent rien moins que la douceur du logis\u00a0: maison de sant\u00e9, de convalescence, d&rsquo;arr\u00eat, de fous, de passe&#8230; Les prestidigitateurs immobiliers qui transforment les cages \u00e0 lapins d&rsquo;une tour de b\u00e9ton en maisons de r\u00eave exploitent fort habilement cette versatilit\u00e9 s\u00e9mantique &#8211; sans se douter qu&rsquo;ils disent ainsi, bien involontairement, la plus stricte v\u00e9rit\u00e9. Ce qui loge dans leurs mornes constructions, c&rsquo;est bien un r\u00eave\u00a0: celui que nourrit l&rsquo;acheteur d&rsquo;en faire une maison dans le sens riche du terme.<\/p>\n<p>R\u00e9aliser ce r\u00eave demande beaucoup de temps, mais pas forc\u00e9ment beaucoup d&rsquo;argent. Plus d&rsquo;un multimillionnaire a appris \u00e0 ses d\u00e9pens que les liasses de billets ne font pas de bonnes fondations.<\/p>\n<p>C&rsquo;est, semble-t-il, Pline le Jeune qui aurait invent\u00e9 le dicton \u00ab\u00a0 l\u00e0 o\u00f9 est mon coeur, l\u00e0 est ma maison\u00a0\u00bb, un si\u00e8cle avant notre \u00e8re. Tous ceux qui r\u00eavent encore d&rsquo;une demeure quitt\u00e9e depuis des lustres savent parfaitement ce qu&rsquo;il voulait dire. Paradoxalement, la phrase s&rsquo;applique avec un \u00e9gal bonheur aux familles migratrices qui, comme la tortue, tra\u00eenent leur maison avec elles dans notre soci\u00e9t\u00e9 en mouvement perp\u00e9tuel\u00a0!<\/p>\n<p>On aurait tort de faire de cette \u00ab\u00a0maison du coeur\u00a0\u00bb\u00a0le privil\u00e8ge exclusif de la famille standard de deux enfants et demi. Quantit\u00e9 de solitaires coulent des jours tr\u00e8s heureux avec un ou deux animaux de compagnie. Quelle famille nord-am\u00e9ricaine n&rsquo;a pas sa tante farouchement attach\u00e9e \u00e0 sa tranquillit\u00e9, son oncle c\u00e9libataire rompu aux corv\u00e9es m\u00e9nag\u00e8res\u00a0? Et puis, il y a les cas extr\u00eames comme ces repris de justice qui, une fois leur peine purg\u00e9e, s&#8217;empressent de se faire pincer la main dans le sac pour retourner derri\u00e8re les barreaux, seul endroit o\u00f9 ils se sentent chez eux.<\/p>\n<p>Le brouillard s\u00e9mantique qui enveloppe la maison ne fait que s&rsquo;\u00e9paissir depuis que la jeunesse d&rsquo;Am\u00e9rique et d&rsquo;Europe s&rsquo;est lanc\u00e9e \u00e0 l&rsquo;assaut des valeurs traditionnelles, au d\u00e9but des ann\u00e9es 1960.<\/p>\n<p>La \u00ab\u00a0maison\u00a0\u00bb\u00a0de l&rsquo;\u00e9poque &#8211; coquette r\u00e9sidence de banlieue avec garage attenant et pelouse manucur\u00e9e &#8211; est une cible naturelle pour celles et ceux qui pr\u00f4nent le renversement de l&rsquo;ordre mat\u00e9rialiste occidental. Dans les communes qui poussent alors comme des champignons se d\u00e9veloppe un mode de vie compl\u00e8tement oppos\u00e9 \u00e0 cette morale suburbaine ancr\u00e9e dans la monogamie et l&rsquo;argent.<\/p>\n<p>Le temps a lim\u00e9 les asp\u00e9rit\u00e9s de langage et de comportement des rebelles. Beaucoup ont fini par avaliser le conformisme bourgeois qu&rsquo;ils vitup\u00e9raient nagu\u00e8re. Leur r\u00e9volte n&rsquo;en a pas moins fait \u00e9clater le cadre ancien de la vie priv\u00e9e. S\u00e9parations et divorces gonflent sans arr\u00eat les rangs des personnes seules et des familles monoparentales. Les couples non mari\u00e9s ne sont plus ostracis\u00e9s, m\u00eame quand leurs membres sont du m\u00eame sexe.<\/p>\n<p>Les difficult\u00e9s \u00e9conomiques poussent les jeunes \u00e0 cohabiter ou \u00e0 vivre chez papa et maman, parfois jusqu&rsquo;\u00e0 30 ans pass\u00e9s, en attendant l&#8217;emploi stable qui leur permettra de voler de leurs propres ailes. Les handicap\u00e9s fondent des foyers communautaires, les personnes \u00e2g\u00e9es pr\u00e9servent une mesure d&rsquo;ind\u00e9pendance dans une maison de retraite. Pour tous ces gens-l\u00e0, \u00ab\u00a0maison\u00a0\u00bb\u00a0n&rsquo;a \u00e9videmment pas le m\u00eame sens que pour leurs parents.<\/p>\n<table border=\"0\" width=\"415\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<div class=\"quote\">\u00ab\u00a0Synonyme de confort et vertu, la maison est un cercle mystique inconnu au-del\u00e0 de ses fronti\u00e8res sacr\u00e9es.\u00a0\u00bb <span class=\"boldtext\">Robert Southey<\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>En a-t-il encore un pour ces l\u00e9gions d&rsquo;adultes que les rigueurs \u00e9conomiques ont jet\u00e9 sur le pav\u00e9, pour ces bandes d&rsquo;enfants en fugue qui errent dans les rues\u00a0? Que certains de ces sans-domicile- fixe ne maudissent pas leur sort n&rsquo;enl\u00e8ve rien \u00e0 sa cruaut\u00e9. Au del\u00e0 de la mis\u00e8re mat\u00e9rielle qu&rsquo;il induit, il les prive en effet d&rsquo;un privil\u00e8ge fondamental\u00a0: celui d&rsquo;avoir un chez-soi.<\/p>\n<p>Les enfants des rues sont doublement d\u00e9favoris\u00e9s, car la rupture avec leurs parents les spolie non seulement de la r\u00e9alit\u00e9 d&rsquo;un chez- soi, mais aussi de sa m\u00e9moire. Dans nos soci\u00e9t\u00e9s flottantes, la plupart des gens tiennent au moins autant au souvenir de la maison de leur enfance qu&rsquo;au confort de celle qu&rsquo;ils habitent.<\/p>\n<h3>La maternit\u00e9, un concept modifi\u00e9<\/h3>\n<p>Il n&rsquo;y a qu&rsquo;un mot pour d\u00e9crire l&rsquo;attachement dont t\u00e9moignent les innombrables po\u00e8mes et chansons sur cette maison des origines\u00a0: sentimental. Un mot qui a mauvaise presse parce qu&rsquo;il exprime la pr\u00e9\u00e9minence du coeur sur la raison. Pourtant, ces hommages na\u00effs, souvent compos\u00e9s par des soldats que la guerre avait arrach\u00e9s \u00e0 leur petite patrie, sont profond\u00e9ment touchants. \u00c0 cause des associations d&rsquo;id\u00e9es qu&rsquo;ils suscitent. Quiconque a eu la chance de grandir au sein d&rsquo;une famille unie ne peut pas rester indiff\u00e9rent \u00e0 l&rsquo;\u00e9vocation de cette image-l\u00e0.<\/p>\n<p>Un seul sujet a suscit\u00e9 plus d&rsquo;inspiration lyrique que la maison familiale dans l&rsquo;histoire humaine, et c&rsquo;est le th\u00e8me qui lui est le plus \u00e9troitement associ\u00e9\u00a0: la m\u00e8re. La maison familiale exprimait l&rsquo;amour maternel au travers de mille et un d\u00e9tails\u00a0: les rideaux de dentelle aux fen\u00eatres, les plantes vertes, les bibelots, l&rsquo;odeur exquise des biscuits qui sortent du four. Certes, la maman moderne n&rsquo;aime pas moins ses enfants que ses a\u00efeules, mais elle doit d\u00e9sormais mener de front deux m\u00e9tiers exigeants.<\/p>\n<p>De la femme mari\u00e9e, on attendait jadis qu&rsquo;elle prenne en charge tous les travaux de la maison. Les m\u00e8res qui rentrent soucieuses et fatigu\u00e9es d&rsquo;une pleine journ\u00e9e de travail salari\u00e9 seraient bien en peine de relever seules pareil d\u00e9fi. Tenir maison, \u00e9lever les enfants, c&rsquo;est aussi l&rsquo;affaire des hommes \u00e0 pr\u00e9sent. Et comme la complexit\u00e9 de notre \u00e9poque ne permet plus de s&rsquo;en remettre \u00e0 la chance, les deux parents doivent s&rsquo;appliquer \u00e0 b\u00e2tir la maison symbolique qu&rsquo;ils l\u00e9gueront \u00e0 leurs enfants, consolidant par la sagesse, la patience et la tol\u00e9rance ses fondations de fermet\u00e9, de tendresse et d&rsquo;\u00e9quit\u00e9.<\/p>\n<h3>La maison, source de bonheur<\/h3>\n<p>Il n&rsquo;a jamais \u00e9t\u00e9, il ne sera jamais facile de b\u00e2tir une vraie maison, mais l&rsquo;abandon de toute pratique religieuse d\u00e9cuple la difficult\u00e9 de l&rsquo;entreprise. Source de discipline pour les enfants, et d&rsquo;ailleurs pour leurs parents, m\u00eame quand elle se r\u00e9duisait au rite, la religion a \u00e9t\u00e9 le ciment de la famille \u00e0 toutes les autres \u00e9poques et le reste partout ailleurs qu&rsquo;en Occident. En l&rsquo;\u00e9vin\u00e7ant de la vie quotidienne, le grand mouvement de lib\u00e9ration qui a balay\u00e9 notre soci\u00e9t\u00e9 a consid\u00e9rablement affaibli l&rsquo;autorit\u00e9 des parents sur leurs enfants, notamment adolescents. \u00ab\u00a0Le pr\u00e9cepte de ce vieux monsieur \u00e9tait que ses enfants devaient se sentir plus heureux \u00e0 la maison que n&rsquo;importe o\u00f9 ailleurs; je tiens ce doux sentiment pour l&rsquo;un des plus beaux cadeaux qu&rsquo;un p\u00e8re ou une m\u00e8re puisse faire.\u00a0\u00bb\u00a0Washington Irving, auteur am\u00e9ricain du XIXe si\u00e8cle, exprime l\u00e0 ce que tous les parents responsables pressentent d&rsquo;instinct\u00a0: la meilleure fa\u00e7on de prot\u00e9ger un enfant des dangers qui le guettent, c&rsquo;est encore de faire en sorte qu&rsquo;il ait envie de passer beaucoup de temps \u00e0 la maison.<\/p>\n<p align=\"center\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dec1998_1.gif\" alt=\"image\" hspace=\"5\" vspace=\"5\" \/><\/p>\n<p>C&rsquo;est plus vite dit que fait, certes, mais si l&rsquo;atmosph\u00e8re est sereine chez vous, vos enfants seront probablement tent\u00e9s d&rsquo;inviter leurs copains \u00e0 la maison au lieu d&rsquo;aller les retrouver \u00e0 l&rsquo;ext\u00e9rieur. Et la partie sera gagn\u00e9e\u00a0: Pascal n&rsquo;a-t-il pas observ\u00e9 que la plupart des maux tiennent \u00e0 ce que l&rsquo;homme ne supporte pas de rester dans sa chambre\u00a0?<\/p>\n<h3>La maison, refuge supr\u00eame dans un monde froid<\/h3>\n<p>Le plus beau, c&rsquo;est que cet effort de s\u00e9duction vous profitera tout autant qu&rsquo;\u00e0 eux\u00a0: les adultes n&rsquo;appr\u00e9cient pas moins la paix et la tranquillit\u00e9 que les jeunes, apr\u00e8s tout. Cette qu\u00eate domestique vous apportera en outre de grandes satisfactions personnelles, car elle stimulera votre instinct cr\u00e9ateur. Dans son am\u00e9nagement, son d\u00e9sordre, m\u00eame, une maison refl\u00e8te les go\u00fbts et les talents de ses habitants. H\u00f4tel particulier ou gar\u00e7onni\u00e8re, elle est l&rsquo;incarnation d&rsquo;une personnalit\u00e9. \u00abRegardez, semble-t-elle dire, voil\u00e0 ce que je suis vraiment.\u00a0\u00bb<\/p>\n<p>Pour le psychologue, la maison est le lieu privil\u00e9gi\u00e9 de la socialisation, tant il est vrai que la qualit\u00e9 de nos rapports avec les autres d\u00e9pend des exp\u00e9riences de notre petite enfance. C&rsquo;est \u00e0 la maison que nous prenons conscience des sentiments et int\u00e9r\u00eats d&rsquo;autrui, que nous nous initions, par le biais des corv\u00e9es, aux responsabilit\u00e9s inh\u00e9rentes \u00e0 l&rsquo;interd\u00e9pendance. C&rsquo;est \u00e0 la maison que nous apprenons \u00e0 nous conduire en \u00eatres civilis\u00e9s, \u00e0 r\u00e9gler les conflits sans violence, \u00e0 mesurer nos faiblesses, \u00e0 pr\u00e9senter des excuses.<\/p>\n<p>Ce qui nous attache le plus \u00e0 la maison de notre enfance, c&rsquo;est sans doute la chaleur qu&rsquo;elle nous procure aux heures les plus sombres. Les tout-petits savent d&rsquo;instinct que c&rsquo;est l\u00e0 qu&rsquo;il trouveront le rem\u00e8de magique contre leurs \u00e9gratignures et blessures d&rsquo;amour-propre. Nous ne perdons jamais ce r\u00e9flexe primitif. \u00ab\u00a0La maison, note Robert Frost dans un superbe \u00e9clair de lucidit\u00e9, c&rsquo;est la porte qu&rsquo;on doit vous ouvrir quand vous devez y frapper.\u00a0\u00bb\u00a0 Combien d&rsquo;adultes viennent demander l&rsquo;asile \u00e0 leurs parents lorsque la vie leur inflige un revers\u00a0?<\/p>\n<table border=\"0\" width=\"415\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<div class=\"quote\">\u00ab\u00a0La meilleure fa\u00e7on d&rsquo;assurer qu&rsquo;un enfant soit bon, c&rsquo;est de le rendre heureux.\u00a0\u00bb <span class=\"boldtext\">Oscar Wilde <\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>La maison prot\u00e8ge les siens de mille et une mani\u00e8res qui, pour insignifiantes qu&rsquo;elles paraissent, n&rsquo;en sont pas moins d\u00e9licieusement r\u00e9confortantes. C&rsquo;est l\u00e0 qu&rsquo;on dorlote ses malaises, qu&rsquo;on baigne son corps fatigu\u00e9, qu&rsquo;on oublie ses soucis entre les pages d&rsquo;un bon livre. On y est libre de tomber la veste, de faire le pitre, de cultiver ses petites manies, d&rsquo;idol\u00e2trer son chien. Elle abrite nos passions et nos traditions, nos pr\u00e9f\u00e9rences culinaires, nos f\u00eates rituelles, nos codes secrets.<\/p>\n<h3>La maison, parfois un monde infernal<\/h3>\n<p><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dec1998_2.gif\" alt=\"image\" align=\"right\" hspace=\"5\" vspace=\"5\" \/><\/p>\n<p>On rit beaucoup et souvent dans une maison comme celle-l\u00e0. Souvent, mais pas toujours. Car elle est aussi le refuge supr\u00eame apr\u00e8s une d\u00e9ception, un chagrin, un drame, un deuil. On y revient apr\u00e8s les fun\u00e9railles d&rsquo;un \u00eatre cher pour trouver consolation aupr\u00e8s de sa famille, de ses amis, de ses voisins. Lesquels, on l&rsquo;oublie trop, font partie int\u00e9grante de la maisonn\u00e9e aux moments forts de sa vie, les plus beaux comme les plus tristes.<\/p>\n<p>Cette maison qui r\u00e9conforte et qui r\u00e9jouit, c&rsquo;est bien s\u00fbr l&rsquo;id\u00e9al. La r\u00e9alit\u00e9, nous le savons tous, n&rsquo;est jamais paradisiaque. Mais elle peut \u00eatre infernale si les membres de la maisonn\u00e9e ne s&rsquo;entendent pas entre eux.<\/p>\n<p>Ceux qui vivent dans une maison d\u00e9chir\u00e9e par les conflits, rong\u00e9e par les rancoeurs, empoisonn\u00e9e par l&rsquo;amertume ne sont gu\u00e8re plus favoris\u00e9s que les sans-logis. Qui envierait la jeune fille \u00e0 qui la po\u00e9tesse Louise Cass fait dire\u00a0: \u00ab\u00a0Et voil\u00e0 de quelle fa\u00e7on\/nous commen\u00e7ons la journ\u00e9e\/dans cet enfer qu&rsquo;on appelle maison\u00a0\u00bb\u00a0?<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dec1998_3.gif\" alt=\"image\" align=\"left\" hspace=\"5\" vspace=\"5\" \/><\/p>\n<p>Le cin\u00e9ma et la t\u00e9l\u00e9vision nous ont longtemps donn\u00e9 l&rsquo;impression que le bonheur faisait partie des meubles dans toutes les familles. Les \u00e9missions t\u00e9l\u00e9 sont plus proches de la r\u00e9alit\u00e9 \u00e0 pr\u00e9sent qu&rsquo;\u00e0 l&rsquo;\u00e9poque du noir et blanc. Il arrive que des tensions affleurent au sein des familles cathodiques, mais on reste tr\u00e8s loin des cris et des g\u00e9missements qui ponctuent les querelles domestiques. Pendant que l&rsquo;industrie du divertissement nous abreuve de sirop sur les joies de la vie de famille, les \u00e9missions d&rsquo;information d\u00e9crivent des maisons hant\u00e9es par une violence domestique qui broie les enfants, rel\u00e8vent des taux de suicide effroyables chez les adolescents, constatent que les familles bris\u00e9es ne sont plus l&rsquo;exception mais la r\u00e8gle, ou presque.<\/p>\n<table border=\"0\" width=\"415\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<tr>\n<td valign=\"top\">\n<div class=\"quote\">\u00ab\u00a0Chacun a l&rsquo;ambition l\u00e9gitime de cr\u00e9er un climat familial heureux.\u00a0\u00bb <span class=\"boldtext\">Samuel Johnson<\/span><\/div>\n<\/td>\n<\/tr>\n<tr>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" width=\"415\" height=\"1\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>On le voit, la maison n&rsquo;est pas le petit paradis priv\u00e9 que sugg\u00e8rent les apparences. Le constat est assez paradoxal quand on songe au confort mat\u00e9riel in\u00e9gal\u00e9 dont jouissent les m\u00e9nages occidentaux. Ces ados qui disposent de tous les moyens invent\u00e9s par la technologie pour se distraire chez soi &#8211; t\u00e9l\u00e9vision par c\u00e2ble et satellite, vid\u00e9ocassettes, disques compacts, Internet, etc. &#8211; devraient \u00eatre plus port\u00e9s \u00e0 rester \u00e0 la maison que leurs a\u00een\u00e9s. Or, un grand nombre d&rsquo;entre eux semblent au contraire si las de la vie de famille qu&rsquo;ils sont pr\u00eats \u00e0 courir tous les risques, au premier chef celui de la drogue, pour trouver rem\u00e8de \u00e0 leur ennui.<\/p>\n<h3>Savoir pardonner et oublier<\/h3>\n<p>\u00ab\u00a0Un grand obstacle au bonheur, c&rsquo;est de s&rsquo;attendre \u00e0 trop de bonheur.\u00a0\u00bb\u00a0L&rsquo;avertissement de Fontenelle para\u00eet fait pour notre \u00e9poque. Si tant de gens c\u00e8dent \u00e0 la premi\u00e8re tentation de rupture ou de fuite, c&rsquo;est probablement parce qu&rsquo;ils attendent trop de la vie de famille.<\/p>\n<p>Et cela nous ram\u00e8ne \u00e0 la place pr\u00e9pond\u00e9rante de la t\u00e9l\u00e9vision dans l&rsquo;univers domestique contemporain. Happ\u00e9 par le flot de bonheur facile qui ruisselle du petit \u00e9cran, le t\u00e9l\u00e9spectateur d\u00e9rive en esprit vers un monde bien trop beau pour \u00eatre vrai, en regard duquel la r\u00e9alit\u00e9 devient forc\u00e9ment repoussante.<\/p>\n<p>Les probl\u00e8mes domestiques ne sont pas diff\u00e9rents des autres. On ne les r\u00e9sout pas en les fuyant, mais en les prenant \u00e0 bras le corps et en cherchant une solution, quitte \u00e0 \u00e9corner son amour-propre. Les familles unies savent pardonner et oublier.<\/p>\n<p>Pour conjurer la menace d&rsquo;explosion, il faut parfois se r\u00e9soudre \u00e0 faire passer la famille avant le travail, si pr\u00e9cieux que soit son apport aux finances domestiques. On ne le dira jamais assez\u00a0: l&rsquo;argent ne fait pas le bonheur. La vie de ch\u00e2teau ne peut pas compenser les sacrifices et les compromissions qu&rsquo;une famille doit s&rsquo;imposer pour en arriver l\u00e0.<\/p>\n<h3>Comme dans les films<\/h3>\n<p>Du pied au sommet de la pyramide sociale, la cl\u00e9 du bonheur domestique r\u00e9side dans l&rsquo;aptitude de chaque membre de la famille \u00e0 c\u00e9der lorsque le bien commun l&rsquo;exige. Les enjeux de ces n\u00e9gociations permanentes d\u00e9passent largement le domaine priv\u00e9. La stabilit\u00e9 de cette pyramide d\u00e9pend de la solidit\u00e9 de ses assises. Or, comme le disait le conf\u00e9rencier Joseph Cook, c&rsquo;est la famille qui fonde l&rsquo;\u00c9tat.<\/p>\n<p>La plupart des criminels grandissent dans des familles dysfonctionnelles, et beaucoup de probl\u00e8mes sociaux s&rsquo;enracinent dans les difficult\u00e9s de la vie familiale. On ne risque gu\u00e8re de se tromper en affirmant que tout effort contribuant \u00e0 garantir la paix et l&rsquo;ordre domestiques tend \u00e0 pr\u00e9server la paix et l&rsquo;ordre dans la soci\u00e9t\u00e9.<\/p>\n<p>Reste que l&rsquo;\u00eatre humain agit d&rsquo;abord dans son propre int\u00e9r\u00eat, ou ce qu&rsquo;il croit \u00eatre son int\u00e9r\u00eat. Cr\u00e9er et entretenir un climat familial sain rel\u00e8ve de la motivation personnelle, non de la volont\u00e9 publique.<\/p>\n<p>Remercions donc la providence d&rsquo;avoir pr\u00e9vu une r\u00e9compense \u00e0 la mesure de l&rsquo;effort puisque le bonheur, objet de notre qu\u00eate existentielle, trouve son incarnation la plus durable dans sa forme domestique. Pour jouir de ce tr\u00e9sor sans prix, il nous faut simplement accepter qu&rsquo;il ne na\u00eet jamais par g\u00e9n\u00e9ration spontan\u00e9e. Le bonheur gratuit n&rsquo;existe qu&rsquo;au cin\u00e9ma. Dans la vraie vie, il est chez lui seulement l\u00e0 o\u00f9 on se donne la peine de lui faire une place.<\/p>\n<\/div>\n","protected":false},"author":86,"featured_media":0,"template":"","categories":[1],"rbc_letter_theme":[],"rbc_letter_year":[55],"class_list":["post-2079","rbc_letter","type-rbc_letter","status-publish","hentry","category-uncategorized","rbc_letter_year-55"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>D\u00e9cembre 1998 - La maison du bonheur - RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9cembre 1998 - La maison du bonheur\" \/>\n<meta property=\"og:description\" content=\"Quand la maison n&rsquo;a pas ou n&rsquo;a plus les vertus du chez- soi dont on r\u00eave, la tentation est forte d&rsquo;en claquer la porte. Ceux qui restent fid\u00e8les \u00e0 cet id\u00e9al rendent pourtant un immense service \u00e0 la soci\u00e9t\u00e9, \u00e0 leurs proches&#8230; et \u00e0 eux-m\u00eames. \u00ab\u00a0Maison\u00a0\u00bb\u00a0: mot doux et flou, plus flou que doux \u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T16:10:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/\",\"name\":\"D\u00e9cembre 1998 - La maison du bonheur - RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/08\\\/dotted_quote_line.gif\",\"datePublished\":\"1998-12-01T00:00:00+00:00\",\"dateModified\":\"2022-10-17T16:10:41+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/08\\\/dotted_quote_line.gif\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2022\\\/08\\\/dotted_quote_line.gif\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/\",\"name\":\"RBC\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"D\u00e9cembre 1998 - La maison du bonheur - RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9cembre 1998 - La maison du bonheur","og_description":"Quand la maison n&rsquo;a pas ou n&rsquo;a plus les vertus du chez- soi dont on r\u00eave, la tentation est forte d&rsquo;en claquer la porte. Ceux qui restent fid\u00e8les \u00e0 cet id\u00e9al rendent pourtant un immense service \u00e0 la soci\u00e9t\u00e9, \u00e0 leurs proches&#8230; et \u00e0 eux-m\u00eames. \u00ab\u00a0Maison\u00a0\u00bb\u00a0: mot doux et flou, plus flou que doux \u00e0 [&hellip;]","og_url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","og_site_name":"RBC","article_modified_time":"2022-10-17T16:10:41+00:00","og_image":[{"url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","url":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","name":"D\u00e9cembre 1998 - La maison du bonheur - RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif","datePublished":"1998-12-01T00:00:00+00:00","dateModified":"2022-10-17T16:10:41+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif","contentUrl":"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2022\/08\/dotted_quote_line.gif"},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/#website","url":"https:\/\/www.rbc.com\/fr\/","name":"RBC","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"D\u00e9cembre 1998 &#8211; La maison du bonheur","url":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/www.rbc.com\/fr\/notre-compagnie\/histoire\/bulletin\/decembre-1998-la-maison-du-bonheur\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Uncategorized","author":[{"@type":"Person","name":"zinoemielu"}],"creator":["zinoemielu"],"publisher":{"@type":"Organization","name":"RBC","logo":""},"keywords":[],"dateCreated":"1998-12-01T00:00:00Z","datePublished":"1998-12-01T00:00:00Z","dateModified":"2022-10-17T16:10:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"D\\u00e9cembre 1998 &#8211; La maison du bonheur\",\"url\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.rbc.com\\\/fr\\\/notre-compagnie\\\/histoire\\\/bulletin\\\/decembre-1998-la-maison-du-bonheur\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Uncategorized\",\"author\":[{\"@type\":\"Person\",\"name\":\"zinoemielu\"}],\"creator\":[\"zinoemielu\"],\"publisher\":{\"@type\":\"Organization\",\"name\":\"RBC\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"1998-12-01T00:00:00Z\",\"datePublished\":\"1998-12-01T00:00:00Z\",\"dateModified\":\"2022-10-17T16:10:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/rbc.com\/p.js"},"featured_img":false,"coauthors":[],"author_meta":{"author_link":"https:\/\/www.rbc.com\/fr\/author\/zinoemielu\/","display_name":"zinoemielu"},"relative_dates":{"created":"Publi\u00e9 27 ans il y a","modified":"Mis \u00e0 jour 4 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 1 d\u00e9cembre 1998","modified":"Mise \u00e0 jour le 17 octobre 2022"},"absolute_dates_time":{"created":"Publi\u00e9 le 1 d\u00e9cembre 1998 12:00  ","modified":"Mise \u00e0 jour le 17 octobre 2022 4:10  "},"featured_img_caption":"","tax_additional":{"category":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/category\/uncategorized\/\" class=\"advgb-post-tax-term\">Uncategorized<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Uncategorized<\/span>"],"slug":"category","name":"Cat\u00e9gories"},"rbc_letter_theme":{"linked":[],"unlinked":[],"slug":"rbc_letter_theme","name":"Themes"},"rbc_letter_year":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/year\/1998\/\" class=\"advgb-post-tax-term\">1998<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">1998<\/span>"],"slug":"rbc_letter_year","name":"Years"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/types\/rbc_letter"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/users\/86"}],"version-history":[{"count":0,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter\/2079\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/media?parent=2079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/categories?post=2079"},{"taxonomy":"rbc_letter_theme","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_theme?post=2079"},{"taxonomy":"rbc_letter_year","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/wp-json\/wp\/v2\/rbc_letter_year?post=2079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}