{"id":4238,"date":"2026-07-14T17:42:15","date_gmt":"2026-07-14T17:42:15","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/leadership-avise\/?p=4238"},"modified":"2026-07-14T17:43:06","modified_gmt":"2026-07-14T17:43:06","slug":"huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/","title":{"rendered":"Huit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises"},"content":{"rendered":"\n<div\n\tid=\"tl-fpb-1\"\n\tstyle=\"background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80&amp;w=4096);background-position:50% 50%;background-size:cover;min-height:500px\" class=\"tl-featured-post-banner wp-block-rbc-thought-leadership-blocks-featured-post-banner\">\n\t\t\t<div class=\"tl-featured-post-banner__gradient\" style=\"position:absolute;top:0;left:0;right:0;bottom:0;z-index:0;pointer-events:none;\"><\/div>\n\t\n\t<div class=\"tl-featured-post-banner__inner\">\n\t\t\t\t<a\n\t\t\tclass=\"tl-pill tl-pill--banner\"\n\t\t\thref=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\"\n\t\t>\n\t\t\tG\u00e9opolitique, commerce et \u00e9conomie\t\t<\/a>\n\t\t\n\t\t<div class=\"tl-featured-post-banner__content\">\n\t\t\t\t\t\t<h2 class=\"tl-featured-post-banner__title\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/\">\n\t\t\t\t\t\tHuit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\n\t\t\t\t\t\t<p class=\"tl-featured-post-banner__excerpt\">\n\t\t\t\tS\u2019il y a une le\u00e7on \u00e0 tirer de la pand\u00e9mie de 2020, c\u2019est que m\u00eame en cette \u00e8re num\u00e9rique, nous demeurons des \u00eatres biologiques.\t\t\t<\/p>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<p class=\"wp-block-paragraph\">Nous avons appris que malgr\u00e9 toutes les technologies dont nous disposons, nous ne pouvons pas \u00e9chapper \u00e0 la nature. Cette crise est une bonne le\u00e7on d\u2019humilit\u00e9. Elle devrait nous rappeler que m\u00eame une puissante secousse \u00e0 l\u2019\u00e9chelle plan\u00e9taire ne saurait contrarier la progression de la quatri\u00e8me r\u00e9volution industrielle. Au contraire, nous sortons de cette crise avec une volont\u00e9 encore plus grande d\u2019exploiter les technologies intelligentes, l\u2019intelligence artificielle et les vastes r\u00e9servoirs de donn\u00e9es pour transformer \u00e0 peu pr\u00e8s tout ce que nous faisons. La COVID n\u2019a donc pas an\u00e9anti l\u2019avenir. Elle l\u2019a simplement avanc\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 court terme, la reprise \u00e9conomique ne sera pas aussi rapide que les changements de consommation et sociaux qui frappent toutes les entreprises et toutes les collectivit\u00e9s. Le tissu cicatriciel mettra du temps \u00e0 gu\u00e9rir. Nous estimons que m\u00eame en connaissant une reprise modeste, l\u2019\u00e9conomie canadienne \u00e9voluera en de\u00e7\u00e0 des niveaux ant\u00e9rieurs \u00e0 la crise jusqu\u2019en 2022, et que la perte de production \u00e9conomique pour le Canada pourrait d\u00e9passer les 500 milliards de dollars.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les entrepreneurs sauront profiter de la reprise \u00e9ventuelle. Certes, le nouveau coronavirus a boulevers\u00e9 l\u2019\u00e9conomie, mais il peut aussi d\u00e9clencher des vagues d\u2019innovation provoqu\u00e9es par les changements que nous apportons \u00e0 nos fa\u00e7ons de travailler, d\u2019acheter, de manger et de voyager. Les soci\u00e9t\u00e9s, anciennes et nouvelles, qui tirent parti de ce changement soudain seront les principaux acteurs des ann\u00e9es 2020.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le pr\u00e9sent rapport, nous examinons huit grandes tendances en cours dans le monde et mettons en \u00e9vidence les possibilit\u00e9s qui s\u2019offrent aux exploitants d\u2019entreprise, aux investisseurs et aux innovateurs avis\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme l\u2019histoire se pla\u00eet \u00e0 nous le rappeler, toute situation sans pr\u00e9c\u00e9dent s\u2019accompagne d\u2019occasions sans precedent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Ce rapport a \u00e9t\u00e9 mis \u00e0 jour le 24 septembre 2020.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recherchistes : Trinh Theresa Do Premi\u00e8re directrice, Strat\u00e9gie de leadership avis\u00e9 et Ben Richardson Charg\u00e9 de recherche associ\u00e9.<\/p>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel pad-b-0 mob-pad-b-0\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-b-qtr\" style=\"border-radius:0x\">\n<div class=\"wp-block-columns has-border-color has-rbc-climate-action-dark-seaweed-border-color is-layout-flex wp-container-core-columns-is-layout-9ba6dbca wp-block-columns-is-layout-flex\" style=\"border-style:solid;border-width:1px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large  mar-r-hlf\"><img loading=\"lazy\" decoding=\"async\" width=\"260\" height=\"173\" src=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/8-Trends-CTA-FR.jpg?quality=80&amp;w=260\" alt=\"\" class=\"wp-image-283\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column mar-t is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 id=\"h-lire-le-rapport-integral\" class=\"wp-block-heading\">Lire le rapport int\u00e9gral<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\"><div>\n<div class=\"wp-block-button btn before is-style-tertiary tertiary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/11\/After-the-crisis-fr.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" data-dig-id=\"LP-G\u00e9opolitique,commerceet\u00e9conomie-4238-6e14bd18\" data-dig-category=\"LP-G\u00e9opolitique,commerceet\u00e9conomie\" data-dig-action=\"button click\" data-dig-label=\"T\u00e9l\u00e9charger-https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/4\/2024\/11\/After-the-crisis-fr.pdf \">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<div class=\"wp-block-rbc-rbc-default-collapsible\"><p><button class=\"collapse-toggle collapsed\" data-target=\"#collapse422d4d10\" data-toggle=\"collapse\" aria-expanded=\"false\" aria-controls=\"collapse422d4d10\" data-dig-id=\"LP-Uncategorized-4238-422d4d10\" data-dig-category=\"LP-Uncategorized\" data-dig-action=\"accordion closed\" action-closed=\"accordion closed\" action-opened=\"accordion open\" data-dig-label=\"Apr\u00e8s la crise\"><div>Apr\u00e8s la crise<\/div><\/button><\/p><div class=\"collapse-content collapse\" id=\"collapse422d4d10\">\n<div class=\"wp-block-rbc-collapsible-inner-block collapse-inner\">\n<h4 id=\"h-s-il-y-a-une-lecon-a-tirer-de-la-pandemie-de-2020-c-est-que-meme-en-cette-ere-numerique-nousdemeurons-des-etres-biologiques\" class=\"wp-block-heading\">S&rsquo;il y a une le\u00e7on \u00e0 tirer de la pand\u00e9mie de 2020,c&rsquo;est que m\u00eame en cette \u00e8re num\u00e9rique, nousdemeurons des \u00eatres biologiques.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avonsappris que malgr\u00e9 toutes les technologies dontnous disposons, nous ne pouvons pas \u00e9chapper \u00e0 lanature. D&rsquo;une part, cette crise est une bonne le\u00e7ond&rsquo;humilit\u00e9. D&rsquo;autre part, elle devrait nous rappelerque m\u00eame une puissante secousse \u00e0 l&rsquo;\u00e9chelleplan\u00e9taire ne saurait contrarier la progression de laquatri\u00e8me r\u00e9volution industrielle. Au contraire, noussortons de cette crise avec une volont\u00e9 encore plusgrande d&rsquo;exploiter les technologies intelligentes,les nouvelles formes de renseignement et les vastesr\u00e9servoirs de donn\u00e9es pour transformer \u00e0 peu pr\u00e8stout ce que nous faisons. La COVID n&rsquo;a donc pasan\u00e9anti l&rsquo;avenir. Elle l&rsquo;a simplement avanc\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 court terme, la reprise \u00e9conomique ne sera pasaussi rapide que les changements de consommationet sociaux qui frappent toutes les entreprises ettoutes les collectivit\u00e9s. Le tissu cicatriciel mettradu temps \u00e0 gu\u00e9rir. Nous nous attendons \u00e0 ce quel&rsquo;\u00e9conomie canadienne, c&rsquo;est\u2011\u00e0\u2011dire le PIB, fl\u00e9chissede 7,1 % en 2020 \u00e0 cause de la stagnation ducommerce international, du ch\u00f4mage invariablement\u00e9lev\u00e9 et du confinement des consommateurs.M\u00eame si les provinces autorisent la r\u00e9ouvertured&rsquo;entreprises, de groupes communautaires et,plus tard, d&rsquo;\u00e9coles, une nervosit\u00e9 sourde entra\u00eeneraune pause collective de l&rsquo;\u00e9conomie. Partout, lesgens accorderont une nouvelle priorit\u00e9 \u00e0 la s\u00e9curit\u00e9du revenu et \u00e0 la protection de la sant\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette nouvelle \u00e8re d&rsquo;ins\u00e9curit\u00e9 n&rsquo;aura pas pourunique effet d&rsquo;impr\u00e9gner la psych\u00e9 des Canadiens.Nous estimons que m\u00eame en connaissant une reprisemodeste, l&rsquo;\u00e9conomie canadienne \u00e9voluera en de\u00e7\u00e0des niveaux ant\u00e9rieurs au coronavirus jusqu&rsquo;en 2022,et que la perte combin\u00e9e de production \u00e9conomiquepour le Canada pourrait d\u00e9passer les 1 000 milliardsde dollars. Ce revers freine d\u00e9j\u00e0 les investisseurset les entrepreneurs, et pourrait \u00e9galement donner\u00e0 r\u00e9fl\u00e9chir aux dirigeants gouvernementaux quidistribuent des sommes sans pr\u00e9c\u00e9dent dans lebut de relancer une \u00e9conomie qui pourrait peiner\u00e0 red\u00e9marrer. Notre suivi r\u00e9gulier des propri\u00e9tairesde petites et moyennes entreprises montre que laprudence est g\u00e9n\u00e9ralis\u00e9e : les trois quarts ont ferm\u00e9leurs portes, en partie ou en totalit\u00e9, et le tiersa licenci\u00e9 du personnel. Plus inqui\u00e9tant encore,un quart d&rsquo;entre eux craignent de ne pouvoir passer\u00e0 travers la crise. Et si un Canadien sur cinq al&rsquo;impression de \u00ab sombrer \u00bb \u00e9conomiquement,les propri\u00e9taires de petite entreprise sont deux foisplus nombreux \u00e0 partager ce sentiment.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il est difficile de savoir qui sera le premier \u00e0 braverla temp\u00eate, mais c&rsquo;est dans de telles circonstancesque les occasions abondent. Certes, le nouveaucoronavirus de 2019 a d\u00e9clench\u00e9 une r\u00e9cessionmondiale massive, mais il d\u00e9clenche \u00e9galementdes vagues d&rsquo;innovation provoqu\u00e9es par leschangements que nous apportons tous \u00e0 nos fa\u00e7onsde travailler, d&rsquo;acheter, de manger et de voyager.Des soci\u00e9t\u00e9s, anciennes et nouvelles, qui observentce changement soudain du comportement humain,commencent \u00e0 prendre de l&rsquo;expansion.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le pr\u00e9sent rapport, nous examinons huitgrandes tendances en cours dans le monde etmettons en \u00e9vidence les possibilit\u00e9s qui s&rsquo;offrentaux exploitants d&rsquo;entreprise, aux investisseurs etaux innovateurs avis\u00e9s. Nous savons tous \u00e0 quelpoint nos vies ont chang\u00e9 et \u00e0 quel point lesprobabilit\u00e9s que nous revenions \u00e0 nos ancienneshabitudes sont faibles. Nous serons plus prudents,mais nous serons peut\u2011\u00eatre aussi plus cr\u00e9atifs.Comme l&rsquo;histoire se pla\u00eet \u00e0 nous le rappeler, toutesituation sans pr\u00e9c\u00e9dent s&rsquo;accompagne d&rsquo;occasionssans pr\u00e9c\u00e9dent.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Voir une version ant\u00e9rieure de ce rapport dat\u00e9e du 22 mai 2020<\/em><\/p>\n<\/div>\n<\/section>\n<style class=\"advgb-styles-renderer\">@media (min-width:782px){#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(135deg, #070707, #00356300 100%);opacity:1;}}@media (max-width:781px){#tl-fpb-1{background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80&w=4096)!important;background-position:50% 50%!important;background-size:cover!important;min-height:400px!important;}#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(45deg, #070707, #00356300 100%);opacity:1;}}<\/style>","protected":false},"excerpt":{"rendered":"<p>S\u2019il y a une le\u00e7on \u00e0 tirer de la pand\u00e9mie de 2020, c\u2019est que m\u00eame en cette \u00e8re num\u00e9rique, nous demeurons des \u00eatres biologiques.<\/p>\n","protected":false},"author":337,"featured_media":282,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[78],"tags":[],"rbc_tl_platform":[],"rbc_tl_newsletter":[],"rbc_tl_content_type":[77],"rbc_tl_author":[98],"class_list":["post-4238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geopolitique-commerce-et-economie","rbc_tl_content_type-article","rbc_tl_author-john-stackhouse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Huit fa\u00e7ons dont la COVID-19 transformera l&#039;\u00e9conomie et perturbera toutes les entreprises - Leadership avis\u00e9 RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Huit fa\u00e7ons dont la COVID-19 transformera l&#039;\u00e9conomie et perturbera toutes les entreprises\" \/>\n<meta property=\"og:description\" content=\"S\u2019il y a une le\u00e7on \u00e0 tirer de la pand\u00e9mie de 2020, c\u2019est que m\u00eame en cette \u00e8re num\u00e9rique, nous demeurons des \u00eatres biologiques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/\" \/>\n<meta property=\"og:site_name\" content=\"Leadership avis\u00e9 RBC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rbc\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T17:42:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T17:43:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"daneilkwan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:site\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"daneilkwan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/\"},\"author\":{\"name\":\"daneilkwan\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/person\\\/2923513c926ada6bb07d1dd8d0c8f342\"},\"headline\":\"Huit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises\",\"datePublished\":\"2026-07-14T17:42:15+00:00\",\"dateModified\":\"2026-07-14T17:43:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/\"},\"wordCount\":947,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Banner-wide-28-scaled-1.jpg?quality=80\",\"articleSection\":[\"G\u00e9opolitique, commerce et \u00e9conomie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/\",\"name\":\"Huit fa\u00e7ons dont la COVID-19 transformera l'\u00e9conomie et perturbera toutes les entreprises - Leadership avis\u00e9 RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Banner-wide-28-scaled-1.jpg?quality=80\",\"datePublished\":\"2026-07-14T17:42:15+00:00\",\"dateModified\":\"2026-07-14T17:43:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Banner-wide-28-scaled-1.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Banner-wide-28-scaled-1.jpg?quality=80\",\"width\":2560,\"height\":1236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leadership avis\u00e9 RBC\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Huit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"name\":\"Leadership avis\u00e9 RBC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\",\"name\":\"Leadership avis\u00e9 RBC\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Leadership avis\u00e9 RBC\"},\"alternateName\":\"Leadership avis\u00e9 Banque Royale du Canada\",\"description\":\"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rbc\",\"https:\\\/\\\/x.com\\\/rbcfr\",\"https:\\\/\\\/www.instagram.com\\\/rbcbanqueroyale\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RBC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rbc\\\/\"],\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"Royal Bank of Canada\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Huit fa\u00e7ons dont la COVID-19 transformera l'\u00e9conomie et perturbera toutes les entreprises - Leadership avis\u00e9 RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/","og_locale":"fr_FR","og_type":"article","og_title":"Huit fa\u00e7ons dont la COVID-19 transformera l'\u00e9conomie et perturbera toutes les entreprises","og_description":"S\u2019il y a une le\u00e7on \u00e0 tirer de la pand\u00e9mie de 2020, c\u2019est que m\u00eame en cette \u00e8re num\u00e9rique, nous demeurons des \u00eatres biologiques.","og_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/","og_site_name":"Leadership avis\u00e9 RBC","article_publisher":"https:\/\/www.facebook.com\/rbc","article_published_time":"2026-07-14T17:42:15+00:00","article_modified_time":"2026-07-14T17:43:06+00:00","og_image":[{"width":2560,"height":1236,"url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","type":"image\/jpeg"}],"author":"daneilkwan","twitter_card":"summary_large_image","twitter_creator":"@rbcfr","twitter_site":"@rbcfr","twitter_misc":{"Written by":"daneilkwan","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/"},"author":{"name":"daneilkwan","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/person\/2923513c926ada6bb07d1dd8d0c8f342"},"headline":"Huit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises","datePublished":"2026-07-14T17:42:15+00:00","dateModified":"2026-07-14T17:43:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/"},"wordCount":947,"commentCount":0,"publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","articleSection":["G\u00e9opolitique, commerce et \u00e9conomie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/","name":"Huit fa\u00e7ons dont la COVID-19 transformera l'\u00e9conomie et perturbera toutes les entreprises - Leadership avis\u00e9 RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","datePublished":"2026-07-14T17:42:15+00:00","dateModified":"2026-07-14T17:43:06+00:00","breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","width":2560,"height":1236},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/huit-facons-dont-la-covid-19-transformera-leconomie-et-perturbera-toutes-les-entreprises\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leadership avis\u00e9 RBC","item":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"},{"@type":"ListItem","position":2,"name":"Huit fa\u00e7ons dont la COVID-19 transformera l&rsquo;\u00e9conomie et perturbera toutes les entreprises"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","name":"Leadership avis\u00e9 RBC","description":"","publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/leadership-avise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization","name":"Leadership avis\u00e9 RBC","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/logo\/image\/","url":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","contentUrl":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","width":"1024","height":"1024","caption":"Leadership avis\u00e9 RBC"},"alternateName":"Leadership avis\u00e9 Banque Royale du Canada","description":"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.","sameAs":["https:\/\/www.facebook.com\/rbc","https:\/\/x.com\/rbcfr","https:\/\/www.instagram.com\/rbcbanqueroyale","https:\/\/www.youtube.com\/user\/RBC","https:\/\/www.linkedin.com\/company\/rbc\/"],"parentOrganization":{"@type":"Organization","name":"Royal Bank of Canada","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"}}]}},"author_meta":{"display_name":"daneilkwan","author_link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/author\/daneilkwan\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Banner-wide-28-scaled-1.jpg?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/category\/geopolitique-commerce-et-economie\/\" class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 7 heures il y a","modified":"Mis \u00e0 jour 7 heures il y a"},"absolute_dates":{"created":"Publi\u00e9 le juillet 14, 2026","modified":"Mise \u00e0 jour le juillet 14, 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le juillet 14, 2026 5:42  ","modified":"Mise \u00e0 jour le juillet 14, 2026 5:43  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/4238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/users\/337"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/comments?post=4238"}],"version-history":[{"count":4,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/4238\/revisions"}],"predecessor-version":[{"id":4244,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/4238\/revisions\/4244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media\/282"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media?parent=4238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/categories?post=4238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/tags?post=4238"},{"taxonomy":"rbc_tl_platform","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_platform?post=4238"},{"taxonomy":"rbc_tl_newsletter","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_newsletter?post=4238"},{"taxonomy":"rbc_tl_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_content_type?post=4238"},{"taxonomy":"rbc_tl_author","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_author?post=4238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}