{"id":2087,"date":"2026-02-02T17:37:21","date_gmt":"2026-02-02T17:37:21","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/tl\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/"},"modified":"2026-07-06T18:22:46","modified_gmt":"2026-07-06T18:22:46","slug":"principaux-risques-2026-les-effets-inattendus-de-la-charte","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/","title":{"rendered":"Principaux risques 2026 : Les effets inattendus de la Charte"},"content":{"rendered":"\n<div\n\tid=\"tl-fpb-1\"\n\tstyle=\"background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80&amp;w=4096);background-position:50% 50%;background-size:cover;min-height:500px\" class=\"tl-featured-post-banner wp-block-rbc-thought-leadership-blocks-featured-post-banner\">\n\t\t\t<div class=\"tl-featured-post-banner__gradient\" style=\"position:absolute;top:0;left:0;right:0;bottom:0;z-index:0;pointer-events:none;\"><\/div>\n\t\n\t<div class=\"tl-featured-post-banner__inner\">\n\t\t\t\t<a\n\t\t\tclass=\"tl-pill tl-pill--banner\"\n\t\t\thref=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\"\n\t\t>\n\t\t\tG\u00e9opolitique, commerce et \u00e9conomie\t\t<\/a>\n\t\t\n\t\t<div class=\"tl-featured-post-banner__content\">\n\t\t\t\t\t\t<h2 class=\"tl-featured-post-banner__title\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/\">\n\t\t\t\t\t\tPrincipaux risques 2026 : Les effets inattendus de la Charte\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\n\t\t\t\t\t\t<p class=\"tl-featured-post-banner__excerpt\">\n\t\t\t\tLes perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.\t\t\t<\/p>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<p class=\"wp-block-paragraph\"><em>Cela fait partie du <a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/le-projet-croissance\/principaux-risques-2026-canada\/\" data-dig-id=\"LP-G\u00e9opolitique,commerceet\u00e9conomie-2087-6d420ce5\" data-dig-label=\"rapport conjoint\" data-dig-action=\"link click\" data-dig-category=\"LP-G\u00e9opolitique,commerceet\u00e9conomie\" class=\"rbc-link-format\">rapport conjoint<\/a> <a href=\"https:\/\/www.rbc.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/Principaux-risques-2026-Canada.pdf\" data-dig-id=\"LP-G\u00e9opolitique,commerceet\u00e9conomie-2087-6d420ce5\" data-dig-label=\"rapport conjoint \" data-dig-action=\"link click\" data-dig-category=\"LP-G\u00e9opolitique,commerceet\u00e9conomie\" class=\"rbc-link-format\"><\/a>de RBC Thought Leadership et d&rsquo;Eurasia Group<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les perspectives \u00e9conomiques du Canada sont menac\u00e9es non seulement par des chocs externes et des voisins exigeants, mais aussi par une asym\u00e9trie croissante du f\u00e9d\u00e9ralisme qui complique l\u2019\u00e9laboration, l\u2019acceptation et la mise en oeuvre d\u2019une strat\u00e9gie \u00e9conomique coh\u00e9rente \u00e0 l\u2019\u00e9chelle nationale.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les divergences de vues entre Ottawa, les provinces et les gouvernements autochtones sur l\u2019exploitation des ressources naturelles, le financement et la prestation de l\u2019\u00e9ducation, ainsi que la stabilisation d\u2019un syst\u00e8me de sant\u00e9 sous tension, accentuent la fragmentation du Canada en un ensemble de r\u00e9gimes de politiques publiques disparates, au moment m\u00eame o\u00f9 le pays doit faire face \u00e0 des n\u00e9gociations commerciales difficiles avec des \u00c9tats-Unis plus transactionnels et \u00e0 une concurrence mondiale accrue. Des instruments constitutionnels autrefois consid\u00e9r\u00e9s comme des recours ultimes \u2014 la clause d\u00e9rogatoire, des contestations juridictionnelles offensives, des demandes d\u2019exemptions aux r\u00e9glementations et normes nationales, voire des votes provinciaux sur l\u2019autonomie \u2014 deviennent de plus en plus courants. Cette \u00e9volution accro\u00eet la probabilit\u00e9 que les provinces et les groupes autochtones recourent \u00e0 des droits de veto, formels ou informels, pour bloquer des priorit\u00e9s nationales. Un seul Canada, peut-\u00eatre, mais de multiples nations en son sein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Les cons\u00e9quences pour l\u2019unit\u00e9 nationale sont plus graves qu\u2019\u00e0 tout autre moment depuis les ann\u00e9es 1990, car la fragmentation s\u2019accompagne d\u00e9sormais de soutiens \u00e0 l\u2019\u00e9tranger. Un ordre mondial plus fragment\u00e9 offre aux gouvernements \u00e9trangers, aux r\u00e9seaux militants et aux acteurs corporatifs davantage d\u2019occasions d\u2019exploiter les tensions entre comp\u00e9tences, que ce soit en favorisant certaines provinces dans les d\u00e9cisions li\u00e9es aux cha\u00eenes d\u2019approvisionnement, en finan\u00e7ant des recours judiciaires et des campagnes m\u00e9diatiques autour de projets de ressources, ou en amplifiant des r\u00e9cits s\u00e9paratistes. Pour des rivaux g\u00e9opolitiques, tout ce qui affaiblit la coh\u00e9rence du Canada en tant qu\u2019alli\u00e9 des \u00c9tats-Unis et partenaire du G7 peut m\u00eame devenir un atout plut\u00f4t qu\u2019un effet ind\u00e9sirable, \u00e0 mesure que des acteurs infranationaux et des d\u00e9tenteurs de droits autochtones cherchent \u00e0 affirmer plus vigoureusement leur voix sur l\u2019\u00e9nergie, le climat, la politique industrielle, le commerce int\u00e9rieur et, de mani\u00e8re plus critique encore, les relations commerciales bilat\u00e9rales avec les \u00c9tats-Unis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>La conf\u00e9d\u00e9ration canadienne a \u00e9t\u00e9 con\u00e7ue pour concilier l\u2019autonomie provinciale et l\u2019autorit\u00e9 f\u00e9d\u00e9rale dans certains domaines d\u2019int\u00e9r\u00eat commun, notamment le commerce. Avec le temps toutefois, la Charte canadienne des droits et libert\u00e9s a plac\u00e9 les tribunaux au coeur de cet \u00e9quilibre. La Charte conf\u00e8re aux individus et aux groupes \u2014 y compris aux collectivit\u00e9s autochtones et aux provinces elles-m\u00eames \u2014 des instruments puissants pour contester, au nom des droits, des lois f\u00e9d\u00e9rales ou provinciales, obligeant ainsi les choix de politiques publiques dans des domaines comme la langue, l\u2019\u00e9ducation et les programmes sociaux \u00e0 r\u00e9sister \u00e0 l\u2019examen constitutionnel. Dans les faits, cette \u00e9volution a \u00e9tendu le r\u00f4le de la Cour supr\u00eame comme arbitre des relations f\u00e9d\u00e9rales-provinciales et Couronne\u2013Autochtones, les gouvernements de tous horizons mobilisant la Charte non seulement pour prot\u00e9ger des droits, mais aussi pour restreindre des initiatives fiscales et r\u00e9glementaires auxquelles ils s\u2019opposent. Parmi ces instruments, le plus controvers\u00e9 est la clause d\u00e9rogatoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Rarement utilis\u00e9e par le pass\u00e9, elle a \u00e9t\u00e9 invoqu\u00e9e ou s\u00e9rieusement menac\u00e9e ces derni\u00e8res ann\u00e9es par le Qu\u00e9bec, l\u2019Ontario, la Saskatchewan et l\u2019Alberta dans des conflits portant sur la langue, les symboles religieux, le financement des \u00e9lections, les droits du travail et l\u2019\u00e9ducation, envoyant ainsi aux \u00e9lecteurs le signal que les gouvernements peuvent contourner les tribunaux lorsque la protection des droits entre en conflit avec des objectifs politiques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Le caract\u00e8re r\u00e9gional \u2014 et les divergences \u2014 de l\u2019\u00e9conomie canadienne accentue les int\u00e9r\u00eats concurrents des provinces, chacune \u00e9tant expos\u00e9e \u00e0 des menaces diff\u00e9rentes li\u00e9es \u00e0 la guerre commerciale de Donald Trump et aux divisions mondiales. L\u2019\u00e9conomie de l\u2019Ontario reste centr\u00e9e sur l\u2019automobile et l\u2019acier ; la Colombie-Britannique d\u00e9pend largement du bois et du commerce avec l\u2019Asie ; la Saskatchewan repose sur le canola et d\u2019autres exportations agricoles ; et la prosp\u00e9rit\u00e9 de l\u2019Alberta est \u00e9troitement li\u00e9e au p\u00e9trole et au gaz. La position de n\u00e9gociation du Canada a \u00e9t\u00e9 fragilis\u00e9e pendant une grande partie de 2025, les premiers ministres tentant de d\u00e9fendre leurs int\u00e9r\u00eats propres \u00e0 Washington. Ces tensions pourraient resurgir d\u00e8s que les n\u00e9gociations de l\u2019AEUMC reprendront s\u00e9rieusement.<br>Le projet de loi C-5, la Loi sur l\u2019unit\u00e9 de l\u2019\u00e9conomie canadienne, est devenu, en raison des r\u00e9actions politiques qu\u2019il suscite, un point central des tensions f\u00e9d\u00e9rales-provinciales concernant la gouvernance des ressources et les droits des Autochtones. Cette l\u00e9gislation permet au Cabinet f\u00e9d\u00e9ral de d\u00e9clarer qu\u2019un projet \u2014 qu\u2019il s\u2019agisse de ports, de pipelines, de mines ou de barrages \u2014 rel\u00e8ve de l\u2019int\u00e9r\u00eat national et d\u2019en acc\u00e9l\u00e9rer l\u2019approbation. Les provinces qui d\u00e9noncent l\u2019ing\u00e9rence f\u00e9d\u00e9rale dans leurs comp\u00e9tences en mati\u00e8re de ressources naturelles consid\u00e8rent le C-5 comme un d\u00e9passement de leurs pr\u00e9rogatives par Ottawa, tandis que de nombreux groupes autochtones y voient une attaque directe contre leur droit constitutionnel \u00e0 \u00eatre consult\u00e9s et pris en compte dans les d\u00e9cisions touchant leurs terres. Le r\u00e9sultat est une s\u00e9rie de contestations judiciaires et de manifestations qui politisent davantage les grands projets sur lesquels le gouvernement Carney compte pour rendre l\u2019\u00e9conomie canadienne moins d\u00e9pendante de celle des \u00c9tats-Unis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 la suite du projet de loi C-5, le protocole d\u2019entente Canada\u2013Alberta sur l\u2019\u00e9nergie et le climat constitue \u00e0 la fois un mod\u00e8le de coop\u00e9ration et un r\u00e9v\u00e9lateur de la nature transactionnelle du f\u00e9d\u00e9ralisme canadien. Aux termes de l\u2019entente, Ottawa et Edmonton collaboreront pour atteindre la carboneutralit\u00e9 d\u2019ici 2050, construire des interconnexions majeures de transport d\u2019\u00e9lectricit\u00e9, r\u00e9duire les d\u00e9lais r\u00e9glementaires \u00e0 environ deux ans et n\u00e9gocier des ententes d\u2019\u00e9quivalence sur la tarification du carbone et la r\u00e9duction du m\u00e9thane d\u2019ici avril 2026. Il esquisse \u00e9galement des voies pour un nouveau pipeline d\u2019exportation et des infrastructures de captage du carbone pr\u00e9voyant explicitement la participation des communaut\u00e9s autochtones et le partage des retomb\u00e9es \u00e9conomiques. Cependant, le fait que ces priorit\u00e9s nationales soient trait\u00e9es au cas par cas, province par province, illustre combien une grande partie de l\u2019agenda Carney s\u2019appuie d\u00e9sormais sur des accords bilat\u00e9raux plut\u00f4t que sur des cadres pancanadiens. Cela invite d\u2019autres provinces riches en ressources \u00e0 exiger des arrangements similaires ou des exceptions, et am\u00e8ne les r\u00e9gions urbaines en expansion, o\u00f9 les Lib\u00e9raux au pouvoir disposent de leur assise politique, \u00e0 se demander si leurs propres aspirations sont \u00e9galement prises en compte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Les tensions asym\u00e9triques au Canada r\u00e9sident dans les relations Couronne\u2013Autochtones situ\u00e9es \u00e0 l\u2019intersection des droits, des ressources et de la l\u00e9gitimit\u00e9. Les nations et collectivit\u00e9s autochtones ont d\u00e9velopp\u00e9 une grande expertise dans l\u2019usage simultan\u00e9 des tribunaux et de l\u2019action directe pour arr\u00eater ou remodeler des projets majeurs, obtenant des injonctions, contraignant les gouvernements \u00e0 revenir \u00e0 la table de n\u00e9gociation et mobilisant l\u2019opinion publique lorsqu\u2019elles jugent que les consultations ont \u00e9t\u00e9 insuffisantes. Les Premi\u00e8res Nations de la Colombie-Britannique repr\u00e9sentent un d\u00e9fi particulier, car elles sont au coeur du d\u00e9veloppement des ressources et de l\u2019expansion des exportations vers le Pacifique, tout en jouissant d\u2019un statut juridique distinct, la province \u00e9tant entr\u00e9e dans la Conf\u00e9d\u00e9ration sans trait\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Sous ces pressions, plusieurs provinces et Ottawa ont commenc\u00e9 \u00e0 exp\u00e9rimenter des exemptions aux r\u00e8gles environnementales, aux r\u00e9gulations \u00e9lectriques et aux normes du commerce interprovincial. Certaines provinces militent \u00e9galement pour une d\u00e9centralisation accrue de l\u2019immigration et exigent un plus grand respect de leur comp\u00e9tence en mati\u00e8re de politiques de logement, qui demeure un enjeu politique particuli\u00e8rement sensible. En cons\u00e9quence, les investisseurs internationaux commencent \u00e0 consid\u00e9rer le f\u00e9d\u00e9ralisme canadien \u2014 autrefois per\u00e7u comme une singularit\u00e9 du Grand Nord \u2014 comme un risque op\u00e9rationnel. \u00ab Peut-on y arriver ? \u00bb reste la question pos\u00e9e \u00e0 de nombreuses propositions canadiennes, qu\u2019il s\u2019agisse de pipelines, de mines ou d\u2019infrastructures d\u2019exportation de grande envergure. Parall\u00e8lement, certains per\u00e7oivent ce r\u00e9seau de protections des droits et d\u2019exigences de consentement multi-niveaux comme un indicateur de robustesse de l\u2019\u00c9tat de droit et de licence sociale, surtout compar\u00e9 \u00e0 des r\u00e9gimes plus arbitraires. L\u2019\u00e9quilibre entre rapidit\u00e9 et certitude sera mesur\u00e9, en partie, par la mani\u00e8re dont le gouvernement Carney g\u00e8re les diff\u00e9rends \u00e0 forte visibilit\u00e9 concernant les projets du C-5 et les engagements pr\u00e9vus dans le protocole d\u2019entente Canada\u2013Alberta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le style hautement centralis\u00e9 du bureau du Premier ministre constitue \u00e0 la fois un atout et une vuln\u00e9rabilit\u00e9. Un centre premier-minist\u00e9riel fort peut coordonner rapidement les politiques \u00e9conomiques, climatiques et \u00e9trang\u00e8res pour r\u00e9agir aux chocs am\u00e9ricains et mobiliser les d\u00e9penses f\u00e9d\u00e9rales autour d\u2019une strat\u00e9gie industrielle coh\u00e9rente. Mais gouverner par bureau du Premier ministre resserr\u00e9 et des accords bilat\u00e9raux avec les premiers ministres comporte le risque de marginaliser les forums intergouvernementaux et le contr\u00f4le parlementaire, alimentant le r\u00e9cit selon lequel Ottawa impose sa volont\u00e9 et incitant les provinces \u00e0 riposter par les tribunaux, la clause d\u00e9rogatoire ou leurs propres r\u00e9f\u00e9rendums sur l\u2019autonomie, sans compter le risque au sein du cabinet et du caucus, particuli\u00e8rement dans un parlement fragile. Une d\u00e9pendance excessive aux ententes ex\u00e9cutives pourrait rendre la politique nationale tributaire d\u2019un petit nombre de relations politiques plut\u00f4t que solidement ancr\u00e9e dans des institutions durables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Le calendrier politique de 2026 fait augmenter le risque que les diff\u00e9rends constitutionnels et entre comp\u00e9tences passent du bruit de fond \u00e0 des points de tension majeurs. Une \u00e9lection f\u00e9d\u00e9rale \u00e9ventuelle, une \u00e9lection pr\u00e9vue au Qu\u00e9bec et les batailles persistantes en Alberta et en Colombie-Britannique sur la politique \u00e9nerg\u00e9tique, les objectifs climatiques et le partage des revenus cr\u00e9ent tous des incitations pour les dirigeants \u00e0 faire campagne contre Ottawa ou contre d\u2019autres provinces. Cette \u00ab politique du grief permanent \u00bb \u00e9rode le capital de confiance n\u00e9cessaire \u00e0 la r\u00e9alisation de projets \u00e9conomiques conjoints. Sans signaux suppl\u00e9mentaires de progr\u00e8s, la \u00ab lev\u00e9e des coudes \u00bb estivale risque de se transformer, \u00e0 l\u2019hiver, en une atmosph\u00e8re de confiance en recul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Combler ces \u00e9carts n\u00e9cessitera une strat\u00e9gie d\u00e9lib\u00e9r\u00e9e de chor\u00e9graphie politique autant qu\u2019une conception soign\u00e9e des politiques publiques. Les sommets f\u00e9d\u00e9raux-provinciaux-territoriaux sur la sant\u00e9, le logement et le climat peuvent encore \u00e9tablir des bases communes, mais ils restent toujours expos\u00e9s au risque de se transformer en moyens de pression provinciaux sur la f\u00e9d\u00e9ration. Des campagnes publicitaires, des initiatives de communication et des forums publics, men\u00e9s non seulement par le Premier ministre mais aussi par les premiers ministres provinciaux, les leaders autochtones et les PDG, peuvent contribuer \u00e0 renforcer un r\u00e9cit partag\u00e9 autour d\u2019un Canada uni et confiant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9forme r\u00e9glementaire constituera un test central de la capacit\u00e9 du gouvernement Carney \u00e0 mobiliser les comp\u00e9tences f\u00e9d\u00e9rales au service de la coh\u00e9sion nationale. Les initiatives visant \u00e0 r\u00e9duire les barri\u00e8res commerciales interprovinciales, \u00e0 harmoniser ou \u00e0 reconna\u00eetre mutuellement les accr\u00e9ditations professionnelles, et \u00e0 rationaliser les parcours d\u2019immigration pour les professions en forte demande offrent des perspectives tangibles de gains de productivit\u00e9 et de mobilit\u00e9 de la main-d\u2019oeuvre. Toutefois, chacune de ces mesures touche \u00e0 des pr\u00e9rogatives provinciales particuli\u00e8rement sensibles. Les m\u00e9canismes de coop\u00e9ration int\u00e9gr\u00e9s au protocole d\u2019entente Canada\u2013Alberta \u2014 \u00e9valuations \u00e0 guichet unique, \u00e9ch\u00e9anciers d\u00e9finis et accords d\u2019\u00e9quivalence \u2014 proposent un cadre op\u00e9rationnel qui pourrait, en th\u00e9orie, \u00eatre transpos\u00e9 \u00e0 d\u2019autres provinces et secteurs, sous r\u00e9serve de la construction d\u2019un niveau suffisant de confiance. En l\u2019absence de telles r\u00e9formes, le Canada risque de laisser inexploit\u00e9es d\u2019importantes efficacit\u00e9s de son march\u00e9 int\u00e9rieur pr\u00e9cis\u00e9ment au moment o\u00f9 il cherche \u00e0 compenser la moindre fiabilit\u00e9 de son partenaire am\u00e9ricain. Les entreprises et les investisseurs devraient ainsi consid\u00e9rer les tensions juridictionnelles comme une caract\u00e9ristique structurelle \u2014 et potentiellement un atout \u2014 du Canada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La n\u00e9cessit\u00e9 d\u2019obtenir un consentement \u00e0 plusieurs niveaux et de naviguer entre des r\u00e9gimes juridiques qui se chevauchent accro\u00eet les co\u00fbts de transaction et allonge les d\u00e9lais de mise en oeuvre des projets. Elle peut toutefois conduire \u00e0 des r\u00e9sultats plus robustes, fond\u00e9s sur une l\u00e9gitimit\u00e9 sociale renforc\u00e9e, et r\u00e9duire le risque de revirements brusques. Pour les entreprises dispos\u00e9es \u00e0 investir dans des relations durables avec les provinces, les gouvernements autochtones et les municipalit\u00e9s, le f\u00e9d\u00e9ralisme complexe du Canada peut devenir une source d\u2019avantage diff\u00e9renci\u00e9 en prot\u00e9geant les engagements de long terme contre les al\u00e9as d\u2019un seul acteur politique, y compris les \u00c9tats-Unis. Le risque en 2026 est que l\u2019escalade des rapports de force constitutionnels transforme cette complexit\u00e9, jusqu\u2019ici g\u00e9rable, en vuln\u00e9rabilit\u00e9 syst\u00e9mique \u2014 au moment m\u00eame o\u00f9 le Canada a besoin d\u2019une strat\u00e9gie coh\u00e9rente et collective pour renforcer son \u00e9conomie et le pays.<\/p>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<div class=\"wp-block-columns has-border-color has-grey-border-color is-layout-flex wp-container-core-columns-is-layout-9ba6dbca wp-block-columns-is-layout-flex\" style=\"border-width:1px\">\n<div class=\"wp-block-column has-border-color has-grey-border-color is-layout-flow wp-block-column-is-layout-flow\" style=\"border-width:1px;flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2026\/01\/Top-Risks-2026-Canada-Edition-Download-PDF-FR_FR-Download-PDF-RBC-TL-5.jpg?quality=80\" alt=\"\" class=\"wp-image-12742\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 id=\"h-telecharger-le-rapport\" class=\"wp-block-heading mar-t mar-l\">T\u00e9l\u00e9charger le rapport<\/h3>\n\n\n\n<div class=\"wp-block-buttons  mar-l is-layout-flex wp-block-buttons-is-layout-flex\"><div>\n<div class=\"wp-block-button btn before is-style-tertiary tertiary\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.rbc.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/Principaux-risques-2026-Canada.pdf\" data-dig-id=\"LP-G\u00e9opolitique,commerceet\u00e9conomie-2087-09519300\" data-dig-category=\"LP-G\u00e9opolitique,commerceet\u00e9conomie\" data-dig-action=\"button click\" data-dig-label=\"T\u00e9l\u00e9charger-https:\/\/www.rbc.com\/en\/wp-content\/uploads\/sites\/4\/2025\/03\/Principaux-risques-2026-Canada.pdf \">T\u00e9l\u00e9charger<\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel mar-t mob-mar-t mar-b mob-mar-b has-rbc-bright-blue-tint-1-background-color has-background\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-t mob-pad-t mob-pad-b pad-b\" style=\"border-radius:0x\">\n<p class=\"mar-b-qtr mob-mar-b-qtr has-white-color has-text-color has-link-color wp-elements-726e37664efef0da9c573a77ccba3fcf wp-block-paragraph\"><strong>Ont contribu\u00e9 au rapport conjoint de Leadership avis\u00e9 RBC et d\u2019Eurasia Group :<\/strong><\/p>\n\n\n\n<p class=\"has-white-color has-text-color has-link-color wp-elements-3e2f9d776958c43083ffc07a15cf8c36 wp-block-paragraph\"><strong>Gerald M. Butts, <\/strong>vice-pr\u00e9sident du Conseil et premier conseiller, Eurasia Group<br><strong>Graeme Thompson, <\/strong>premier analyste et analyste mondial, Macro\u00e9conomie, Eurasia Group<br><strong>John Stackhouse<\/strong>, premier vice-pr\u00e9sident, Leadership avis\u00e9 RBC, Bureau du chef de la direction<br><strong>John Intini, <\/strong>directeur g\u00e9n\u00e9ral principal, R\u00e9daction, Leadership avis\u00e9 RBC<br><strong>Yadullah Hussain,<\/strong> directeur de r\u00e9daction, Leadership avis\u00e9 RBC<br><strong>Jackie Pichette, <\/strong>responsable principale des politiques, Aptitudes et enseignement sup\u00e9rieur, Leadership avis\u00e9 RBC<br><strong>Shaz Merwat,<\/strong> responsable principal des politiques, \u00c9nergie, Leadership avis\u00e9 RBC<br><strong>Lavanya Kaleeswaran,<\/strong> directrice g\u00e9n\u00e9rale, Production et num\u00e9rique, Leadership avis\u00e9 RBC<br><strong>Caprice Biasoni, <\/strong>responsable principale, Conception, Leadership avis\u00e9 RBC<\/p>\n<\/div>\n<\/section>\n<style class=\"advgb-styles-renderer\">@media (min-width:782px){#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(135deg, #070707, #00356300 100%);opacity:1;}}@media (max-width:781px){#tl-fpb-1{background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80&w=4096)!important;background-position:50% 50%!important;background-size:cover!important;min-height:400px!important;}#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(45deg, #070707, #00356300 100%);opacity:1;}}<\/style>","protected":false},"excerpt":{"rendered":"<p>Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.<\/p>\n","protected":false},"author":89,"featured_media":2088,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[78],"tags":[],"rbc_tl_platform":[90],"rbc_tl_newsletter":[],"rbc_tl_content_type":[88],"rbc_tl_author":[102],"class_list":["post-2087","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geopolitique-commerce-et-economie","rbc_tl_platform-le-projet-croissance","rbc_tl_content_type-rapports-denvergure","rbc_tl_author-leadership-avise-rbc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Principaux risques 2026 : Les effets inattendus de la Charte - Leadership avis\u00e9 RBC<\/title>\n<meta name=\"description\" content=\"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Principaux risques 2026 : Les effets inattendus de la Charte\" \/>\n<meta property=\"og:description\" content=\"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/\" \/>\n<meta property=\"og:site_name\" content=\"Leadership avis\u00e9 RBC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rbc\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-02T17:37:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-06T18:22:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"7250\" \/>\n\t<meta property=\"og:image:height\" content=\"3500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lavanyakaleeswaran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Principaux risques 2026 : Les effets inattendus de la Charte\" \/>\n<meta name=\"twitter:creator\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:site\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"lavanyakaleeswaran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/\"},\"author\":{\"name\":\"lavanyakaleeswaran\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/person\\\/cec9995a792157ffbea0c44069edcb32\"},\"headline\":\"Principaux risques 2026 : Les effets inattendus de la Charte\",\"datePublished\":\"2026-02-02T17:37:21+00:00\",\"dateModified\":\"2026-07-06T18:22:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/\"},\"wordCount\":2450,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80\",\"articleSection\":[\"G\u00e9opolitique, commerce et \u00e9conomie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/\",\"name\":\"Principaux risques 2026 : Les effets inattendus de la Charte - Leadership avis\u00e9 RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80\",\"datePublished\":\"2026-02-02T17:37:21+00:00\",\"dateModified\":\"2026-07-06T18:22:46+00:00\",\"description\":\"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80\",\"width\":7250,\"height\":3500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/geopolitique-commerce-et-economie\\\/principaux-risques-2026-les-effets-inattendus-de-la-charte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leadership avis\u00e9 RBC\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Principaux risques 2026 : Les effets inattendus de la Charte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"name\":\"Leadership avis\u00e9 RBC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\",\"name\":\"Leadership avis\u00e9 RBC\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Leadership avis\u00e9 RBC\"},\"alternateName\":\"Leadership avis\u00e9 Banque Royale du Canada\",\"description\":\"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rbc\",\"https:\\\/\\\/x.com\\\/rbcfr\",\"https:\\\/\\\/www.instagram.com\\\/rbcbanqueroyale\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RBC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rbc\\\/\"],\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"Royal Bank of Canada\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Principaux risques 2026 : Les effets inattendus de la Charte - Leadership avis\u00e9 RBC","description":"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/","og_locale":"fr_FR","og_type":"article","og_title":"Principaux risques 2026 : Les effets inattendus de la Charte","og_description":"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.","og_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/","og_site_name":"Leadership avis\u00e9 RBC","article_publisher":"https:\/\/www.facebook.com\/rbc","article_published_time":"2026-02-02T17:37:21+00:00","article_modified_time":"2026-07-06T18:22:46+00:00","og_image":[{"width":7250,"height":3500,"url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","type":"image\/jpeg"}],"author":"lavanyakaleeswaran","twitter_card":"summary_large_image","twitter_title":"Principaux risques 2026 : Les effets inattendus de la Charte","twitter_creator":"@rbcfr","twitter_site":"@rbcfr","twitter_misc":{"Written by":"lavanyakaleeswaran","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/"},"author":{"name":"lavanyakaleeswaran","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/person\/cec9995a792157ffbea0c44069edcb32"},"headline":"Principaux risques 2026 : Les effets inattendus de la Charte","datePublished":"2026-02-02T17:37:21+00:00","dateModified":"2026-07-06T18:22:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/"},"wordCount":2450,"publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","articleSection":["G\u00e9opolitique, commerce et \u00e9conomie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/","name":"Principaux risques 2026 : Les effets inattendus de la Charte - Leadership avis\u00e9 RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","datePublished":"2026-02-02T17:37:21+00:00","dateModified":"2026-07-06T18:22:46+00:00","description":"Les perspectives \u00e9conomiques du Canada sont menac\u00e9es par des chocs externes, des voisins exigeants et un d\u00e9s\u00e9quilibre f\u00e9d\u00e9ral croissant.","breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","width":7250,"height":3500},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/geopolitique-commerce-et-economie\/principaux-risques-2026-les-effets-inattendus-de-la-charte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leadership avis\u00e9 RBC","item":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"},{"@type":"ListItem","position":2,"name":"Principaux risques 2026 : Les effets inattendus de la Charte"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","name":"Leadership avis\u00e9 RBC","description":"","publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/leadership-avise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization","name":"Leadership avis\u00e9 RBC","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/logo\/image\/","url":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","contentUrl":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","width":"1024","height":"1024","caption":"Leadership avis\u00e9 RBC"},"alternateName":"Leadership avis\u00e9 Banque Royale du Canada","description":"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.","sameAs":["https:\/\/www.facebook.com\/rbc","https:\/\/x.com\/rbcfr","https:\/\/www.instagram.com\/rbcbanqueroyale","https:\/\/www.youtube.com\/user\/RBC","https:\/\/www.linkedin.com\/company\/rbc\/"],"parentOrganization":{"@type":"Organization","name":"Royal Bank of Canada","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"}}]}},"author_meta":{"display_name":"lavanyakaleeswaran","author_link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/author\/lavanyakaleeswaran\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/Top-Risks-2026-Canada-Edition-Banner-Image_RISK-5.jpg?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/category\/geopolitique-commerce-et-economie\/\" class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 5 mois il y a","modified":"Mis \u00e0 jour 1 semaine il y a"},"absolute_dates":{"created":"Publi\u00e9 le f\u00e9vrier 2, 2026","modified":"Mise \u00e0 jour le juillet 6, 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le f\u00e9vrier 2, 2026 5:37  ","modified":"Mise \u00e0 jour le juillet 6, 2026 6:22  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/2087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/comments?post=2087"}],"version-history":[{"count":3,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/2087\/revisions"}],"predecessor-version":[{"id":3922,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/2087\/revisions\/3922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media\/2088"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media?parent=2087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/categories?post=2087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/tags?post=2087"},{"taxonomy":"rbc_tl_platform","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_platform?post=2087"},{"taxonomy":"rbc_tl_newsletter","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_newsletter?post=2087"},{"taxonomy":"rbc_tl_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_content_type?post=2087"},{"taxonomy":"rbc_tl_author","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_author?post=2087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}