{"id":1705,"date":"2025-04-28T19:53:47","date_gmt":"2025-04-28T19:53:47","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/tl\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/"},"modified":"2026-06-30T19:28:46","modified_gmt":"2026-06-30T19:28:46","slug":"cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/","title":{"rendered":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia"},"content":{"rendered":"\n<div\n\tid=\"tl-fpb-1\"\n\tstyle=\"background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80&amp;w=4096);background-position:50% 50%;background-size:cover;min-height:500px\" class=\"tl-featured-post-banner wp-block-rbc-thought-leadership-blocks-featured-post-banner\">\n\t\t\t<div class=\"tl-featured-post-banner__gradient\" style=\"position:absolute;top:0;left:0;right:0;bottom:0;z-index:0;pointer-events:none;\"><\/div>\n\t\n\t<div class=\"tl-featured-post-banner__inner\">\n\t\t\t\t<a\n\t\t\tclass=\"tl-pill tl-pill--banner\"\n\t\t\thref=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\"\n\t\t>\n\t\t\t\u00c9nergie\t\t<\/a>\n\t\t\n\t\t<div class=\"tl-featured-post-banner__content\">\n\t\t\t\t\t\t<h2 class=\"tl-featured-post-banner__title\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/\">\n\t\t\t\t\t\tCinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/h2>\n\t\t\t\n\t\t\t\t\t\t<p class=\"tl-featured-post-banner__excerpt\">\n\t\t\t\tShaz Merwat sur les th\u00e8mes les plus pressants du Columbia Global Energy Summit de cette ann\u00e9e.\t\t\t<\/p>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner pad-b-hlf mob-pad-b-hlf\" style=\"border-radius:0x\">\n<p class=\"wp-block-paragraph\">\u00c9nergie. G\u00e9opolitique. Commerce international.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces trois th\u00e8mes \u00e9taient au c\u0153ur des discussions lors du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia la semaine derni\u00e8re. Les droits de douane et les politiques commerciales ont domin\u00e9 le sommet en raison de leurs r\u00e9percussions importantes sur l\u2019offre et la demande d\u2019\u00e9nergie d\u2019Am\u00e9rique du Nord. Shaz Merwat, responsable principal, Politique \u00e9nerg\u00e9tique, Institut d\u2019action climatique RBC, y assistait, et revient sur les cinq enjeux qui ont marqu\u00e9 le sommet de cette ann\u00e9e.<\/p>\n\n\n\n<h3 id=\"h-les-enjeux-energetiques-se-complexifient\" class=\"wp-block-heading\">Les enjeux \u00e9nerg\u00e9tiques se complexifient<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9orientation des \u00e9changes commerciaux dans le but d\u2019atteindre des r\u00e9sultats \u00e9conomiques pr\u00e9cis (r\u00e9duction du d\u00e9ficit commercial, relocalisation de la production) pourrait accentuer les risques li\u00e9s aux prix en fracturant l\u2019\u00e9quilibre entre l\u2019offre et la demande de certaines mati\u00e8res premi\u00e8res essentielles. Il est clair que les droits de douane sur l\u2019acier, l\u2019aluminium et, possiblement, le cuivre \u2013 tous essentiels aux infrastructures \u00e9nerg\u00e9tiques \u2013 entra\u00eenent une diff\u00e9renciation r\u00e9gionale des prix. Comme l\u2019illustre le graphique ci-dessous, les prix de l\u2019aluminium aux \u00c9tats-Unis ont fortement augment\u00e9 par rapport aux prix europ\u00e9ens, une cons\u00e9quence directe des droits de douane impos\u00e9s par l\u2019administration Trump. De mani\u00e8re similaire, l\u2019\u00e9cart entre les prix de l\u2019acier lamin\u00e9 \u00e0 chaud du Midwest am\u00e9ricain (1 075 $ US\/tonne) et ceux du nord de l\u2019Europe (715 $ US\/tonne) a augment\u00e9 pour atteindre environ 360 $ US\/tonne, comparativement \u00e0 150 $ US\/tonne en d\u00e9but d\u2019ann\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized mar-b mob-mar-b\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/05\/Columbia-Energy-Summit-Graphs-04-2048x1026-1.png?quality=80&amp;w=1024\" alt=\"Prix de l&apos;aluminium, derni\u00e8re ann\u00e9e\" class=\"wp-image-6503\" style=\"aspect-ratio:1.996101364522417;width:1170px;height:auto\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sur le plan g\u00e9opolitique, les risques s\u2019\u00e9tendent d\u00e9sormais au-del\u00e0 du simple risque d\u2019approvisionnement en provenance du Moyen-Orient auquel nous sommes confront\u00e9s depuis un demi-si\u00e8cle. Les sph\u00e8res d\u2019influence peuvent red\u00e9finir les dynamiques de l\u2019offre et de la demande, en particulier pour le gaz naturel liqu\u00e9fi\u00e9 et les min\u00e9raux critiques. Ces nouvelles restrictions commerciales \u00e0 motivation politique r\u00e9duisent la capacit\u00e9 des march\u00e9s mondiaux \u00e0 absorber les chocs au chapitre de l\u2019offre ou de la demande, ces chocs \u00e9tant d\u00e9sormais de plus en plus d\u00e9lib\u00e9r\u00e9s dans un contexte de commerce mondial instrumentalis\u00e9 (gaz russe, cha\u00eenes d\u2019approvisionnement chinoises, march\u00e9 am\u00e9ricain).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quelle h\u00e9g\u00e9monie \u00e9nerg\u00e9tique ?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019administration am\u00e9ricaine promettait d\u2019assurer la supr\u00e9matie \u00e9nerg\u00e9tique des \u00c9tats-Unis, mais les faits d\u00e9montrent qu\u2019elle semble avoir fait exactement l\u2019inverse. Au chapitre du p\u00e9trole, les strat\u00e9gies am\u00e9ricaines en mati\u00e8re de droits de douane et d\u2019\u00e9changes commerciaux ont fait tomber les prix sous les niveaux observ\u00e9s pendant la majorit\u00e9 de la pr\u00e9sidence de Joe Biden. Le prix WTI est tomb\u00e9 sous les 60 $ US le baril \u00e0 deux reprises la semaine derni\u00e8re. Ce seuil \u00e9tant consid\u00e9r\u00e9 comme le point d\u2019\u00e9quilibre du gaz de schiste am\u00e9ricain, les producteurs pourraient bien d\u00e9cider de ralentir leurs activit\u00e9s de forage. Selon S&amp;P Global, un prix de 50 $ US le baril pourrait motiver une chute de 1 million de barils par jour de la production am\u00e9ricaine. Pendant ce temps, l\u2019OPEP continue d\u2019augmenter sa production.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large mar-b mob-mar-b\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/05\/Columbia-Energy-Summit-Graphs-05-2048x1064-1.png?quality=80&amp;w=1024\" alt=\"Prix du p\u00e9trole brut WTI, quatre derni\u00e8res ann\u00e9es\" class=\"wp-image-6504\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9sir constant de r\u00e9duire les fonds allou\u00e9s aux programmes et projets en vertu de la loi sur la r\u00e9duction de l\u2019inflation, m\u00eame les cr\u00e9dits d\u2019imp\u00f4t consid\u00e9r\u00e9s comme favorables \u00e0 l\u2019industrie p\u00e9troli\u00e8re (comme les cr\u00e9dits d\u2019imp\u00f4t 45Q pour la capture du carbone), fait aussi obstacle au d\u00e9veloppement des \u00e9nergies renouvelables aux \u00c9tats-Unis. Enfin, les inqui\u00e9tudes concernant l\u2019inflation des co\u00fbts d\u2019approvisionnement (droits de douane sur l\u2019acier et l\u2019aluminium) et l\u2019incertitude g\u00e9n\u00e9rale relative au march\u00e9 et \u00e0 l\u2019\u00e9conomie ont cr\u00e9\u00e9 des conditions particuli\u00e8rement difficiles pour l\u2019investissement de capitaux.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Les frictions commerciales li\u00e9es au climat sont toujours bien pr\u00e9sentes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Avec la lente agonie de l\u2019OMC et les droits de douane \u00ab r\u00e9ciproques \u00bb de Trump, les conditions commerciales pr\u00e9f\u00e9rentielles offertes aux pays en d\u00e9veloppement (taux de douane \u00ab autoris\u00e9s \u00bb plus \u00e9lev\u00e9s) disparaissent. Il faut ajouter le climat \u00e0 la liste des enjeux, car les pays imposent des mesures commerciales li\u00e9es au climat pour renforcer leur comp\u00e9titivit\u00e9 \u00e9conomique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Europe, le m\u00e9canisme d\u2019ajustement au carbone aux fronti\u00e8res (MACF) prot\u00e8ge les politiques climatiques int\u00e9rieures. Aux \u00c9tats-Unis, une taxe sur la pollution aux fronti\u00e8res exploite l\u2019avantage carbone de l\u2019Am\u00e9rique, notamment vis-\u00e0-vis de la Chine. Le Royaume-Uni et l\u2019Australie envisagent de mettre en place leurs propres ajustements carbone aux fronti\u00e8res.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les politiques int\u00e9rieures en mati\u00e8re de carbone sans mesure commerciale climatique (comme le MACF) sont presque certainement vou\u00e9es \u00e0 l\u2019\u00e9chec sur le plan politique. Il semble toutefois peu probable que les pays en d\u00e9veloppement puissent instaurer des prix du carbone s\u2019apparentant \u00e0 ceux du syst\u00e8me d\u2019\u00e9change de droits d\u2019\u00e9mission de carbone de l\u2019Union europ\u00e9enne \u2013 au sein duquel le prix du carbone a augment\u00e9 au cours des deux derni\u00e8res d\u00e9cennies \u2013 en l\u2019espace de seulement quelques ann\u00e9es. Cette situation risque d\u2019accentuer les tensions commerciales li\u00e9es au climat entre le Nord et le Sud.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">R\u00e9duction du d\u00e9ficit commercial<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aux yeux de M. Trump, des droits de douane \u00ab r\u00e9ciproques \u00bb garantissent une relation commerciale \u00e9quilibr\u00e9e. Pour les partenaires commerciaux, une relation commerciale \u00e9quilibr\u00e9e est \u00e0 peu pr\u00e8s tout ce que l\u2019on peut esp\u00e9rer dans la vision de l\u2019\u00ab America First \u00bb (l\u2019Am\u00e9rique d\u2019abord) du pr\u00e9sident am\u00e9ricain. Les partenaires commerciaux seront bien servis s\u2019ils parviennent \u00e0 faire meilleure place aux exportations am\u00e9ricaines de marchandises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le gaz naturel liqu\u00e9fi\u00e9 des \u00c9tats-Unis semble promis \u00e0 un bel avenir. Selon les pr\u00e9visions de RBC March\u00e9s des Capitaux pr\u00e9sent\u00e9es ci-dessous, le pays devrait d\u00e9passer le Qatar et devenir le plus grand exportateur de GNL au monde d\u2019ici 2030. Pour les grands acheteurs de GNL qui affichent d\u2019importants exc\u00e9dents commerciaux avec les \u00c9tats-Unis (l\u2019Union europ\u00e9enne, le Japon, la Cor\u00e9e, l\u2019Inde), l\u2019augmentation de leurs achats de GNL pourrait constituer une strat\u00e9gie gagnante.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized mar-b mob-mar-b\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/fr\/wp-content\/uploads\/sites\/5\/2025\/05\/Columbia-Energy-Summit-Graphs-06-2048x1299-1.png?quality=80&amp;w=1024\" alt=\"Le Qatar maintient l&apos;emprise sur le march\u00e9, mais les \u00c9tats-Unis prend la part du lion en 2030\" class=\"wp-image-6505\" style=\"aspect-ratio:1.5778120184899846;width:1004px;height:auto\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">P\u00f4les d\u2019IA et flux de donn\u00e9es transfronti\u00e8re<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Les pays disposant d\u2019\u00e9lectricit\u00e9 abondante et bon march\u00e9 sont les mieux positionn\u00e9s pour se lancer dans la construction de centres informatiques. Il en r\u00e9sultera probablement des \u00ab p\u00f4les \u00bb d\u2019approvisionnement centr\u00e9s sur la production d\u2019\u00e9nergie renouvelable, compte tenu des engagements climatiques des entreprises technologiques. Il est de plus en plus \u00e9vident que le Canada, les \u00c9tats-Unis et le Moyen-Orient deviendront des p\u00f4les de d\u00e9ploiement de l\u2019intelligence artificielle am\u00e9ricaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais quelles seront les cons\u00e9quences pour les flux de donn\u00e9es ? Le protectionnisme en mati\u00e8re d\u2019h\u00e9bergement (colocation) persistera probablement, mais il faudra s\u2019entendre sur les transferts de donn\u00e9es transfronti\u00e8re r\u00e9sultant des capacit\u00e9s informatiques (centres de donn\u00e9es \u00e0 tr\u00e8s grande \u00e9chelle). Ce sujet devrait revenir sur la table lors de la ren\u00e9gociation de l\u2019Accord \u00c9tats-Unis\u2013Mexique\u2013Canada en 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><strong>Shaz Merwat<\/strong>&nbsp;est responsable principal, Politique \u00e9nerg\u00e9tique, Institut d\u2019action climatique RBC.<\/em><\/p>\n<\/div>\n<\/section>\n<style class=\"advgb-styles-renderer\">@media (min-width:782px){#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(135deg, #070707, #00356300 100%);opacity:1;}}@media (max-width:781px){#tl-fpb-1{background-image:url(https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80&w=4096)!important;background-position:50% 50%!important;background-size:cover!important;min-height:400px!important;}#tl-fpb-1 .tl-featured-post-banner__gradient{background:linear-gradient(45deg, #070707, #00356300 100%);opacity:1;}}<\/style>","protected":false},"excerpt":{"rendered":"<p>Shaz Merwat sur les th\u00e8mes les plus pressants du Columbia Global Energy Summit de cette ann\u00e9e.<\/p>\n","protected":false},"author":79,"featured_media":1706,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"disable_focal_point":true,"featured_image_focal_point":{"x":0.5,"y":0.5},"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[85,49,78],"tags":[],"rbc_tl_platform":[86,84],"rbc_tl_newsletter":[],"rbc_tl_content_type":[77],"rbc_tl_author":[141],"class_list":["post-1705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-action-climatique","category-energie","category-geopolitique-commerce-et-economie","rbc_tl_platform-institut-daction-climatique","rbc_tl_platform-lespace-commercial","rbc_tl_content_type-article","rbc_tl_author-shaz-merwat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia - Leadership avis\u00e9 RBC<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia\" \/>\n<meta property=\"og:description\" content=\"Shaz Merwat sur les th\u00e8mes les plus pressants du Columbia Global Energy Summit de cette ann\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/\" \/>\n<meta property=\"og:site_name\" content=\"Leadership avis\u00e9 RBC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rbc\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T19:53:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T19:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"amandeepsingh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:site\" content=\"@rbcfr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"amandeepsingh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/\"},\"author\":{\"name\":\"amandeepsingh\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/person\\\/db529602099a2ded312dbdba2faeec36\"},\"headline\":\"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia\",\"datePublished\":\"2025-04-28T19:53:47+00:00\",\"dateModified\":\"2026-06-30T19:28:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/\"},\"wordCount\":1233,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80\",\"articleSection\":[\"Action climatique\",\"\u00c9nergie\",\"G\u00e9opolitique, commerce et \u00e9conomie\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/\",\"name\":\"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia - Leadership avis\u00e9 RBC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80\",\"datePublished\":\"2025-04-28T19:53:47+00:00\",\"dateModified\":\"2026-06-30T19:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80\",\"width\":2560,\"height\":1236,\"caption\":\"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/energie\\\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Leadership avis\u00e9 RBC\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"name\":\"Leadership avis\u00e9 RBC\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#organization\",\"name\":\"Leadership avis\u00e9 RBC\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/tl\\\/wp-content\\\/uploads\\\/sites\\\/28\\\/2026\\\/06\\\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"Leadership avis\u00e9 RBC\"},\"alternateName\":\"Leadership avis\u00e9 Banque Royale du Canada\",\"description\":\"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rbc\",\"https:\\\/\\\/x.com\\\/rbcfr\",\"https:\\\/\\\/www.instagram.com\\\/rbcbanqueroyale\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/RBC\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/rbc\\\/\"],\"parentOrganization\":{\"@type\":\"Organization\",\"name\":\"Royal Bank of Canada\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/leadership-avise\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia - Leadership avis\u00e9 RBC","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/","og_locale":"fr_FR","og_type":"article","og_title":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia","og_description":"Shaz Merwat sur les th\u00e8mes les plus pressants du Columbia Global Energy Summit de cette ann\u00e9e.","og_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/","og_site_name":"Leadership avis\u00e9 RBC","article_publisher":"https:\/\/www.facebook.com\/rbc","article_published_time":"2025-04-28T19:53:47+00:00","article_modified_time":"2026-06-30T19:28:46+00:00","og_image":[{"width":2560,"height":1236,"url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","type":"image\/jpeg"}],"author":"amandeepsingh","twitter_card":"summary_large_image","twitter_creator":"@rbcfr","twitter_site":"@rbcfr","twitter_misc":{"Written by":"amandeepsingh","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/"},"author":{"name":"amandeepsingh","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/person\/db529602099a2ded312dbdba2faeec36"},"headline":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia","datePublished":"2025-04-28T19:53:47+00:00","dateModified":"2026-06-30T19:28:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/"},"wordCount":1233,"publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","articleSection":["Action climatique","\u00c9nergie","G\u00e9opolitique, commerce et \u00e9conomie"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/","name":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia - Leadership avis\u00e9 RBC","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","datePublished":"2025-04-28T19:53:47+00:00","dateModified":"2026-06-30T19:28:46+00:00","breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","width":2560,"height":1236,"caption":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/energie\/cinq-points-a-retenir-du-global-energy-summit-2025-de-luniversite-columbia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Leadership avis\u00e9 RBC","item":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"},{"@type":"ListItem","position":2,"name":"Cinq points \u00e0 retenir du Global Energy Summit 2025 de l\u2019Universit\u00e9 Columbia"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#website","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","name":"Leadership avis\u00e9 RBC","description":"","publisher":{"@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/leadership-avise\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#organization","name":"Leadership avis\u00e9 RBC","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/leadership-avise\/#\/schema\/logo\/image\/","url":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","contentUrl":"https:\/\/www.rbc.com\/fr\/tl\/wp-content\/uploads\/sites\/28\/2026\/06\/rbc-logo-shield_b9cb35.svg?quality=80&w=1024","width":"1024","height":"1024","caption":"Leadership avis\u00e9 RBC"},"alternateName":"Leadership avis\u00e9 Banque Royale du Canada","description":"Le leadership avis\u00e9 de RBC fournit des renseignements essentiels pour aider les entreprises, les d\u00e9cideurs politiques et les communaut\u00e9s \u00e0 prendre des d\u00e9cisions \u00e9clair\u00e9es dans un monde en \u00e9volution. Des changements g\u00e9opolitiques \u00e0 la croissance et \u00e0 la productivit\u00e9 canadiennes, en passant par les technologies de rupture et l'avenir des comp\u00e9tences, nos recherches sont con\u00e7ues pour fournir des informations significatives qui peuvent contribuer \u00e0 la prosp\u00e9rit\u00e9 de tous les Canadiens.","sameAs":["https:\/\/www.facebook.com\/rbc","https:\/\/x.com\/rbcfr","https:\/\/www.instagram.com\/rbcbanqueroyale","https:\/\/www.youtube.com\/user\/RBC","https:\/\/www.linkedin.com\/company\/rbc\/"],"parentOrganization":{"@type":"Organization","name":"Royal Bank of Canada","url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/"}}]}},"author_meta":{"display_name":"amandeepsingh","author_link":"https:\/\/www.rbc.com\/fr\/leadership-avise\/author\/amandeepsingh\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-content\/uploads\/sites\/28\/2026\/06\/DL-Blog-Image-Template-BLANK_Banner-wide-JPEG_Banner-wide-scaled-2.jpg?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/category\/action-climatique\/\" class=\"advgb-post-tax-term\">Action climatique<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/category\/energie\/\" class=\"advgb-post-tax-term\">\u00c9nergie<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/category\/geopolitique-commerce-et-economie\/\" class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Action climatique<\/span>","<span class=\"advgb-post-tax-term\">\u00c9nergie<\/span>","<span class=\"advgb-post-tax-term\">G\u00e9opolitique, commerce et \u00e9conomie<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 1 an il y a","modified":"Mis \u00e0 jour 2 semaines il y a"},"absolute_dates":{"created":"Publi\u00e9 le avril 28, 2025","modified":"Mise \u00e0 jour le juin 30, 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le avril 28, 2025 7:53  ","modified":"Mise \u00e0 jour le juin 30, 2026 7:28  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/1705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/users\/79"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/comments?post=1705"}],"version-history":[{"count":3,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/1705\/revisions"}],"predecessor-version":[{"id":3729,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/posts\/1705\/revisions\/3729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media\/1706"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/media?parent=1705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/categories?post=1705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/tags?post=1705"},{"taxonomy":"rbc_tl_platform","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_platform?post=1705"},{"taxonomy":"rbc_tl_newsletter","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_newsletter?post=1705"},{"taxonomy":"rbc_tl_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_content_type?post=1705"},{"taxonomy":"rbc_tl_author","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/leadership-avise\/wp-json\/wp\/v2\/rbc_tl_author?post=1705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}