{"id":411,"date":"2022-09-14T04:00:00","date_gmt":"2022-09-14T04:00:00","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/economique\/2022\/09\/14\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/"},"modified":"2022-09-14T04:00:00","modified_gmt":"2022-09-14T04:00:00","slug":"preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/","title":{"rendered":"<b>Point cl\u00e9 :<\/b> l&rsquo;essor des services dans le commerce des biens au Canada"},"content":{"rendered":"<ul class=\"disc pad-l\">\n<li>Les services sont en passe de devenir un \u00e9l\u00e9ment essentiel des biens manufactur\u00e9s au Canada, ce qui laisse entendre qu\u2019une impulsion pour revitaliser le secteur manufacturier du pays pourrait acc\u00e9l\u00e9rer les \u00e9changes de biens et de services.<\/li>\n<li>Prenons, par exemple, le secteur de l\u2019automobile. Pr\u00e8s de 40 % des valeurs ajout\u00e9es d\u2019exportations proviennent maintenant des services (comme la conception du v\u00e9hicule ou du logiciel qu\u2019il transporte), soit une hausse de 8 % par rapport au milieu des ann\u00e9es 1990.<\/li>\n<li>Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.<\/li>\n<li>Pourtant, pr\u00e8s de la moiti\u00e9 des services int\u00e9gr\u00e9s \u00e0 nos exportations de biens proviennent de l\u2019ext\u00e9rieur du pays, notamment en raison de la forte participation \u00e9trang\u00e8re dans le secteur manufacturier canadien.<\/li>\n<li><b>Conclusion :<\/b> comme le Canada est associ\u00e9 \u00e0 des partenaires dans les cha\u00eenes logistiques r\u00e9gionales, le contenu des services dans le commerce des marchandises ne peut \u00eatre ignor\u00e9. L\u2019\u00e9largissement de notre empreinte dans ce domaine pourrait profiter \u00e0 un \u00e9ventail de secteurs.<\/li>\n<\/ul>\n<hr \/>\n<h4>Les services sont plus importants que jamais pour les cha\u00eenes logistiques canadiennes<\/h4>\n<p>La fa\u00e7on traditionnelle de mesurer le commerce est d\u2019utiliser les exportations brutes. Et selon ce param\u00e8tre, les services repr\u00e9sentent moins d\u2019un cinqui\u00e8me de l\u2019ensemble des \u00e9changes commerciaux. Toutefois, lorsque la valeur ajout\u00e9e int\u00e9rieure des exportations canadiennes est \u00e9valu\u00e9e, la part du secteur des services passe \u00e0 la moiti\u00e9. Parmi les facteurs \u00e0 l\u2019origine de cette hausse, il y a la \u00ab servicification \u00bb de la fabrication, c\u2019est-\u00e0-dire la d\u00e9pendance croissante du secteur manufacturier \u00e0 l\u2019\u00e9gard des intrants de services comme les logiciels, la conception et autres. Les ventes de services regroup\u00e9s avec des biens, comme l\u2019installation, le service et l\u2019entretien continus, augmentent \u00e9galement.<\/p>\n<p>La base de donn\u00e9es de l\u2019OCDE sur la valeur ajout\u00e9e au commerce (TiVA) montre que les services repr\u00e9sentaient 34 % de la valeur ajout\u00e9e des exportations de produits manufactur\u00e9s du Canada en 2018, comparativement \u00e0 28 % en 1995. Les services commerciaux, le transport et l\u2019entreposage, les services financiers et d\u2019assurance, les services juridiques, comptables, publicitaires, architecturaux, techniques et de conception, et les services administratifs et de soutien, repr\u00e9sentent tous des liens croissants dans les cha\u00eenes logistiques de fabrication.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38514\" src=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/03\/Services-trade-PP-charts_v3-FR_Services-are-crucial_1200px.png\" alt=\"\" width=\"1201\" height=\"628\" \/><\/p>\n<p>Ils sont aussi essentiels \u00e0 l\u2019emploi. Statistique Canada estime que les exportations de produits manufactur\u00e9s soutiennent indirectement plus de 800 000 emplois, dont la plupart sont dans le secteur des services. Et avec des donn\u00e9es professionnelles sugg\u00e9rant qu\u2019environ quatre employ\u00e9s du secteur manufacturier sur dix exercent des activit\u00e9s de services, une part consid\u00e9rable des 650 000 emplois du secteur manufacturier directement li\u00e9s aux exportations sont en fait des postes de services. Ces emplois prendront de plus en plus d\u2019importance \u00e0 mesure que l\u2019intelligence artificielle, la robotique et l\u2019apprentissage automatique constitueront le moteur des usines de l\u2019avenir.<\/p>\n<p>On peut en d\u00e9duire que les avantages d\u2019une production int\u00e9rieure revigor\u00e9e, par le d\u00e9veloppement de cha\u00eenes logistiques dans des secteurs \u00e9mergents, innovants et en rapide expansion comme les technologies propres et les v\u00e9hicules \u00e9lectriques, pourraient s\u2019\u00e9tendre bien au-del\u00e0 du commerce des biens.<\/p>\n<h4>La plupart des services offerts avec nos produits ne sont pas r\u00e9alis\u00e9s au Canada<\/h4>\n<p>L\u2019internationalisation des services au sein des cha\u00eenes de valeur mondiales s\u2019est envol\u00e9e dans les \u00e9conomies de l\u2019OCDE, les fabricants s\u2019approvisionnant de plus en plus en services \u00e0 l\u2019\u00e9tranger. Au Canada, le secteur manufacturier a connu une croissance, tant en ce qui concerne les services produits au pays que ceux import\u00e9s. Mais ce sont les services provenant de l\u2019ext\u00e9rieur de nos fronti\u00e8res qui sont responsables de l\u2019augmentation de la valeur ajout\u00e9e des services au cours des derni\u00e8res ann\u00e9es. En fait, parmi les \u00e9conomies du G7, le secteur manufacturier du Canada est le plus d\u00e9pendant des services \u00e9trangers, et il a la plus faible proportion de services nationaux dans ses exportations.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38515\" src=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/03\/Services-trade-PP-charts_v3-FR_Services-content_1200px.png\" alt=\"\" width=\"1201\" height=\"628\" \/><\/p>\n<p>Cela est en partie attribuable \u00e0 la pr\u00e9sence importante d\u2019entreprises multinationales \u00e9trang\u00e8res au Canada, qui repr\u00e9sentent pr\u00e8s des deux tiers de nos exportations de produits manufactur\u00e9s. Ces entreprises canadiennes affili\u00e9es importent des services \u00e0 partir de leur soci\u00e9t\u00e9 m\u00e8re et tirent probablement parti des relations de cette derni\u00e8re avec des soci\u00e9t\u00e9s de services \u00e9trang\u00e8res.<\/p>\n<p>En effet, les sous-secteurs manufacturiers domin\u00e9s par les multinationales \u00e9trang\u00e8res ont tendance \u00e0 compter davantage sur les intrants import\u00e9s que sur les intrants nationaux de services. Par exemple, les multinationales \u00e9trang\u00e8res repr\u00e9sentent plus de 80 % des exportations canadiennes dans le secteur de la fabrication de mat\u00e9riels de transport et de m\u00e9taux de base, secteurs qui fournissent plus de la moiti\u00e9 de leurs intrants de services \u00e0 l\u2019\u00e9tranger.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-38513\" src=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/03\/Services-trade-PP-charts_v3-FR_Canadian-factories_1200px.png\" alt=\"\" width=\"1201\" height=\"628\" \/><\/p>\n<h4>Les liens commerciaux \u00e9troits avec les \u00c9tats-Unis rendent difficile l\u2019am\u00e9lioration du contenu des services<\/h4>\n<p>Les relations commerciales \u00e9troites entre le Canada et les \u00c9tats-Unis pourraient freiner l\u2019accroissement de notre contribution au commerce des biens. Les \u00c9tats-Unis ont le contenu \u00e9tranger le plus faible dans leurs exportations de produits manufactur\u00e9s entre les pays de l\u2019OCDE, ce qui est conforme \u00e0 la part n\u00e9gligeable de propri\u00e9t\u00e9 \u00e9trang\u00e8re dans le secteur.<\/p>\n<p>Pour ce qui est des services comme le transport terrestre, l\u2019entreposage, les finances et l\u2019assurance, les usines canadiennes s\u2019appuient principalement sur les fournisseurs nationaux. Mais elles font davantage appel \u00e0 des entreprises \u00e9trang\u00e8res pour les services professionnels, scientifiques et techniques, administratifs et de soutien, et les services de programmation informatique, de conseil et d\u2019information. Il s\u2019agit de secteurs dans lesquels le Canada dispose de nombreuses capacit\u00e9s.<\/p>\n<p>Et comme une grande partie de la valeur ajout\u00e9e de la production de biens et des exportations provient du secteur des services, ces liens essentiels des cha\u00eenes logistiques ne peuvent \u00eatre ignor\u00e9s. Par exemple, le secteur florissant des v\u00e9hicules \u00e9lectriques au Canada s\u2019est surtout concentr\u00e9 sur la r\u00e9tention des activit\u00e9s d\u2019assemblage, l\u2019optimisation des investissements dans la production de batteries et d\u2019autres segments de la cha\u00eene logistique physique. C\u2019est manifestement une priorit\u00e9, mais nous ne devrions pas perdre de vue le fait que pr\u00e8s de 40 % de la valeur ajout\u00e9e des exportations d\u2019automobiles provient des services.<\/p>\n<p>Le simple fait de reproduire la cha\u00eene logistique de services actuelle du secteur de l\u2019automobile pourrait laisser les entreprises de services canadiennes \u00e0 l\u2019\u00e9cart d\u2019une industrie des v\u00e9hicules \u00e9lectriques en pleine croissance.<\/p>\n<p>Les services devraient \u00eatre une priorit\u00e9 au Canada pour attirer les investissements<\/p>\n<p>La pr\u00e9sence importante de services dans le commerce des biens au Canada semble indiquer que le secteur est plus expos\u00e9 qu\u2019on le croit \u00e0 des retournements de tendance dans les \u00e9changes. Il y a de nombreux probl\u00e8mes qui poussent \u00e0 repenser les cha\u00eenes logistiques mondialis\u00e9es, notamment les goulots d\u2019\u00e9tranglement dans les transports, la fiabilit\u00e9 de l\u2019approvisionnement en intrants, les pr\u00e9occupations concernant la s\u00e9curit\u00e9 nationale et la d\u00e9pendance \u00e0 l\u2019\u00e9gard d\u2019entreprises \u00e9trang\u00e8res, et le leadership dans les technologies \u00e9mergentes. Toutefois, cela s\u2019applique non seulement \u00e0 la circulation physique des biens, mais aussi aux services qu\u2019ils contiennent.<\/p>\n<p>Le Canada et ses partenaires commerciaux adoptent des politiques industrielles de fa\u00e7on proactive pour d\u00e9velopper le secteur manufacturier du pays. La r\u00e9cente loi am\u00e9ricaine sur la r\u00e9duction de l\u2019inflation comprend un volet de plus de 60 milliards de dollars am\u00e9ricains pour appuyer les industries de transformation propres. Alors que les d\u00e9cideurs r\u00e9fl\u00e9chissent \u00e0 la relocalisation strat\u00e9gique ou au partenariat avec leurs alli\u00e9s dans les cha\u00eenes logistiques r\u00e9gionales, les services int\u00e9gr\u00e9s dans les exportations de marchandises doivent \u00eatre \u00e9galement un \u00e9l\u00e9ment cl\u00e9. Cela signifie que les gouvernements devraient consid\u00e9rer les liens des cha\u00eenes logistiques dans leur ensemble lorsqu\u2019ils \u00e9valuent le soutien aux fabricants. Et les efforts visant \u00e0 promouvoir les entreprises locales pourraient se r\u00e9v\u00e9ler encore plus payants si ces derni\u00e8res s\u2019associent davantage \u00e0 des fournisseurs de services nationaux qu\u2019\u00e0 des entreprises \u00e9trang\u00e8res.<\/p>\n<p>\u00a0<\/p>\n<hr \/>\n<p><em><b>Josh Nye<\/b> s\u2019est joint aux Services \u00e9conomiques RBC en 2012, \u00e0 titre d\u2019\u00e9conomiste. Il est titulaire d\u2019un baccalaur\u00e9at \u00e8s arts (avec distinction) en \u00e9conomie de l\u2019Universit\u00e9 Western Ontario et d\u2019une ma\u00eetrise en \u00e9conomie de la London School of Economics.<\/em><\/p>\n<p><em><b>Naomi Powell<\/b> s\u2019est jointe au groupe Leadership avis\u00e9 RBC en 2020. Elle est responsable de l\u2019\u00e9dition et de la r\u00e9daction d\u2019articles pour les groupes Services \u00e9conomiques RBC et Leadership avis\u00e9 RBC. Avant de se joindre \u00e0 RBC, elle a travaill\u00e9 comme journaliste \u00e9conomique au Canada et en Europe, et, plus r\u00e9cemment, elle a r\u00e9alis\u00e9 des reportages sur le commerce international et l\u2019\u00e9conomie pour le Financial Post.<\/em><\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.<\/p>\n","protected":false},"author":268,"featured_media":401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[77,71,79],"tags":[46],"rbc_econ_content_type":[],"class_list":["post-411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse-en-vedette","category-analyse-pour-le-canada","category-perspectives","tag-preuve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Point cl\u00e9 : l&#039;essor des services dans le commerce des biens au Canada - RBC Economique<\/title>\n<meta name=\"description\" content=\"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Point cl\u00e9 : l&#039;essor des services dans le commerce des biens au Canada\" \/>\n<meta property=\"og:description\" content=\"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Economique\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-14T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"7251\" \/>\n\t<meta property=\"og:image:height\" content=\"3501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Josh Nye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josh Nye\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/\"},\"author\":{\"name\":\"Josh Nye\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/d44e5d2581cf957836ba7d1ef4af6528\"},\"headline\":\"Point cl\u00e9 : l&rsquo;essor des services dans le commerce des biens au Canada\",\"datePublished\":\"2022-09-14T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/\"},\"wordCount\":1515,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Proof-Point_Banner-wide-2.png?quality=80\",\"keywords\":[\"Preuve\"],\"articleSection\":[\"Analyse en vedette\",\"Analyse pour le Canada\",\"Perspectives\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/\",\"name\":\"Point cl\u00e9 : l'essor des services dans le commerce des biens au Canada - RBC Economique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Proof-Point_Banner-wide-2.png?quality=80\",\"datePublished\":\"2022-09-14T04:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/d44e5d2581cf957836ba7d1ef4af6528\"},\"description\":\"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Proof-Point_Banner-wide-2.png?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Proof-Point_Banner-wide-2.png?quality=80\",\"width\":7251,\"height\":3501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Point cl\u00e9 : l&rsquo;essor des services dans le commerce des biens au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\",\"name\":\"RBC Economique\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/d44e5d2581cf957836ba7d1ef4af6528\",\"name\":\"Josh Nye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g\",\"caption\":\"Josh Nye\"},\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/author\\\/josh-nye\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Point cl\u00e9 : l'essor des services dans le commerce des biens au Canada - RBC Economique","description":"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/","og_locale":"fr_FR","og_type":"article","og_title":"Point cl\u00e9 : l'essor des services dans le commerce des biens au Canada","og_description":"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.","og_url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/","og_site_name":"RBC Economique","article_published_time":"2022-09-14T04:00:00+00:00","og_image":[{"width":7251,"height":3501,"url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","type":"image\/png"}],"author":"Josh Nye","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Josh Nye","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/"},"author":{"name":"Josh Nye","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/d44e5d2581cf957836ba7d1ef4af6528"},"headline":"Point cl\u00e9 : l&rsquo;essor des services dans le commerce des biens au Canada","datePublished":"2022-09-14T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/"},"wordCount":1515,"commentCount":0,"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","keywords":["Preuve"],"articleSection":["Analyse en vedette","Analyse pour le Canada","Perspectives"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/","url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/","name":"Point cl\u00e9 : l'essor des services dans le commerce des biens au Canada - RBC Economique","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","datePublished":"2022-09-14T04:00:00+00:00","author":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/d44e5d2581cf957836ba7d1ef4af6528"},"description":"Et environ 40 % des emplois manufacturiers li\u00e9s aux exportations de biens sont en fait des postes concernant des services.","breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","width":7251,"height":3501},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/preuve-lessor-des-services-dans-le-commerce-des-biens-au-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rbc.com\/fr\/economique\/"},{"@type":"ListItem","position":2,"name":"Point cl\u00e9 : l&rsquo;essor des services dans le commerce des biens au Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/economique\/#website","url":"https:\/\/www.rbc.com\/fr\/economique\/","name":"RBC Economique","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/economique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/d44e5d2581cf957836ba7d1ef4af6528","name":"Josh Nye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e5e3c5f9262b2b78b019886ca43dc22ea5c8e9cb105daadb22698d5224d4f1?s=96&d=mm&r=g","caption":"Josh Nye"},"url":"https:\/\/www.rbc.com\/fr\/economique\/author\/josh-nye\/"}]}},"author_meta":{"display_name":"Josh Nye","author_link":"https:\/\/www.rbc.com\/fr\/economique\/author\/josh-nye\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Proof-Point_Banner-wide-2.png?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/\" class=\"advgb-post-tax-term\">Analyse en vedette<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/\" class=\"advgb-post-tax-term\">Analyse pour le Canada<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">Perspectives<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Analyse en vedette<\/span>","<span class=\"advgb-post-tax-term\">Analyse pour le Canada<\/span>","<span class=\"advgb-post-tax-term\">Perspectives<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">Preuve<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Preuve<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 4 ans il y a","modified":"Mis \u00e0 jour 4 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 14 septembre 2022","modified":"Mise \u00e0 jour le 14 septembre 2022"},"absolute_dates_time":{"created":"Publi\u00e9 le 14 septembre 2022 4:00  ","modified":"Mise \u00e0 jour le 14 septembre 2022 4:00  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/users\/268"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/comments?post=411"}],"version-history":[{"count":0,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media\/401"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media?parent=411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/categories?post=411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/tags?post=411"},{"taxonomy":"rbc_econ_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/rbc_econ_content_type?post=411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}