{"id":3666,"date":"2026-02-06T17:31:58","date_gmt":"2026-02-06T17:31:58","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/economique\/?p=3666"},"modified":"2026-02-09T15:15:41","modified_gmt":"2026-02-09T15:15:41","slug":"fr","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/","title":{"rendered":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada"},"content":{"rendered":"\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<p>Les conditions de l\u2019offre et de la demande se sont encore affaiblies dans la plupart des grands march\u00e9s canadiens en janvier.<\/p>\n\n\n\n<p>Les acheteurs potentiels sont demeur\u00e9s prudents, malgr\u00e9 les stocks \u00e9lev\u00e9s qui leur donnent l\u2019avantage. Les conditions m\u00e9t\u00e9orologiques hivernales extr\u00eames ont probablement contribu\u00e9 au ralentissement, les pr\u00e9cipitations importantes dans plusieurs r\u00e9gions ayant maintenu les acheteurs potentiels \u00e0 l\u2019\u00e9cart.<\/p>\n\n\n\n<p>Les tendances r\u00e9centes de l\u2019activit\u00e9 ont \u00e9galement \u00e9t\u00e9 brouill\u00e9es par les distorsions du calendrier. Le nombre de jours ouvrables en janvier&nbsp;2026 \u00e9tait plus \u00e9lev\u00e9 qu\u2019il y a un an, tandis qu\u2019en d\u00e9cembre, ce nombre correspondait exceptionnellement \u00e0 celui de janvier, ce qui se produit rarement et qui a probablement accentu\u00e9 les tendances.<\/p>\n\n\n\n<p>La demande a n\u00e9anmoins chut\u00e9 dans plusieurs march\u00e9s, en particulier \u00e0 Vancouver et dans la vall\u00e9e du Fraser, et les r\u00e9sultats ont \u00e9t\u00e9 nettement d\u00e9cevants \u00e0 Edmonton, \u00e0 Winnipeg et \u00e0 Saskatoon. Les march\u00e9s de Toronto et de Montr\u00e9al ont \u00e9galement continu\u00e9 de ralentir. Calgary et Regina figurent parmi les rares exceptions o\u00f9 on a constat\u00e9 une augmentation des achats. <\/p>\n\n\n\n<p>Les stocks ont toutefois continu\u00e9 d\u2019augmenter dans la plupart des r\u00e9gions, ce qui a pes\u00e9 sur les prix. Plusieurs march\u00e9s ont enregistr\u00e9 les plus fortes baisses de prix sur 12&nbsp;mois depuis des ann\u00e9es.<\/p>\n\n\n\n<div id=\"everviz-hgb8BZiMk\" class=\"everviz-hgb8BZiMk\" data-view=\"graph\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-rbc-bright-blue-color has-text-color has-link-color wp-elements-d7a2d24b61fac1a6797958129908e1da\" id=\"h-region-de-toronto-nbsp-le-marche-n-est-pas-encore-en-declin\">R\u00e9gion de Toronto&nbsp;: le march\u00e9 n\u2019est pas encore en d\u00e9clin<\/h4>\n\n\n\n<p>Les donn\u00e9es de janvier ont r\u00e9v\u00e9l\u00e9 une faiblesse persistante dans la r\u00e9gion du Grand Toronto, les ventes ayant diminu\u00e9 de 9,9&nbsp;% par rapport \u00e0 d\u00e9cembre, en donn\u00e9es d\u00e9saisonnalis\u00e9es.<\/p>\n\n\n\n<p>Le repli prolonge les conditions difficiles qui ont caract\u00e9ris\u00e9 2025 et repr\u00e9sente la quatri\u00e8me baisse mensuelle cons\u00e9cutive et la plus forte contraction de ce type en pr\u00e8s d\u2019un an.<\/p>\n\n\n\n<p>Les conditions m\u00e9t\u00e9orologiques hivernales extr\u00eames Ontario, dont l\u2019une des plus importantes temp\u00eates de neige depuis des ann\u00e9es, ont probablement contribu\u00e9 \u00e0 freiner l\u2019activit\u00e9, car la faiblesse des conditions du march\u00e9 a rendu les acheteurs potentiels peu press\u00e9s de s\u2019aventurer.<\/p>\n\n\n\n<p>Les nouvelles inscriptions ont l\u00e9g\u00e8rement augment\u00e9 (1,1&nbsp;%, en donn\u00e9es d\u00e9saisonnalis\u00e9es), ce qui a gonfl\u00e9 les stocks disponibles. La croissance des inscriptions actives sur 12&nbsp;mois a ralenti au cours des derniers mois, mais les stocks demeurent obstin\u00e9ment \u00e9lev\u00e9s par rapport aux normes historiques.<\/p>\n\n\n\n<p>Les conditions de l\u2019offre et de la demande continuent de favoriser les acheteurs, ce qui maintient les pressions \u00e0 la baisse sur les prix. L\u2019indice compos\u00e9 MLS des prix des propri\u00e9t\u00e9s a maintenu sa tendance \u00e0 la baisse en janvier, reculant de 8&nbsp;% par rapport \u00e0 l\u2019an dernier. Il s\u2019agit de la 22<sup>e<\/sup> baisse cons\u00e9cutive et de la plus forte diminution en trois ans.<\/p>\n\n\n\n<div id=\"everviz-0ypPKSe69\" class=\"everviz-0ypPKSe69\" data-view=\"graph\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-rbc-bright-blue-color has-text-color has-link-color wp-elements-015ea7a94a780528dc46b22235145250\" id=\"h-region-de-montreal-nbsp-le-ralentissement-se-poursuit-en-janvier\">R\u00e9gion de Montr\u00e9al&nbsp;: le ralentissement se poursuit en janvier<\/h4>\n\n\n\n<p>Le ralentissement constat\u00e9 \u00e0 la fin de 2025 dans la r\u00e9gion de Montr\u00e9al a persist\u00e9 en janvier. Nous estimons que les ventes ont diminu\u00e9 de 1,4&nbsp;% par rapport \u00e0 d\u00e9cembre, en donn\u00e9es d\u00e9saisonnalis\u00e9es, mais un afflux important de nouvelles inscriptions, attribuable principalement aux copropri\u00e9t\u00e9s, r\u00e9\u00e9quilibre enfin le march\u00e9. Pour la premi\u00e8re fois depuis des mois, le ratio ventes\/nouvelles inscriptions a atteint l\u2019\u00e9quilibre.<\/p>\n\n\n\n<p>Ce changement freine d\u00e9j\u00e0 la croissance des prix. Les prix m\u00e9dians des maisons unifamiliales ont diminu\u00e9, les gains annuels passant de 7,8&nbsp;% en d\u00e9cembre \u00e0 environ la moiti\u00e9 de ce chiffre en janvier, \u00e0 mesure que le march\u00e9 s\u2019\u00e9quilibre. L\u2019appr\u00e9ciation des prix des copropri\u00e9t\u00e9s demeure la plus lente des trois types de propri\u00e9t\u00e9s, le prix m\u00e9dian ayant augment\u00e9 de 2&nbsp;% par rapport \u00e0 l\u2019an dernier.<\/p>\n\n\n\n<p>Malgr\u00e9 l\u2019augmentation de l\u2019offre en janvier, les inscriptions actives demeurent relativement faibles, ce qui limite le choix des acheteurs. Les stocks limit\u00e9s permettront sans doute une plus grande appr\u00e9ciation des prix au cours de la prochaine ann\u00e9e, car la confiance des acheteurs se raffermit lentement.<\/p>\n\n\n\n<div id=\"everviz-Ur7NA_LLo\" class=\"everviz-Ur7NA_LLo\" data-view=\"graph\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-rbc-bright-blue-color has-text-color has-link-color wp-elements-4485839cbe7ddf75a810fb99222c3cd8\" id=\"h-region-de-vancouver-nbsp-le-repli-marque-interrompt-l-elan-du-quatrieme-trimestre\">R\u00e9gion de Vancouver&nbsp;: le repli marqu\u00e9 interrompt l\u2019\u00e9lan du quatri\u00e8me trimestre<\/h4>\n\n\n\n<p>La s\u00e9rie d\u2019am\u00e9liorations constat\u00e9es au cours des derniers mois sur le march\u00e9 de Vancouver s\u2019est arr\u00eat\u00e9e en janvier.<\/p>\n\n\n\n<p>Les ventes ont chut\u00e9 de pr\u00e8s de 30&nbsp;% par rapport \u00e0 d\u00e9cembre, en donn\u00e9es d\u00e9saisonnalis\u00e9es, effa\u00e7ant trois mois cons\u00e9cutifs de gains modestes, ce qui montre \u00e0 quel point la r\u00e9cente am\u00e9lioration avait \u00e9t\u00e9 fragile. M\u00eame si les facteurs de d\u00e9saisonnalisation peuvent exacerber une partie de la faiblesse, la situation sous-jacente demeure r\u00e9solument difficile.<\/p>\n\n\n\n<p>Les reventes demeurent nettement inf\u00e9rieures \u00e0 la moyenne saisonni\u00e8re sur 10&nbsp;ans, tandis que les inscriptions sont nettement sup\u00e9rieures aux normes historiques. C\u2019est une combinaison qui continue de renforcer le pouvoir de n\u00e9gociation des acheteurs et qui maintient la tendance \u00e0 la baisse des prix. L\u2019IPP&nbsp;MLS du Grand Vancouver a recul\u00e9 de 5,7&nbsp;% sur 12&nbsp;mois en janvier, marquant pr\u00e8s d\u2019une ann\u00e9e de baisses annuelles.<\/p>\n\n\n\n<p>On a vu des signes provisoires de stabilisation \u00e0 la fin de 2025, mais le march\u00e9 continue de faire face \u00e0 une faible abordabilit\u00e9 et \u00e0 une offre \u00e9lev\u00e9e par rapport \u00e0 la demande des acheteurs. Selon nous, cette dynamique maintiendra les prix relativement bas au cours des prochains mois.<\/p>\n\n\n\n<div id=\"everviz-rxEZYnay-\" class=\"everviz-rxEZYnay-\" data-view=\"graph\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-rbc-bright-blue-color has-text-color has-link-color wp-elements-5fa0dcad63c1fbaa882b23283b535588\" id=\"h-calgary-nbsp-la-domination-de-l-offre-se-poursuit\">Calgary&nbsp;: la domination de l\u2019offre se poursuit<\/h4>\n\n\n\n<p>\u00c0 Calgary, les ventes ont augment\u00e9 de 7,3&nbsp;% en janvier par rapport \u00e0 d\u00e9cembre, en donn\u00e9es d\u00e9saisonnalis\u00e9es, une hausse notable apr\u00e8s une fin d\u2019ann\u00e9e&nbsp;2025 calme.<\/p>\n\n\n\n<p>Les gains ont toutefois \u00e9t\u00e9 \u00e9clips\u00e9s par un bond encore plus important des nouvelles inscriptions, ce qui renforce la domination de l\u2019offre qui continue de d\u00e9finir le march\u00e9.<\/p>\n\n\n\n<p>Les stocks \u00e9lev\u00e9s maintiennent la tendance \u00e0 la baisse des prix des logements. L\u2019indice composite des prix des propri\u00e9t\u00e9s a d\u00e9gringol\u00e9 de 4,7&nbsp;% sur 12&nbsp;mois, mais la d\u00e9t\u00e9rioration n\u2019a pas \u00e9t\u00e9 r\u00e9partie \u00e9galement entre les types de propri\u00e9t\u00e9s. Les maisons isol\u00e9es r\u00e9sistent mieux aux baisses de prix que les logements \u00e0 plus forte densit\u00e9.<\/p>\n\n\n\n<p>Les nombreuses constructions r\u00e9sidentielles en cours portent \u00e0 croire que les stocks demeureront \u00e9lev\u00e9s, ce qui emp\u00eachera l\u2019\u00e9lan de se d\u00e9placer du c\u00f4t\u00e9 des vendeurs sans une augmentation ad\u00e9quate de la demande.<\/p>\n\n\n\n<div id=\"everviz-7OBxsf5NM\" class=\"everviz-7OBxsf5NM\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" id=\"h-telechargez-le-rapport\"><a href=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2026\/02\/La-hausse-de-loffre-maintient-la-tendance-a-la-baisse-des-prix-des-logements-au-Canada-Etat-des-marches-immobiliers-locaux-6-fevr.-2026.pdf\" target=\"_blank\" data-dig-id=\"LP-U.S.Analysis-FeaturedAnalysis-US-5317-a3a70bf2\" data-dig-category=\"LP-U.S.Analysis-FeaturedAnalysis-US\" data-dig-action=\"link click\" data-dig-label=\"Download the Report\" class=\"rbc-link-format rbc-link-format pdf-link\" data-icon-class=\"pdf-link\" rel=\"noreferrer noopener\">T\u00e9l\u00e9chargez le rapport<\/a><\/h4>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<p><em><em><em><strong>Rachel Battaglia<\/strong>&nbsp;est \u00e9conomiste \u00e0 RBC. Elle est membre du groupe d\u2019Analyse macro\u00e9conomique et r\u00e9gionale et fournit des analyses des perspectives macro\u00e9conomiques provinciales. Elle est titulaire d\u2019un baccalaur\u00e9at en \u00e9conomie (avec distinction) de l\u2019Universit\u00e9 Western Ontario et d\u2019une ma\u00eetrise en sciences de l\u2019Amsterdam School of Economics.<\/em><\/em><\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":318,"featured_media":2551,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[71,75,23],"tags":[],"rbc_econ_content_type":[],"class_list":["post-3666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse-pour-le-canada","category-etat-des-marches-immobiliers-locaux","category-logement-au-canada"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada - RBC Economique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Economique\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-06T17:31:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T15:15:41+00:00\" \/>\n<meta name=\"author\" content=\"viktoriyapanahova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"viktoriyapanahova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/\"},\"author\":{\"name\":\"viktoriyapanahova\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\"},\"headline\":\"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada\",\"datePublished\":\"2026-02-06T17:31:58+00:00\",\"dateModified\":\"2026-02-09T15:15:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/\"},\"wordCount\":1157,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/11\\\/Housing-B-compressed-banner.png?quality=80\",\"articleSection\":[\"Analyse pour le Canada\",\"\u00c9tat des march\u00e9s immobiliers locaux\",\"Logement au Canada\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/\",\"name\":\"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada - RBC Economique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/11\\\/Housing-B-compressed-banner.png?quality=80\",\"datePublished\":\"2026-02-06T17:31:58+00:00\",\"dateModified\":\"2026-02-09T15:15:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/11\\\/Housing-B-compressed-banner.png?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/2025\\\/11\\\/Housing-B-compressed-banner.png?quality=80\",\"width\":6134,\"height\":3700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/etat-des-marches-immobiliers-locaux\\\/fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\",\"name\":\"RBC Economique\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\",\"name\":\"viktoriyapanahova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"caption\":\"viktoriyapanahova\"},\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/author\\\/viktoriyapanahova\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada - RBC Economique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada","og_url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/","og_site_name":"RBC Economique","article_published_time":"2026-02-06T17:31:58+00:00","article_modified_time":"2026-02-09T15:15:41+00:00","author":"viktoriyapanahova","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","twitter_misc":{"Written by":"viktoriyapanahova","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/"},"author":{"name":"viktoriyapanahova","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea"},"headline":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada","datePublished":"2026-02-06T17:31:58+00:00","dateModified":"2026-02-09T15:15:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/"},"wordCount":1157,"commentCount":0,"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","articleSection":["Analyse pour le Canada","\u00c9tat des march\u00e9s immobiliers locaux","Logement au Canada"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/","url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/","name":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada - RBC Economique","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","datePublished":"2026-02-06T17:31:58+00:00","dateModified":"2026-02-09T15:15:41+00:00","author":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea"},"breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","width":6134,"height":3700},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rbc.com\/fr\/economique\/"},{"@type":"ListItem","position":2,"name":"La hausse de l\u2019offre maintient la tendance \u00e0 la baisse des prix des logements au Canada"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/economique\/#website","url":"https:\/\/www.rbc.com\/fr\/economique\/","name":"RBC Economique","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/economique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea","name":"viktoriyapanahova","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","caption":"viktoriyapanahova"},"url":"https:\/\/www.rbc.com\/fr\/economique\/author\/viktoriyapanahova\/"}]}},"author_meta":{"display_name":"viktoriyapanahova","author_link":"https:\/\/www.rbc.com\/fr\/economique\/author\/viktoriyapanahova\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/2025\/11\/Housing-B-compressed-banner.png?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/\" class=\"advgb-post-tax-term\">Analyse pour le Canada<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/logement-au-canada\/etat-des-marches-immobiliers-locaux\/\" class=\"advgb-post-tax-term\">\u00c9tat des march\u00e9s immobiliers locaux<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/logement-au-canada\/\" class=\"advgb-post-tax-term\">Logement au Canada<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Analyse pour le Canada<\/span>","<span class=\"advgb-post-tax-term\">\u00c9tat des march\u00e9s immobiliers locaux<\/span>","<span class=\"advgb-post-tax-term\">Logement au Canada<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 3 mois il y a","modified":"Mis \u00e0 jour 3 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 6 f\u00e9vrier 2026","modified":"Mise \u00e0 jour le 9 f\u00e9vrier 2026"},"absolute_dates_time":{"created":"Publi\u00e9 le 6 f\u00e9vrier 2026 5:31  ","modified":"Mise \u00e0 jour le 9 f\u00e9vrier 2026 3:15  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/3666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/comments?post=3666"}],"version-history":[{"count":6,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/3666\/revisions"}],"predecessor-version":[{"id":3678,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/3666\/revisions\/3678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media\/2551"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media?parent=3666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/categories?post=3666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/tags?post=3666"},{"taxonomy":"rbc_econ_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/rbc_econ_content_type?post=3666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}