{"id":1551,"date":"2021-01-26T22:00:11","date_gmt":"2021-01-26T22:00:11","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/economique\/2021\/01\/26\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/"},"modified":"2021-01-26T22:00:11","modified_gmt":"2021-01-26T22:00:11","slug":"la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/","title":{"rendered":"La COVID-19 \u00e9branle la ligne d&rsquo;action des organismes de bienfaisance"},"content":{"rendered":"<p>Une bonne reprise en d\u00e9cembre a att\u00e9nu\u00e9 ce qui aurait \u00e9t\u00e9 une ann\u00e9e lamentable pour les organismes de bienfaisance canadiens. Ils se souviendront de 2020 comme d&rsquo;une ann\u00e9e de p\u00e9nibles perturbations, alors que les mesures de lutte contre le virus ont frein\u00e9 le flux des dons.<\/p>\n<p>Selon les donn\u00e9es de RBC, les dons ont diminu\u00e9 de 4 % au Canada l&rsquo;an dernier. Sous ce d\u00e9clin se cachent toutefois d&rsquo;importants \u00e9carts : certaines organisations ont constat\u00e9 une augmentation des contributions tandis que d&rsquo;autres n&rsquo;ont litt\u00e9ralement rien re\u00e7u.<\/p>\n<p>\u00ab Pour survivre, les associations caritatives ont \u00e9t\u00e9 contraintes de passer au num\u00e9rique du jour au lendemain, a mentionn\u00e9 Kelly Schmitt, chef de la direction, Benevity (dont le logiciel aide \u00e0 g\u00e9rer les dons de bienfaisance et les initiatives de b\u00e9n\u00e9volat), lors d&rsquo;un r\u00e9cent \u00e9pisode de la s\u00e9rie Les innovateurs RBC. Il n&rsquo;y a eu ni galas de charit\u00e9 ni de tournois de golf. Les activit\u00e9s de financement habituelles n&rsquo;\u00e9taient plus une option. \u00bb<\/p>\n<p>Les dons de charit\u00e9 ont \u00e9galement diminu\u00e9 lors de r\u00e9cessions pr\u00e9c\u00e9dentes, notamment durant la crise financi\u00e8re de 2008-2009. Selon Statistique Canada, les dons auraient alors d\u00e9clin\u00e9 de plus de 5 % par ann\u00e9e (les donn\u00e9es pour 2020 ne sont pas encore accessibles). La diff\u00e9rence, cette fois-ci, c&rsquo;est que certains ont vu dans cette crise une occasion d&rsquo;innover en adoptant de nouvelles technologies et plateformes pour rejoindre des partenaires de longue date et en attirer de nouveaux.<\/p>\n<hr>\n<p><div id=\"highcharts-eMNiDyPu8\"><script src=\"https:\/\/app.everviz.com\/inject\/eMNiDyPu8\/\" defer=\"defer\"><\/script><\/div>\n<\/p>\n<hr>\n<h4>La pand\u00e9mie a port\u00e9 un coup in\u00e9gal aux organismes de bienfaisance canadiens.<\/h4>\n<p>Selon les donn\u00e9es de RBC, pr\u00e8s de 42 % des organismes qui ont re\u00e7u des dons en 2019 en ont recueilli moins en 2020. Les pertes combin\u00e9es se sont \u00e9lev\u00e9es \u00e0 60 millions de dollars. Certains organismes s&rsquo;en sont bien sortis, alors que d&rsquo;autres (27 %) n&rsquo;ont re\u00e7u aucun don en 2020. <\/p>\n<p>Le plus grand coup collectif a \u00e9t\u00e9 enregistr\u00e9 en mai, au d\u00e9but de la pand\u00e9mie, lorsque les dons ont chut\u00e9 de 30 % par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. Toutefois, en d\u00e9cembre, il y a eu une hausse de 21 % des dons par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente. Cette augmentation s&rsquo;explique par l&#8217;empressement de nombreux Canadiens \u00e0 verser des dons avant la fin de l&rsquo;ann\u00e9e d&rsquo;imposition. <\/p>\n<p>Selon un <a href=\"https:\/\/imaginecanada.ca\/en\/research\">rapport d&rsquo;Imagine Canada<\/a>, organisme sans but lucratif qui fait conna\u00eetre le travail de milliers d&rsquo;organismes de bienfaisance canadiens, les petites organisations communautaires sont les plus \u00e0 risque. Elles ont g\u00e9n\u00e9ralement moins de r\u00e9serves financi\u00e8res et bon nombre de leurs donateurs habituels ont \u00e9t\u00e9 durement touch\u00e9s par le ralentissement \u00e9conomique.<\/p>\n<hr>\n<p><div id=\"highcharts-UOCBbXbLQ\"><script src=\"https:\/\/app.everviz.com\/inject\/UOCBbXbLQ\/\" defer=\"defer\"><\/script><\/div>\n<\/p>\n<hr>\n<h4>L&rsquo;annulation des activit\u00e9s en personne a fait beaucoup de tort aux organismes caritatifs.<\/h4>\n<p>Malgr\u00e9 les pertes d&#8217;emplois g\u00e9n\u00e9ralis\u00e9es, le revenu disponible des m\u00e9nages n&rsquo;a jamais chut\u00e9 sous les niveaux de 2019 gr\u00e2ce aux programmes d&rsquo;aide d&rsquo;Ottawa. Ce qui laisse croire que la baisse des dons en 2020 est davantage attribuable \u00e0 l&rsquo;absence d&rsquo;\u00e9v\u00e9nements en direct, de la plus haute importance pour les collectes de fonds, qu&rsquo;aux difficult\u00e9s financi\u00e8res li\u00e9es \u00e0 la COVID-19. Du jour au lendemain, les organismes de bienfaisance ont d\u00fb renoncer \u00e0 des m\u00e9thodes \u00e9prouv\u00e9es pour recueillir les dons : les sollicitations porte-\u00e0-porte, les ench\u00e8res en direct, les courses et les marches, et m\u00eame les ventes de p\u00e2tisseries. <\/p>\n<p>Apr\u00e8s avoir vu ses revenus diminuer drastiquement en raison de l&rsquo;annulation des activit\u00e9s de collecte de fonds en personne, YMCA Canada a <a href=\"https:\/\/www.theglobeandmail.com\/opinion\/article-the-charities-that-help-struggling-canadians-are-struggling-too\/\">demand\u00e9<\/a> un soutien d&rsquo;urgence au gouvernement f\u00e9d\u00e9ral. De m\u00eame, l&rsquo;Arm\u00e9e du Salut <a href=\"https:\/\/www.thestar.com\/news\/canada\/2020\/12\/23\/salvation-army-christmas-kettle-campaign-short-250000-across-maritime-provinces.html\">n&rsquo;a pas r\u00e9ussi<\/a> \u00e0 atteindre les objectifs qu&rsquo;elle s&rsquo;\u00e9tait fix\u00e9s pour la traditionnelle campagne des marmites de No\u00ebl dans plusieurs r\u00e9gions en raison des restrictions et dommages caus\u00e9s par la COVID-19, notamment les rassemblements limit\u00e9s et la diminution du bassin de b\u00e9n\u00e9voles disponibles.<\/p>\n<p>Par cons\u00e9quent, les organismes se voient contraints de faire plus avec des capacit\u00e9s diminu\u00e9es. En effet, un <a href=\"https:\/\/imaginecanada.ca\/en\/holiday-giving-survey-2020\">sondage<\/a> r\u00e9alis\u00e9 en novembre 2020 par Imagine Canada indique que 68 % des organismes de bienfaisance ont enregistr\u00e9 une baisse des dons depuis le d\u00e9but de la pand\u00e9mie. En m\u00eame temps, la demande pour leurs services continue d&rsquo;augmenter : 46 % de ces organismes rapportent une hausse de la demande. <\/p>\n<h4>Les outils num\u00e9riques ont permis \u00e0 certaines associations caritatives de prosp\u00e9rer.<\/h4>\n<p>Les organisations qui \u00e9taient d\u00e9j\u00e0 pr\u00e9sentes virtuellement ou qui ont fait un virage en ligne ont mieux r\u00e9ussi que les autres. Selon les donn\u00e9es de RBC, CanaDon, une plateforme nationale qui accepte les dons en ligne pour les organismes de bienfaisance enregistr\u00e9s, a recueilli pr\u00e8s de 33 % de l&rsquo;augmentation des dons de d\u00e9cembre. Les employ\u00e9s et clients des entreprises clientes de Benevity ont <a href=\"https:\/\/www.benevity.com\/media\/press-releases\/2020-benevity-data-people-gave-more-money\">remis<\/a> 500 millions de dollars de leurs propres fonds \u00e0 la soci\u00e9t\u00e9 de Calgary, soit une augmentation de 76 % par rapport \u00e0 l&rsquo;an dernier. <\/p>\n<p>\u00ab Nous avons compris qu&rsquo;il \u00e9tait payant d&rsquo;investir dans une infrastructure num\u00e9rique, a dit Todd Minerson, directeur national \u2013 Canada, Movember. Nous sommes en ligne depuis 2010, et c&rsquo;est ce qui nous a en grande partie permis de r\u00e9ussir cette ann\u00e9e. \u00bb <\/p>\n<p> Certains organismes de bienfaisance ont m\u00eame trouv\u00e9 le moyen de convertir des \u00e9v\u00e9nements en direct en \u00e9v\u00e9nements virtuels \u00e0 l&rsquo;aide d&rsquo;applications comme Strava et Zwift.<\/p>\n<h4>Les organismes de bienfaisance vou\u00e9s au culte et \u00e0 la sant\u00e9 s&rsquo;en sont mieux tir\u00e9s.<\/h4>\n<p>Les organismes de bienfaisance vou\u00e9s au culte et \u00e0 la sant\u00e9 ont enregistr\u00e9 une hausse de leurs revenus par rapport \u00e0 2019. Les organismes d&rsquo;aide internationale ou \u00e0 vocation \u00e9ducative ont perdu du terrain. Les entreprises ont aussi chang\u00e9 leurs habitudes de dons. Par Benevity, les entreprises ont davantage soutenu les campagnes de lutte contre la COVID-19 ou l&rsquo;in\u00e9galit\u00e9 raciale, ce qui s&rsquo;est traduit par une augmentation moyenne du total des dons de 150 % en avril et de 215 % en juin.<\/p>\n<hr>\n<p><div id=\"highcharts-WC4iMtImb\"><script src=\"https:\/\/app.everviz.com\/inject\/WC4iMtImb\/\" defer=\"defer\"><\/script><\/div>\n<\/p>\n<hr>\n<h4>Le virage num\u00e9rique a \u00e9galement touch\u00e9 le secteur philanthropique.<\/h4>\n<p>\u00c0 l&rsquo;instar des autres secteurs \u00e9conomiques, le secteur philanthropique peut tirer parti d&rsquo;un avantage de taille du num\u00e9rique : la possibilit\u00e9 de rejoindre beaucoup plus de donateurs. Par exemple, M<sup>me<\/sup> Schmitt de Benevity indique qu&rsquo;un client de Walmart sur sept accepte de verser un don lorsqu&rsquo;on lui demande. \u00ab Le succ\u00e8s d&rsquo;une collecte de fonds repose en grande partie sur la sollicitation \u00bb, explique-t-elle. C&rsquo;est exactement ce que permet de faire le num\u00e9rique, et de fa\u00e7on plus efficace.<\/p>\n<p>Benevity a g\u00e9r\u00e9 6 milliards de dollars en dons et 34 millions d&rsquo;heures de b\u00e9n\u00e9volat. Les plateformes num\u00e9riques peuvent \u00e9galement stimuler les microdons, qui peuvent s&rsquo;additionner rapidement, surtout lorsque les entreprises font des dons \u00e9quivalents, a mentionn\u00e9 M<sup>me<\/sup> Schmitt. \u00ab Sans tenir compte des contributions de contrepartie des entreprises, le montant moyen des dons sur notre plateforme est de 50 $. Il n&#8217;emp\u00eache qu&rsquo;entre 2 et 3 milliards de dollars ont \u00e9t\u00e9 donn\u00e9s par l&rsquo;interm\u00e9diaire de la plateforme en 2020. \u00bb<\/p>\n<hr>\n<p><strong>\u2021 <b>M\u00e9thodologie<\/b><\/strong><\/p>\n<p>Ce rapport RBC est fond\u00e9 sur la base de donn\u00e9es exclusive de Donn\u00e9es et analyse RBC portant sur les op\u00e9rations sur carte des clients canadiens rendues anonymes. Les donn\u00e9es visent les op\u00e9rations de commer\u00e7ant effectu\u00e9es en personne et en ligne. Les op\u00e9rations purement financi\u00e8res, comme les avances de fonds et les assurances, ne sont pas prises en compte. Les donn\u00e9es de RBC sont un bon indicateur de l&rsquo;ensemble du march\u00e9 et c&rsquo;est pourquoi nous les utilisons. Nous recueillons des renseignements d&rsquo;un large \u00e9ventail de sources, dont ces donn\u00e9es.<\/p>\n<p>L&rsquo;estimation du volume des d\u00e9penses en ligne se fonde sur la pr\u00e9sence d&rsquo;une carte RBC au moment de l&rsquo;autorisation. <\/p>\n<p>Dans la mesure du possible, nous veillons \u00e0 rep\u00e9rer les organismes de bienfaisance et \u00e0 les mettre en contact les uns avec les autres au fil du temps. Comme de plus en plus d&rsquo;organismes de bienfaisance ont opt\u00e9 pour les plateformes en ligne, il est possible que nous ayons rep\u00e9r\u00e9 des organismes qui semblent ne recevoir aucun don, mais qu&rsquo;en fait, il s&rsquo;agisse d&rsquo;une erreur et que ceux-ci aient simplement adopt\u00e9 de nouvelles approches en mati\u00e8re de collecte de fonds et les plateformes en ligne.<\/p>\n<p>La protection de vos renseignements personnels constitue la pierre angulaire de l&rsquo;\u00e9thique et des valeurs de notre entreprise et demeurera toujours l&rsquo;une de nos grandes priorit\u00e9s. Les donn\u00e9es sous-jacentes de cette analyse ont \u00e9t\u00e9 cumul\u00e9es en fonction de la date de l&rsquo;op\u00e9ration, de la r\u00e9gion, ainsi que de la cat\u00e9gorie de commer\u00e7ant, et ne peuvent pas \u00eatre utilis\u00e9es pour identifier un client ou un commer\u00e7ant. Pour en savoir plus, allez \u00e0 l&rsquo;adresse suivante : <a href=\"http:\/\/www.rbc.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.rbc.com\/rensperssecurite<\/a>.<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Situation de crise pour certains organismes de bienfaisance canadiens, mais pour d&rsquo;autres, une occasion d&rsquo;innover et d&rsquo;adopter de nouvelles technologies afin de rejoindre les partenaires.<\/p>\n","protected":false},"author":234,"featured_media":1548,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","editor_notices":[],"footnotes":"","jetpack_post_was_ever_published":false},"categories":[77,71,79],"tags":[14,10,12],"rbc_econ_content_type":[],"class_list":["post-1551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse-en-vedette","category-analyse-pour-le-canada","category-perspectives","tag-economie","tag-innovation","tag-technologie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.7 (Yoast SEO v27.7) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La COVID-19 \u00e9branle la ligne d&#039;action des organismes de bienfaisance - RBC Economique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La COVID-19 \u00e9branle la ligne d&#039;action des organismes de bienfaisance\" \/>\n<meta property=\"og:description\" content=\"Situation de crise pour certains organismes de bienfaisance canadiens, mais pour d&#039;autres, une occasion d&#039;innover et d&#039;adopter de nouvelles technologies afin de rejoindre les partenaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Economique\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-26T22:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1236\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RBC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"RBC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/\"},\"author\":{\"name\":\"RBC\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/176c7a354542d537fffc23f98f89e80f\"},\"headline\":\"La COVID-19 \u00e9branle la ligne d&rsquo;action des organismes de bienfaisance\",\"datePublished\":\"2021-01-26T22:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/\"},\"wordCount\":1523,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Banner-wide-63-scaled-1.jpg?quality=80\",\"keywords\":[\"\u00c9conomie\",\"Innovation\",\"Technologie\"],\"articleSection\":[\"Analyse en vedette\",\"Analyse pour le Canada\",\"Perspectives\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/\",\"name\":\"La COVID-19 \u00e9branle la ligne d'action des organismes de bienfaisance - RBC Economique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Banner-wide-63-scaled-1.jpg?quality=80\",\"datePublished\":\"2021-01-26T22:00:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/176c7a354542d537fffc23f98f89e80f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Banner-wide-63-scaled-1.jpg?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/03\\\/Banner-wide-63-scaled-1.jpg?quality=80\",\"width\":2560,\"height\":1236},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/analyse-en-vedette\\\/perspectives\\\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La COVID-19 \u00e9branle la ligne d&rsquo;action des organismes de bienfaisance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\",\"name\":\"RBC Economique\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/176c7a354542d537fffc23f98f89e80f\",\"name\":\"RBC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g\",\"caption\":\"RBC\"},\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/author\\\/rbc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La COVID-19 \u00e9branle la ligne d'action des organismes de bienfaisance - RBC Economique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/","og_locale":"fr_FR","og_type":"article","og_title":"La COVID-19 \u00e9branle la ligne d'action des organismes de bienfaisance","og_description":"Situation de crise pour certains organismes de bienfaisance canadiens, mais pour d'autres, une occasion d'innover et d'adopter de nouvelles technologies afin de rejoindre les partenaires.","og_url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/","og_site_name":"RBC Economique","article_published_time":"2021-01-26T22:00:11+00:00","og_image":[{"width":2560,"height":1236,"url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","type":"image\/jpeg"}],"author":"RBC","twitter_card":"summary_large_image","twitter_misc":{"Written by":"RBC","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/"},"author":{"name":"RBC","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/176c7a354542d537fffc23f98f89e80f"},"headline":"La COVID-19 \u00e9branle la ligne d&rsquo;action des organismes de bienfaisance","datePublished":"2021-01-26T22:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/"},"wordCount":1523,"commentCount":0,"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","keywords":["\u00c9conomie","Innovation","Technologie"],"articleSection":["Analyse en vedette","Analyse pour le Canada","Perspectives"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/","url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/","name":"La COVID-19 \u00e9branle la ligne d'action des organismes de bienfaisance - RBC Economique","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","datePublished":"2021-01-26T22:00:11+00:00","author":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/176c7a354542d537fffc23f98f89e80f"},"breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","width":2560,"height":1236},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/la-covid-19-ebranle-la-ligne-daction-des-organismes-de-bienfaisance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rbc.com\/fr\/economique\/"},{"@type":"ListItem","position":2,"name":"La COVID-19 \u00e9branle la ligne d&rsquo;action des organismes de bienfaisance"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/economique\/#website","url":"https:\/\/www.rbc.com\/fr\/economique\/","name":"RBC Economique","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/economique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/176c7a354542d537fffc23f98f89e80f","name":"RBC","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b105f9755b11baabaedb73de5e85848c5a51158a9bc64574c454cf7d0fea8968?s=96&d=mm&r=g","caption":"RBC"},"url":"https:\/\/www.rbc.com\/fr\/economique\/author\/rbc\/"}]}},"author_meta":{"display_name":"RBC","author_link":"https:\/\/www.rbc.com\/fr\/economique\/author\/rbc\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/03\/Banner-wide-63-scaled-1.jpg?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/\" class=\"advgb-post-tax-term\">Analyse en vedette<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/\" class=\"advgb-post-tax-term\">Analyse pour le Canada<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">Perspectives<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Analyse en vedette<\/span>","<span class=\"advgb-post-tax-term\">Analyse pour le Canada<\/span>","<span class=\"advgb-post-tax-term\">Perspectives<\/span>"]},"tags":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">\u00c9conomie<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">Innovation<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/analyse-en-vedette\/perspectives\/\" class=\"advgb-post-tax-term\">Technologie<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">\u00c9conomie<\/span>","<span class=\"advgb-post-tax-term\">Innovation<\/span>","<span class=\"advgb-post-tax-term\">Technologie<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 5 ans il y a","modified":"Mis \u00e0 jour 5 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 26 janvier 2021","modified":"Mise \u00e0 jour le 26 janvier 2021"},"absolute_dates_time":{"created":"Publi\u00e9 le 26 janvier 2021 10:00  ","modified":"Mise \u00e0 jour le 26 janvier 2021 10:00  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/1551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/users\/234"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/comments?post=1551"}],"version-history":[{"count":0,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/1551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media\/1548"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media?parent=1551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/categories?post=1551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/tags?post=1551"},{"taxonomy":"rbc_econ_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/rbc_econ_content_type?post=1551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}