{"id":1434,"date":"2025-09-08T20:27:08","date_gmt":"2025-09-08T20:27:08","guid":{"rendered":"https:\/\/www.rbc.com\/fr\/economique\/2025\/09\/08\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/"},"modified":"2025-10-29T16:16:46","modified_gmt":"2025-10-29T16:16:46","slug":"le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale","status":"publish","type":"post","link":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/","title":{"rendered":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale"},"content":{"rendered":"\n<section class=\"wp-block-rbc-section-block  pos-rel\" style=\"border-radius:0px\">\n<div class=\"wp-block-rbc-section-inner-block  section-inner\" style=\"border-radius:0x\">\n<p>En ao\u00fbt, de nouveaux signes ont mis en \u00e9vidence qu\u2019une reprise prenait forme dans de nombreux march\u00e9s du logement partout au Canada. Toutefois, \u00e0 l\u2019\u00e9chelle locale, les tendances des prix demeuraient variables, et le repli s\u2019est poursuivi dans les r\u00e9gions caract\u00e9ris\u00e9es par des probl\u00e8mes d\u2019accessibilit\u00e9 et une accumulation des stocks.&nbsp;<\/p>\n\n\n\n<p>D\u2019apr\u00e8s les rapports pr\u00e9liminaires des chambres immobili\u00e8res locales, le nombre de maisons faisant l\u2019objet de changements de mains a continu\u00e9 de remonter par rapport aux creux de cette ann\u00e9e \u00e0 Vancouver, \u00e0 Calgary, \u00e0 Edmonton et \u00e0 Montr\u00e9al. L\u2019activit\u00e9 n\u2019a toutefois pas d\u00e9pass\u00e9 les niveaux d\u2019il y a un an \u00e0 Calgary et \u00e0 Edmonton. En ao\u00fbt, Toronto a connu ce que nous consid\u00e9rons comme une pause temporaire dans son processus de redressement.<\/p>\n\n\n\n<p>Ces \u00e9volutions confortent <a href=\"https:\/\/www.rbc.com\/fr\/leadership-avise\/recherche-economique\/logement-au-canada\/rapports-speciaux-sur-le-logement\/mise-a-jour-des-previsions-pour-le-marche-canadien-du-logement\/\" target=\"_blank\" data-dig-id=\"LP-Rapportssp\u00e9ciauxsurlelogement-AnalysepourleCanada-1434-ea047ed7\" data-dig-category=\"LP-Rapportssp\u00e9ciauxsurlelogement-AnalysepourleCanada\" data-dig-action=\"link click\" data-dig-label=\"notre opinion\" rel=\"noreferrer noopener\" class=\"rbc-link-format\">notre opinion<\/a> selon laquelle le regain de confiance des march\u00e9s entra\u00eenera une reprise mod\u00e9r\u00e9e au second semestre de 2025 et ouvrira la voie \u00e0 une demande plus soutenue en 2026.<\/p>\n\n\n\n<p>La divergence des prix est un autre facteur qui devrait persister \u00e0 court terme, \u00e9tant donn\u00e9 que les conditions de l\u2019offre et de la demande varient entre les r\u00e9gions. Les conditions \u00e9quilibr\u00e9es, parfois tendues, font grimper la valeur des propri\u00e9t\u00e9s dans une grande partie des Prairies, au Qu\u00e9bec et dans certaines provinces de l\u2019Atlantique, tandis que le niveau \u00e9lev\u00e9 des stocks a un effet n\u00e9gatif sur la valeur des propri\u00e9t\u00e9s en Ontario et en Colombie-Britannique.<\/p>\n\n\n\n<p>Les donn\u00e9es locales indiquent que l\u2019indice des prix des propri\u00e9t\u00e9s&nbsp;MLS a de nouveau chut\u00e9 \u00e0 Toronto, \u00e0 Hamilton, \u00e0 Calgary, \u00e0 Edmonton, dans la vall\u00e9e du Fraser et \u00e0 Vancouver, o\u00f9 les stocks sont abondants.<\/p>\n\n\n\n<p>Le dynamisme de la construction a \u00e9t\u00e9 le principal moteur de l\u2019accroissement des stocks \u00e0 Calgary et \u00e0 Edmonton.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div id=\"everviz-UnvCbLodI\" class=\"everviz-UnvCbLodI\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-region-de-toronto-la-pause-dans-la-reprise-devrait-etre-temporaire\">R\u00e9gion de Toronto : la pause dans la reprise devrait \u00eatre temporaire<\/h2>\n\n\n\n<p>La r\u00e9gion de Toronto a fait une pause en ao\u00fbt apr\u00e8s quatre mois de progression soutenue. Les reventes de propri\u00e9t\u00e9s ont subi un l\u00e9ger d\u00e9clin de 1,8&nbsp;% par rapport \u00e0 juillet (en donn\u00e9es d\u00e9saisonnalis\u00e9es), la faiblesse du segment des copropri\u00e9t\u00e9s ayant min\u00e9 l\u2019activit\u00e9. Les reventes ont toutefois progress\u00e9 de 2,3&nbsp;% par rapport \u00e0 l\u2019an dernier.<\/p>\n\n\n\n<p>Selon nous, les r\u00e9sultats du mois d\u2019ao\u00fbt marquent une pause temporaire sur la voie de la reprise. Les r\u00e9ductions de taux d\u2019int\u00e9r\u00eat, les r\u00e9centes chutes des prix, l\u2019augmentation des stocks et l\u2019apaisement des craintes de guerre commerciale entra\u00eeneront une remont\u00e9e progressive de l\u2019activit\u00e9.<\/p>\n\n\n\n<p>La correction des prix, \u00e0 la fois modeste et g\u00e9n\u00e9ralis\u00e9e, s\u2019est poursuivie le mois dernier. L\u2019indice composite des prix des propri\u00e9t\u00e9s&nbsp;MLS de la r\u00e9gion a c\u00e9d\u00e9 0,1&nbsp;% par rapport \u00e0 son niveau de juillet, en donn\u00e9es d\u00e9saisonnalis\u00e9es, pour s\u2019\u00e9tablir \u00e0 978\u2009100&nbsp;$ \u2013 dans le sillage de la tendance \u00e0 la baisse observ\u00e9e depuis un&nbsp;an.<\/p>\n\n\n\n<p>L\u2019indice des prix des copropri\u00e9t\u00e9s est celui qui a le plus recul\u00e9, en repli de 7&nbsp;% par rapport \u00e0 l\u2019an dernier, mais toutes les cat\u00e9gories ont subi une correction, y compris les maisons unifamiliales non attenantes (-5,6&nbsp;%).<\/p>\n\n\n\n<p>Nous pensons que la valeur des propri\u00e9t\u00e9s continuera de d\u00e9cliner pendant que le march\u00e9 reprend pied. Cela dit, bien que l\u2019accessibilit\u00e9 s\u2019am\u00e9liore, elle demeurera un probl\u00e8me important.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div id=\"everviz-kvqXjw7_S\" class=\"everviz-kvqXjw7_S\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-region-de-montreal-nbsp-l-activite-redemarre-apres-une-longue-periode-d-accalmie\">R\u00e9gion de Montr\u00e9al&nbsp;: l\u2019activit\u00e9 red\u00e9marre, apr\u00e8s une longue p\u00e9riode d\u2019accalmie<\/h2>\n\n\n\n<p>Un plus grand nombre de vendeurs sont arriv\u00e9s sur le march\u00e9 de Montr\u00e9al, ce qui a provoqu\u00e9 une envol\u00e9e des transactions. Selon nos estimations, les nouvelles mises en vente et les reventes de propri\u00e9t\u00e9s ont respectivement bondi de plus de 8&nbsp;% et 5&nbsp;%, en donn\u00e9es d\u00e9saisonnalis\u00e9es, par rapport \u00e0 juillet. C\u2019est le premier signe que l\u2019activit\u00e9 est enfin sortie de sa l\u00e9thargie de cette ann\u00e9e.<\/p>\n\n\n\n<p>Les acheteurs restent impatients de conclure des transactions, mais les constantes hausses des prix, les conditions serr\u00e9es de l\u2019offre et de la demande et les stocks limit\u00e9s rendent les affaires difficiles.<\/p>\n\n\n\n<p>C\u2019est pourquoi nous nous attendons \u00e0 un march\u00e9 cahoteux dans les prochains temps. La poursuite de la croissance des ventes d\u00e9pendra fortement du flux de transactions et de la combinaison de propri\u00e9t\u00e9s \u00e0 vendre. Les acheteurs ayant des contraintes budg\u00e9taires ne prendront pas de d\u00e9cision \u00e0 moins que des options appropri\u00e9es se pr\u00e9sentent.<\/p>\n\n\n\n<p>Nous pensons que ce contexte soutiendra l\u2019appr\u00e9ciation des prix, bien que les probl\u00e8mes d\u2019accessibilit\u00e9 puissent ralentir leur progression. Les prix m\u00e9dians des maisons unifamiliales et des copropri\u00e9t\u00e9s ont augment\u00e9 de 7,3&nbsp;% et de 3,7&nbsp;%, respectivement, par rapport \u00e0 l\u2019an dernier.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div id=\"everviz-HgkngsQQ4\" class=\"everviz-HgkngsQQ4\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-region-de-vancouver-nbsp-la-reprise-prend-de-l-elan\"><strong><strong>R\u00e9gion de Vancouver&nbsp;: la reprise prend de l\u2019\u00e9lan<\/strong><\/strong><\/h2>\n\n\n\n<p>Dans la r\u00e9gion de Vancouver, la reprise s\u2019est de nouveau acc\u00e9l\u00e9r\u00e9e en ao\u00fbt, mais elle n\u2019en est qu\u2019\u00e0 ses d\u00e9buts. Selon nos estimations, les reventes de propri\u00e9t\u00e9s ont augment\u00e9 de pr\u00e8s de 6&nbsp;% par rapport \u00e0 juillet, ce qui repr\u00e9sente la troisi\u00e8me hausse mensuelle cons\u00e9cutive.<\/p>\n\n\n\n<p>Les acheteurs ayant suspendu leur recherche de logement lorsque la guerre commerciale a \u00e9clat\u00e9 cet hiver reviennent sur le march\u00e9. L\u2019apaisement des tensions commerciales, dans un contexte de hausse du nombre de propri\u00e9t\u00e9s \u00e0 vendre et de baisse des prix, sera probablement un gros avantage.<\/p>\n\n\n\n<p>Les mises en vente actives, proches de leur sommet en plus de dix ans, attisent une concurrence f\u00e9roce entre les vendeurs.<\/p>\n\n\n\n<p>Cette tendance s\u2019est traduite par un recul graduel de l\u2019indice des prix des propri\u00e9t\u00e9s MLS de la r\u00e9gion de Vancouver cette ann\u00e9e, avec un recul de 3,8&nbsp;% sur un an en ao\u00fbt.<\/p>\n\n\n\n<p>Fait important, cette reprise des reventes a rapproch\u00e9 l\u2019offre et la demande d\u2019un point d\u2019\u00e9quilibre. Un raffermissement des conditions pourrait att\u00e9nuer les pressions \u00e0 la baisse sur les prix.<\/p>\n\n\n\n<p>Cela dit, les graves probl\u00e8mes d\u2019accessibilit\u00e9 continueront de limiter la capacit\u00e9 des acheteurs \u00e0 offrir des prix plus \u00e9lev\u00e9s.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div id=\"everviz-Xa413jxpN\" class=\"everviz-Xa413jxpN\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-calgary-un-tournant-pour-les-ventes-mais-pas-encore-pour-les-prix\"><strong>Calgary : un tournant pour les ventes, mais pas encore pour les prix<\/strong><\/h2>\n\n\n\n<p>\u00c0 Calgary, le nombre de transactions s\u2019est redress\u00e9 au cours des derniers mois, marquant ainsi un tournant apr\u00e8s une tendance \u00e0 la baisse qui a dur\u00e9 pr\u00e8s de deux ans. Bien qu\u2019une forte hausse estim\u00e9e \u00e0 8 % ait \u00e9t\u00e9 observ\u00e9e en ao\u00fbt par rapport \u00e0 juillet, l\u2019activit\u00e9 \u00e9conomique reste inf\u00e9rieure \u00e0 celle de l\u2019ann\u00e9e derni\u00e8re.<br>Cette remont\u00e9e n\u2019a pas encore eu d\u2019incidence sur les prix, qui demeurent influenc\u00e9s par l\u2019augmentation de l\u2019offre. Une vague de nouveaux logements construits depuis le d\u00e9but de 2024 a donn\u00e9 aux acheteurs plus d\u2019options et de pouvoir de n\u00e9gociation, ce qui a pes\u00e9 sur l\u2019indice des prix des propri\u00e9t\u00e9s MLS cette ann\u00e9e. En ao\u00fbt, l\u2019indice a baiss\u00e9 de 4,1 % par rapport \u00e0 l\u2019ann\u00e9e derni\u00e8re.<br>Cette situation pourrait changer si l\u2019augmentation de la demande perdure. Nous nous attendons \u00e0 ce que la confiance grandissante \u00e0 l\u2019\u00e9gard du march\u00e9, dans un contexte d\u2019apaisement des craintes \u00e9conomiques, aide \u00e0 stabiliser les prix.<br>Cela dit, \u00e9tant donn\u00e9 que la construction r\u00e9sidentielle fr\u00f4le encore des niveaux historiques et qu\u2019elle devrait continuer de stimuler l\u2019offre, nous pensons que le potentiel de hausse des prix est limit\u00e9 \u00e0 court terme.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div id=\"everviz-DIK02DZCP\" class=\"everviz-DIK02DZCP\" data-view=\"graph\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide wide\" \/>\n\n\n\n<div class=\"wp-block-columns has-border-color is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" style=\"border-color:#0b0b0b;border-width:1px\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.rbc.com\/en\/wp-content\/uploads\/sites\/4\/2025\/05\/pdf-button-housing-m.png?quality=80\" alt=\"\" class=\"wp-image-14712\" style=\"aspect-ratio:1.4745762711864407;width:335px;height:auto\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"wp-block-buttons mar-l is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\"><div>\n<div class=\"wp-block-button btn before is-style-tag tag mar-t-dbl\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/5\/2025\/03\/Housing-S-PDF-FR.pdf\" target=\"_blank\" rel=\"noreferrer noopener\" data-dig-id=\"LP-Rapportssp\u00e9ciauxsurlelogement-AnalysepourleCanada-1434-131ae1b6\" data-dig-category=\"LP-Rapportssp\u00e9ciauxsurlelogement-AnalysepourleCanada\" data-dig-action=\"button click\" data-dig-label=\"T\u00e9l\u00e9chargez le rapport-https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/5\/2025\/03\/Housing-S-PDF-FR.pdf \">T\u00e9l\u00e9chargez le rapport<\/a><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-light-grey-color has-alpha-channel-opacity has-light-grey-background-color has-background is-style-wide wide\" \/>\n\n\n\n<p><em><strong>Robert Hogue<\/strong><em>&nbsp;est membre du l\u2019\u00e9quipe \u00c9conomique et leadership avis\u00e9 RBC, se sp\u00e9cialisant dans l\u2019analyse et les pr\u00e9visions pour le march\u00e9 de l\u2019habitation canadien et les \u00e9conomies provinciales. Il compte parmi ses publications Tendances immobili\u00e8res et accessibilit\u00e9 \u00e0 la propri\u00e9t\u00e9, Perspectives provinciales et l\u2019analyse des budgets provinciaux. Dans ses fonctions, il est fr\u00e9quemment appel\u00e9 \u00e0 commenter l\u2019\u00e9volution de la conjoncture \u00e9conomique aupr\u00e8s de la direction de RBC, de ses clients et des m\u00e9dias.<\/em><\/em><\/p>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":318,"featured_media":1380,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[71,23,24],"tags":[],"rbc_econ_content_type":[],"class_list":["post-1434","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analyse-pour-le-canada","category-logement-au-canada","category-rapports-speciaux-sur-le-logement"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale - RBC Economique<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/\" \/>\n<meta property=\"og:site_name\" content=\"RBC Economique\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-08T20:27:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-29T16:16:46+00:00\" \/>\n<meta name=\"author\" content=\"viktoriyapanahova\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"viktoriyapanahova\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/\"},\"author\":{\"name\":\"viktoriyapanahova\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\"},\"headline\":\"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale\",\"datePublished\":\"2025-09-08T20:27:08+00:00\",\"dateModified\":\"2025-10-29T16:16:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/\"},\"wordCount\":1381,\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/07\\\/compressed-housing-S-1.png?quality=80\",\"articleSection\":[\"Analyse pour le Canada\",\"Logement au Canada\",\"Rapports sp\u00e9ciaux sur le logement\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/\",\"name\":\"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale - RBC Economique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/07\\\/compressed-housing-S-1.png?quality=80\",\"datePublished\":\"2025-09-08T20:27:08+00:00\",\"dateModified\":\"2025-10-29T16:16:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/07\\\/compressed-housing-S-1.png?quality=80\",\"contentUrl\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/wp-content\\\/uploads\\\/sites\\\/24\\\/\\\/2025\\\/07\\\/compressed-housing-S-1.png?quality=80\",\"width\":6134,\"height\":3700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/analyse-pour-le-canada\\\/logement-au-canada\\\/rapports-speciaux-sur-le-logement\\\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#website\",\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/\",\"name\":\"RBC Economique\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/#\\\/schema\\\/person\\\/109dd1bd3c90e818f8159356d46905ea\",\"name\":\"viktoriyapanahova\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g\",\"caption\":\"viktoriyapanahova\"},\"url\":\"https:\\\/\\\/www.rbc.com\\\/fr\\\/economique\\\/author\\\/viktoriyapanahova\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale - RBC Economique","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/","og_locale":"fr_FR","og_type":"article","og_title":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale","og_url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/","og_site_name":"RBC Economique","article_published_time":"2025-09-08T20:27:08+00:00","article_modified_time":"2025-10-29T16:16:46+00:00","author":"viktoriyapanahova","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","twitter_misc":{"Written by":"viktoriyapanahova","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#article","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/"},"author":{"name":"viktoriyapanahova","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea"},"headline":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale","datePublished":"2025-09-08T20:27:08+00:00","dateModified":"2025-10-29T16:16:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/"},"wordCount":1381,"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","articleSection":["Analyse pour le Canada","Logement au Canada","Rapports sp\u00e9ciaux sur le logement"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/","url":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/","name":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale - RBC Economique","isPartOf":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#primaryimage"},"image":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","datePublished":"2025-09-08T20:27:08+00:00","dateModified":"2025-10-29T16:16:46+00:00","author":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea"},"breadcrumb":{"@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#primaryimage","url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","contentUrl":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","width":6134,"height":3700},{"@type":"BreadcrumbList","@id":"https:\/\/www.rbc.com\/fr\/economique\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/le-marche-canadien-du-logement-se-redresse-lentement-mais-de-facon-inegale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rbc.com\/fr\/economique\/"},{"@type":"ListItem","position":2,"name":"Le march\u00e9 canadien du logement se redresse lentement, mais de fa\u00e7on in\u00e9gale"}]},{"@type":"WebSite","@id":"https:\/\/www.rbc.com\/fr\/economique\/#website","url":"https:\/\/www.rbc.com\/fr\/economique\/","name":"RBC Economique","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rbc.com\/fr\/economique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.rbc.com\/fr\/economique\/#\/schema\/person\/109dd1bd3c90e818f8159356d46905ea","name":"viktoriyapanahova","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/885bcff339d33080f070ec9cbe77fcf3007653305ae17de7827e19af43e61913?s=96&d=mm&r=g","caption":"viktoriyapanahova"},"url":"https:\/\/www.rbc.com\/fr\/economique\/author\/viktoriyapanahova\/"}]}},"author_meta":{"display_name":"viktoriyapanahova","author_link":"https:\/\/www.rbc.com\/fr\/economique\/author\/viktoriyapanahova\/"},"featured_img":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80&w=300","jetpack_featured_media_url":"https:\/\/www.rbc.com\/fr\/economique\/wp-content\/uploads\/sites\/24\/\/2025\/07\/compressed-housing-S-1.png?quality=80","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/\" class=\"advgb-post-tax-term\">Analyse pour le Canada<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/logement-au-canada\/\" class=\"advgb-post-tax-term\">Logement au Canada<\/a>","<a href=\"https:\/\/www.rbc.com\/fr\/economique\/category\/analyse-pour-le-canada\/logement-au-canada\/rapports-speciaux-sur-le-logement\/\" class=\"advgb-post-tax-term\">Rapports sp\u00e9ciaux sur le logement<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Analyse pour le Canada<\/span>","<span class=\"advgb-post-tax-term\">Logement au Canada<\/span>","<span class=\"advgb-post-tax-term\">Rapports sp\u00e9ciaux sur le logement<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Publi\u00e9 8 mois il y a","modified":"Mis \u00e0 jour 7 mois il y a"},"absolute_dates":{"created":"Publi\u00e9 le 8 septembre 2025","modified":"Mise \u00e0 jour le 29 octobre 2025"},"absolute_dates_time":{"created":"Publi\u00e9 le 8 septembre 2025 8:27  ","modified":"Mise \u00e0 jour le 29 octobre 2025 4:16  "},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/1434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/users\/318"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/comments?post=1434"}],"version-history":[{"count":5,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/1434\/revisions"}],"predecessor-version":[{"id":3660,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/posts\/1434\/revisions\/3660"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media\/1380"}],"wp:attachment":[{"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/media?parent=1434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/categories?post=1434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/tags?post=1434"},{"taxonomy":"rbc_econ_content_type","embeddable":true,"href":"https:\/\/www.rbc.com\/fr\/economique\/wp-json\/wp\/v2\/rbc_econ_content_type?post=1434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}